{"id":25239,"date":"2020-05-25T10:19:03","date_gmt":"2020-05-25T14:19:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25239"},"modified":"2020-05-25T10:19:03","modified_gmt":"2020-05-25T14:19:03","slug":"boi-menor-atratividade-do-confinamento-pode-afetar-oferta-na-entressafra","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/boi-menor-atratividade-do-confinamento-pode-afetar-oferta-na-entressafra\/","title":{"rendered":"Boi: menor atratividade do confinamento pode afetar oferta na entressafra"},"content":{"rendered":"<p>A press\u00e3o causada pelo aumento da oferta de boiadas est\u00e1 menor nesse final de safra em rela\u00e7\u00e3o \u00e0 safra de 2019, o que implica em estabilidade de pre\u00e7o frente \u00e0 demanda interna est\u00e1vel. A Scot Consultoria afirma que as varia\u00e7\u00f5es de pre\u00e7os registradas durante a semana passada em algumas regi\u00f5es, positivas ou negativas, foram reflexo desse cen\u00e1rio.<\/p>\n<p>Al\u00e9m disso, a menor atratividade para o confinamento em fun\u00e7\u00e3o da rela\u00e7\u00e3o apertada entre os pre\u00e7os do boi gordo no mercado futuro e os pre\u00e7os vigentes para a reposi\u00e7\u00e3o e, tamb\u00e9m, para os insumos, poder\u00e1 afetar a oferta de gado gordo na entressafra, em especial de bovinos jovens, que atendem o mercado chin\u00eas.<\/p>\n<p>A empresa afirma que para o curto prazo, a demanda interna \u00e9 ponto de aten\u00e7\u00e3o, mas sem expectativa de melhora relevante, tendo em vista o per\u00edodo de quarentena e crise econ\u00f4mica.\u00a0No mercado externo, apesar da queda do d\u00f3lar nos \u00faltimos dias, o c\u00e2mbio ainda elevado associado \u00e0 demanda exterior firme, favorece o embarque de carne bovina.<\/p>\n<h2><strong>Carne bovina no atacado<\/strong><\/h2>\n<p>Ap\u00f3s um aumento no consumo na primeira quinzena de maio, as vendas de carne bovina recuaram no mercado interno.\u00a0Entretanto, como os frigor\u00edficos est\u00e3o trabalhando com a capacidade de abate reduzida, as margens s\u00e3o menores para varia\u00e7\u00e3o nos pre\u00e7os.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>Na compara\u00e7\u00e3o semanal, na m\u00e9dia dos cortes pesquisados pela Scot Consultoria, o pre\u00e7o da carne bovina no mercado atacadista teve queda de 0,08% e na compara\u00e7\u00e3o mensal, houve alta de 2,2%. O mercado de carnes segue sustentado pelas exporta\u00e7\u00f5es, principalmente para a China.<\/p>\n<p>Analisando os cortes bovinos, os oriundos do dianteiro tiveram queda de 0,38%, enquanto os do traseiro subiram 0,01%.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A press\u00e3o causada pelo aumento da oferta de boiadas est\u00e1 menor nesse final de safra &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25240,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-25239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Scot Consultoria afirma que demanda interna ainda \u00e9 ponto de aten\u00e7\u00e3o e no mercado externo, d\u00f3lar em alta e demanda firme favorecem as exporta\u00e7\u00f5es","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25239"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25239\/revisions"}],"predecessor-version":[{"id":25241,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25239\/revisions\/25241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25240"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}