{"id":25389,"date":"2020-05-29T08:34:58","date_gmt":"2020-05-29T12:34:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25389"},"modified":"2020-05-29T08:34:58","modified_gmt":"2020-05-29T12:34:58","slug":"preco-do-leite-despenca-5-em-maio-veja-tendencia-para-junho","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/preco-do-leite-despenca-5-em-maio-veja-tendencia-para-junho\/","title":{"rendered":"Pre\u00e7o do leite despenca 5% em maio; veja tend\u00eancia para junho!"},"content":{"rendered":"<p>Depois de registrar altas entre dezembro e abril de 2020, o pre\u00e7o do leite pago ao produtor despencou em maio. Segundo o\u00a0<a href=\"https:\/\/cepea.esalq.usp.br\/br\"><strong>Centro de Estudos Avan\u00e7ados em Economia Aplicada (Cepea)<\/strong><\/a>, a \u2018m\u00e9dia Brasil\u2019 l\u00edquida em maio (referente \u00e0 capta\u00e7\u00e3o de abril) chegou a R$ 1,3783 por litro, recuo de 5% frente ao m\u00eas anterior. Na compara\u00e7\u00e3o com maio do ano passado, a queda foi de 11,2% em termos reais, ou seja, descontada a infla\u00e7\u00e3o.<\/p>\n<p>Segundo o Cepea, a desvaloriza\u00e7\u00e3o do leite no campo aconteceu\u00a0<strong>por conta das incertezas no mercado de derivados em abril, decorrentes da crise por causa da pandemia do novo coronav\u00edrus (Covid-19)<\/strong>.\u00a0 O centro de estudos explica que os servi\u00e7os de alimenta\u00e7\u00e3o (importantes canais de distribui\u00e7\u00e3o de l\u00e1cteos) foi prejudicado pelo agravamento da pandemia.<\/p>\n<p>Al\u00e9m disso, tamb\u00e9m houve a\u00a0<strong>diminui\u00e7\u00e3o da frequ\u00eancia das compras por parte dos consumidores<\/strong>, diante da\u00a0<strong>redu\u00e7\u00e3o da renda de muitas fam\u00edlias<\/strong>. \u201cAbril marcou o primeiro m\u00eas completo de enfrentamento \u00e0 pandemia e de, consequentemente, uma nova din\u00e2mica de consumo da popula\u00e7\u00e3o\u201d, disse o Cepea em boletim. Segundo agentes consultados, esses fatores impactaram negativamente sobre a demanda de derivados no correr de abril.<\/p>\n<h2><strong>Leite UHT<\/strong><\/h2>\n<p>De acordo com a pesquisa di\u00e1ria do Cepea, o pre\u00e7o do leite UHT (longa vida)\u00a0<strong>registrou queda acumulada de 17,8% em abril<\/strong>. Ainda assim, a m\u00e9dia mensal, de R$ 2,87 o litro, ficou 8,41% acima da registrada em mar\u00e7o, quando foi verificado o choque de demanda no in\u00edcio do isolamento social.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<h2><strong>Mu\u00e7arela<\/strong><\/h2>\n<p>O mercado de queijo mu\u00e7arela tamb\u00e9m foi afetado pelas incertezas do cen\u00e1rio atual, registrando demanda enfraquecida e volume reduzido de negocia\u00e7\u00f5es. Esse\u00a0<strong>derivado apresentou desvaloriza\u00e7\u00e3o acumulada de 8,3% em abril<\/strong>, e o pre\u00e7o m\u00e9dio mensal fechou a R$ 17,93 por quilo, recuo de 5,97% em rela\u00e7\u00e3o ao de mar\u00e7o.<\/p>\n<p>\u201cA dificuldade em se assegurar a liquidez impactou negativamente na produ\u00e7\u00e3o deste l\u00e1cteo em abril. Como consequ\u00eancia, houve aumento da oferta de leite cru no mercado\u00a0<em>spot<\/em>\u00a0(negocia\u00e7\u00e3o entre ind\u00fastrias) em abril. Em Minas Gerais, o pre\u00e7o m\u00e9dio do leite cru caiu 7,3% na primeira quinzena de abril e 11,7% na segunda\u201d, diz o Cepea.<\/p>\n<h2><strong>Capta\u00e7\u00e3o de leite<\/strong><\/h2>\n<p>A entressafra da produ\u00e7\u00e3o leiteira avan\u00e7a no Sudeste e Centro-Oeste. No Sul, a estiagem prejudica a atividade e compromete a quantidade e a qualidade da produ\u00e7\u00e3o de silagem para os pr\u00f3ximos meses. O\u00a0<strong>\u00cdndice de Capta\u00e7\u00e3o Leiteira do Cepea registrou queda de 0,6% de mar\u00e7o para abril<\/strong>\u00a0na \u2018m\u00e9dia Brasil\u2019 e acumula baixa de 12,4% neste ano.<\/p>\n<p>Tipicamente, neste cen\u00e1rio, as ind\u00fastrias empenhariam esfor\u00e7os para recompor seus estoques. Contudo, as perspectivas negativas sobre o consumo no m\u00e9dio e longo prazos aumentaram o n\u00edvel de incerteza em abril e diminu\u00edram o investimento das ind\u00fastrias em estoques, pressionando as cota\u00e7\u00f5es no campo em maio.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-3-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<h2><strong>Tend\u00eancia de pre\u00e7os<\/strong><\/h2>\n<p>O Cepea explica que como o pre\u00e7o do leite ao produtor \u00e9 formado depois das negocia\u00e7\u00f5es quinzenais do leite\u00a0<em>spot<\/em>\u00a0(negocia\u00e7\u00e3o de leite cru entre ind\u00fastrias) e das vendas de l\u00e1cteos,\u00a0<strong>as cota\u00e7\u00f5es no campo de junho refletir\u00e3o o mercado de derivados de maio.<\/strong><\/p>\n<p>Durante este m\u00eas, o observado \u00e9 que a produ\u00e7\u00e3o de leite no campo diminuiu. Como consequ\u00eancia, pesquisas apontam que o pre\u00e7o m\u00e9dio mensal do leite\u00a0<em>spot<\/em>\u00a0em Minas Gerais em maio foi 6,7% maior que o de abril, em termos nominais.<\/p>\n<p>\u201cA menor oferta no campo em maio e a menor produ\u00e7\u00e3o de derivados em abril, por sua vez, reduziram os estoques de UHT e mu\u00e7arela neste m\u00eas, favorecendo o aumento das cota\u00e7\u00f5es\u201d, diz.<\/p>\n<p>De 4 a 27 de maio, a pesquisa di\u00e1ria do Cepea mostrou alta acumulada de 14,4% para as cota\u00e7\u00f5es de UHT e eleva\u00e7\u00e3o de 15,7% para as de mu\u00e7arela. Ainda assim, as m\u00e9dias mensais parciais dos pre\u00e7os do UHT e da mu\u00e7arela neste per\u00edodo, de R$ 2,68 por litro e de R$ 17,90 o quilo, s\u00e3o 6,62% e 0,1% menores que as respectivas m\u00e9dias de abril.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de registrar altas entre dezembro e abril de 2020, o pre\u00e7o do leite pago &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25390,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-25389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Segundo o Cepea, na compara\u00e7\u00e3o com maio de 2019, a baixa \u00e9 de 11%; fechamento de restaurantes e diminui\u00e7\u00e3o nas compras pelo consumidor afetaram o mercado","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25389"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25389\/revisions"}],"predecessor-version":[{"id":25391,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25389\/revisions\/25391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25390"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}