{"id":25737,"date":"2020-06-11T16:52:03","date_gmt":"2020-06-11T20:52:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25737"},"modified":"2020-06-11T16:52:03","modified_gmt":"2020-06-11T20:52:03","slug":"governo-impoe-a-partir-da-2a-expediente-reduzido-em-turno-unico-diante-do-avanco-da-covid-19","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governo-impoe-a-partir-da-2a-expediente-reduzido-em-turno-unico-diante-do-avanco-da-covid-19\/","title":{"rendered":"Governo imp\u00f5e a partir da 2\u00aa expediente reduzido, em turno \u00fanico, diante do avan\u00e7o da covid-19"},"content":{"rendered":"<p>A partir da pr\u00f3xima segunda-feira (15) o expediente nas reparti\u00e7\u00f5es p\u00fablicas do Estado passa a ser das 07h30 \u00e0s 13h30.\u00a0<a href=\"https:\/\/www.iomat.mt.gov.br\/portal\/visualizacoes\/html\/15928\/#e:15928\/#m:1170023\" target=\"_blank\" rel=\"noopener noreferrer\">O decreto n\u00ba 520<\/a>\u00a0regulamentando a medida foi publicado na noite desta quarta-feira (10) e visa contribuir com o isolamento social como forma efetiva de evitar a propaga\u00e7\u00e3o do novo coronav\u00edrus. A decis\u00e3o do Governo levou em conta o aumento exponencial dos casos no Estado.<\/p>\n<p>Os servidores continuar\u00e3o trabalhando em regime de revezamento como vem ocorrendo desde o in\u00edcio da pandemia. Quando liberados do comparecimento f\u00edsico, dever\u00e3o prestar suas atividades de maneira remota obedecendo a mesma carga hor\u00e1ria.<\/p>\n<p>Os servidores do grupo de risco dever\u00e3o atuar apenas em teletrabalho, assim como aqueles que tenham tido contato direto com casos confirmados de coronav\u00edrus ou que apresentem sinais e sintomas gripais, tais como tosse, febre, coriza, dor de garganta e dificuldade para respirar.<\/p>\n<p>Caso as atividades desempenhadas pelo servidor sejam incompat\u00edveis com o teletrabalho a administra\u00e7\u00e3o poder\u00e1 lotar o servidor em unidade que seja poss\u00edvel a realiza\u00e7\u00e3o de trabalho remoto.<\/p>\n<p>Tamb\u00e9m est\u00e1 proibida\u00a0a circula\u00e7\u00e3o de pessoas nos pr\u00e9dios p\u00fablicos sem o uso de m\u00e1scara facial, mesmo que seja artesanal.<\/p>\n<p>Os atendimentos dever\u00e3o ser realizados preferencialmente por meio eletr\u00f4nico ou via telefone, e quando isso n\u00e3o for poss\u00edvel, os atendimentos presenciais dever\u00e3o ser agendados visando evitar aglomera\u00e7\u00f5es.<\/p>\n<p>Para contribuir com o isolamento social e evitar a propaga\u00e7\u00e3o da Covid-19, o Governo do Estado tamb\u00e9m decretou ponto facultativo nesta sexta-feira (12). As exce\u00e7\u00f5es s\u00e3o os \u00f3rg\u00e3os que trabalham em regime de plant\u00e3o, que exercem atividades essenciais como a seguran\u00e7a e a sa\u00fade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/odocumento.com.br\/\">Odocumento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir da pr\u00f3xima segunda-feira (15) o expediente nas reparti\u00e7\u00f5es p\u00fablicas do Estado passa a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-25737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25737"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25737\/revisions"}],"predecessor-version":[{"id":25739,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25737\/revisions\/25739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25738"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}