{"id":25742,"date":"2020-06-11T16:55:07","date_gmt":"2020-06-11T20:55:07","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25742"},"modified":"2020-06-11T16:55:07","modified_gmt":"2020-06-11T20:55:07","slug":"lockdown-em-confresa-mt-atinge-a-agricultura-familiar-e-a-pecuaria","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/lockdown-em-confresa-mt-atinge-a-agricultura-familiar-e-a-pecuaria\/","title":{"rendered":"Lockdown em Confresa-MT atinge a agricultura familiar e a pecu\u00e1ria"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/cdn.jwplayer.com\/players\/pNHM5Ndz-rdL4PV50.html\" width=\"640\" height=\"360\" frameborder=\"0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>O decreto de \u201clockdown\u201d em Confresa, entrou em vigor esta semana. Segundo o prefeito Ronio Cond\u00e3o, a decis\u00e3o levou em conta o n\u00famero de casos de Covid-19 no munic\u00edpio. At\u00e9 aqui s\u00e3o 192 registros, dos quais 15 profissionais da \u00e1rea da sa\u00fade. O decreto tamb\u00e9m atinge o agro. \u201cA agricultura familiar foi a mais atingida, porque houve fechamento total das feiras, comprometendo a comercializa\u00e7\u00e3o de hortifrutigranjeiros. J\u00e1 a agricultura mecanizada n\u00e3o foi afetada pela medida. Quanto \u00e0 pecu\u00e1ria, houve diminui\u00e7\u00e3o de 50% no n\u00famero de abates no frigor\u00edfico instalado na cidade\u201d, explica o prefeito de Confresa. Ele diz ainda que h\u00e1 uma equipe do munic\u00edpio avaliando a possibilidade de \u201cflexibiliza\u00e7\u00e3o ao final dos quinze dias de lockdown impostos pelo decreto\u201d, mas que isso \u201cir\u00e1 depender muito dos n\u00fameros da sa\u00fade na cidade\u201d.<\/p>\n<p>Desde o in\u00edcio da pandemia, os produtores rurais t\u00eam adotado medidas preventivas contra a Covid-19 e t\u00eam refor\u00e7ado os cuidados agora durante a colheita, quando a circula\u00e7\u00e3o de pessoas aumenta nas fazendas. Com o avan\u00e7o no n\u00famero de casos da doen\u00e7a em Mato Grosso \u2013 e, consequentemente \u2013 a implanta\u00e7\u00e3o de medidas mais restritivas em alguns munic\u00edpios, a preocupa\u00e7\u00e3o fica maior. Tanto com a sa\u00fade no campo, quanto com os reflexos para o setor.<\/p>\n<p>\u201cO campo est\u00e1 em plena colheita da safrinha. O transporte da produ\u00e7\u00e3o n\u00e3o foi prejudicado pelo \u2018lockdown\u2019. Mas, de qualquer forma, essa \u00e9 uma situa\u00e7\u00e3o grav\u00edssima para n\u00f3s. O agroneg\u00f3cio tamb\u00e9m se sente prejudicado\u201d, destaca Biraja Meireles Capuzzo, presidente do Sindicato Rural de Confresa.<\/p>\n<p>\u201cIsso impacta negativamente as atividades agropecu\u00e1rias de toda regi\u00e3o. Confresa concentra a maior parte das revendas, oficinas, armaz\u00e9ns, al\u00e9m do frigor\u00edfico. E o abate de gado da regi\u00e3o tamb\u00e9m j\u00e1 foi prejudicado. A nossa preocupa\u00e7\u00e3o agora tamb\u00e9m \u00e9 com o risco de a doen\u00e7a chegar no campo, nas fazendas\u201d, alerta o presidente do Sindicato Rural de Porto Alegre do Norte, Alessandro Pires Leandro.<\/p>\n<p>Mato Grosso tinha 4.762 casos de Covid-19 confirmados pela Secretaria Estadual de Sa\u00fade at\u00e9 a noite desta quarta-feira, 10. Quase o dobro do n\u00famero registrado no fim de maio (2.413). O crescimento acelerado nas \u00faltimas semanas, tende a seguir em ritmo forte, segundo uma pesquisa realizada pela Universidade Federal (UFMT). O estudo aponta o in\u00edcio do m\u00eas de setembro como o prov\u00e1vel pico da doen\u00e7a no estado, com aproximadamente 300 mil casos.<\/p>\n<p>Um dos respons\u00e1veis pela pesquisa, o professor Moises Cecconello explica que dois fatores podem alterar esta proje\u00e7\u00e3o. \u201cUm deles \u00e9 a subnotifica\u00e7\u00e3o. H\u00e1 evid\u00eancias de que existe subnotifica\u00e7\u00e3o, pessoas que contraem a \u2018Covid\u2019 mas n\u00e3o apresentam sintomas e acabam n\u00e3o procurando o sistema de sa\u00fade e portanto n\u00e3o entram nas estat\u00edsticas. N\u00f3s n\u00e3o levamos em conta a subnotifica\u00e7\u00e3o no estudo. Outro fator importante \u00e9 a ades\u00e3o da sociedade ao isolamento social, que \u00e9 a \u00fanica maneira de evitar a evolu\u00e7\u00e3o da doen\u00e7a no estado\u201d, refor\u00e7a<\/p>\n<p>Se a pesquisa for confirmada, o estado estar\u00e1 no auge da pandemia \u00e0s v\u00e9speras do in\u00edcio do plantio da safra de soja. O que refor\u00e7a a import\u00e2ncia da perman\u00eancia do alerta e da continuidade das medidas preventivas no campo. A agricultora Roseli Giachini endossa o recado: \u201co alerta nosso do setor \u00e9 para que estes profissionais que transitam tenham mais cuidado, usem a m\u00e1scara, fa\u00e7am higieniza\u00e7\u00e3o correta, evitem aglomera\u00e7\u00f5es. Porque ningu\u00e9m \u00e9 exce\u00e7\u00e3o! N\u00f3s estamos bastante preocupados diante deste aumento do n\u00famero de casos em Mato Grosso\u201d, enfatiza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/blogs.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O decreto de \u201clockdown\u201d em Confresa, entrou em vigor esta semana. Segundo o prefeito Ronio &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25743,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-25742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"N\u00famero de abates de bovinos foi reduzido pela metade, segundo a Prefeitura; aumento de casos de Covid-19 em Mato Grosso preocupa produtores rurais","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25742"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25742\/revisions"}],"predecessor-version":[{"id":25744,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25742\/revisions\/25744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25743"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}