{"id":25804,"date":"2020-06-13T12:11:41","date_gmt":"2020-06-13T16:11:41","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25804"},"modified":"2020-06-13T12:11:41","modified_gmt":"2020-06-13T16:11:41","slug":"confira-as-tendencias-para-o-boi-gordo-e-para-a-carne-bovina","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/confira-as-tendencias-para-o-boi-gordo-e-para-a-carne-bovina\/","title":{"rendered":"Confira as tend\u00eancias para o boi gordo e para a carne bovina"},"content":{"rendered":"<p>Em S\u00e3o Paulo, o pre\u00e7o m\u00e9dio do boi gordo acumula alta de 2,6% nos \u00faltimos 30 dias, mas recuo de 3,5% no acumulado de janeiro a junho de 2020, de acordo com a consultoria Cogo \u2013 Intelig\u00eancia em Agroneg\u00f3cio.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>\u201cA rea\u00e7\u00e3o dos pre\u00e7os do boi em junho decorre do quadro de oferta restrita, firme demanda externa, do retorno gradual de algumas atividades comerciais no pa\u00eds e do afrouxamento da quarentena em algumas regi\u00f5es.<\/p>\n<p>Em algumas regi\u00f5es pecu\u00e1rias, as escalas de abate est\u00e3o mais curtas, resultado da reten\u00e7\u00e3o de bovinos nas pastagens, que ainda apresentam boas condi\u00e7\u00f5es.<\/p>\n<p>As exporta\u00e7\u00f5es totais de carne bovina (in natura e industrializada) cresceram 9,1% entre janeiro a maio de 2020, quando comparados ao mesmo per\u00edodo de 2019.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em S\u00e3o Paulo, o pre\u00e7o m\u00e9dio do boi gordo acumula alta de 2,6% nos \u00faltimos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-25804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"De acordo com a consultoria Cogo \u2013 Intelig\u00eancia em Agroneg\u00f3cio, a mat\u00e9ria-prima vem se valorizando com oferta restrita e reabertura de economias","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25804"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25804\/revisions"}],"predecessor-version":[{"id":25806,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25804\/revisions\/25806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25805"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}