{"id":25830,"date":"2020-06-15T11:50:51","date_gmt":"2020-06-15T15:50:51","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=25830"},"modified":"2020-06-15T11:50:51","modified_gmt":"2020-06-15T15:50:51","slug":"militares-assinam-novo-manifesto-contra-ministro-do-supremo","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/militares-assinam-novo-manifesto-contra-ministro-do-supremo\/","title":{"rendered":"Militares assinam novo manifesto contra ministro do Supremo"},"content":{"rendered":"<div class=\"gd12\">\n<figure class=\"foto-legenda  componente-galeria\"><figcaption class=\"foto-legenda-citacao undefined\">\n<div class=\"undefined\">O presidente Jair Bolsonaro conta com a fidelidade das For\u00e7as Armadas desde o in\u00edcio da gest\u00e3o.<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\"\">Um manifesto contra o ministro Celso de Mello, do Supremo Tribunal Federal (STF) foi divulgado por um grupo de militares no s\u00e1bado (13). O documento foi compartilhado durante mais um cen\u00e1rio de crise entre o governo Jair Bolsonaro e o Supremo, ap\u00f3s o ministro\u00a0\u00a0<a href=\"https:\/\/ultimosegundo.ig.com.br\/2020-06-13\/supremo-recebe-com-cautela-nota-conjunta-do-planalto-sobre-forcas-armadas.html\" target=\"_blank\" rel=\"noopener noreferrer\">Luiz Fux concedeu uma liminar que afirma n\u00e3o ser da responsabilidade das For\u00e7as Armadas exercer Poder Moderador na Rep\u00fablica.<\/a><\/p>\n<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<p>\u201cA miss\u00e3o institucional das\u00a0<strong>For\u00e7as Armadas<\/strong>\u00a0na defesa da P\u00e1tria, na garantia dos poderes constitucionais e na garantia da lei e da ordem n\u00e3o acomoda o exerc\u00edcio de poder moderador entre os poderes Executivo, Legislativo e Judici\u00e1rio\u201d, escreveu o ministro.<\/p>\n<p>O presidente\u00a0<strong>Jair Bolsonaro<\/strong>\u00a0afirmou, em resposta, que as \u201cFFAA (\u00a0<strong>For\u00e7as Armadas<\/strong>\u00a0) do Brasil n\u00e3o cumprem ordens absurdas, como p. ex. a tomada de Poder. Tamb\u00e9m n\u00e3o aceitam tentativas de tomada de Poder por outro Poder da Rep\u00fablica, ao arrepio das Leis, ou por conta de julgamentos pol\u00edticos\u201d.<\/p>\n<p>Coron\u00e9is da For\u00e7a A\u00e9rea Brasileira est\u00e3o tomando a frente do manifesto, que recebeu 52 assinaturas de integrantes da\u00a0<strong>Aeron\u00e1utica<\/strong>\u00a0, 16 assinaturas da Marinha e 10 do Ex\u00e9rcito, todos de militares da reserva. Outros 30 civis e um oficial da\u00a0<strong>Pol\u00edcia Militar do Rio de Janeiro<\/strong>\u00a0assinaram o documento.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"http:\/\/ultimosegundo.ig.com.br\/politica\/2020-06-15\/militares-assinam-novo-manifesto-contra-ministro-do-supremo.html\" target=\"_blank\" rel=\"noopener noreferrer\">IG Pol\u00edtica<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro conta com a fidelidade das For\u00e7as Armadas desde o in\u00edcio da &hellip;<\/p>\n","protected":false},"author":4,"featured_media":25831,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-25830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=25830"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25830\/revisions"}],"predecessor-version":[{"id":25832,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/25830\/revisions\/25832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/25831"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=25830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=25830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=25830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}