{"id":26332,"date":"2020-07-06T09:05:03","date_gmt":"2020-07-06T13:05:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=26332"},"modified":"2020-07-06T09:05:03","modified_gmt":"2020-07-06T13:05:03","slug":"gabinete-de-bolsonaro-tinha-vaivem-suspeito-de-dinheiro-e-cargos-revela-jornal","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/gabinete-de-bolsonaro-tinha-vaivem-suspeito-de-dinheiro-e-cargos-revela-jornal\/","title":{"rendered":"Gabinete de Bolsonaro tinha vaivem suspeito de dinheiro e cargos, revela jornal"},"content":{"rendered":"<div class=\"gd12\">\n<figure class=\"foto-legenda undefined\"><figcaption class=\"foto-legenda-citacao undefined\">\n<div class=\"undefined\" style=\"text-align: left;\">Movimenta\u00e7\u00f5es analisadas s\u00e3o do tempo em que o presidente era deputado federal<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\"\" style=\"text-align: left;\">Uma intensa e incomum rotatividade salarial de assessores e exonera\u00e7\u00f5es \u201cde fachada\u201d. Assim pode ser\u00a0explicada a an\u00e1lise realizada em documentos relativos aos anos em que o\u00a0\u00a0<a href=\"https:\/\/ultimosegundo.ig.com.br\/brasil\/2020-07-02\/em-live-bolsonaro-ataca-a-imprensa-e-afirma-que-vai-vetar-lei-das-fake-news.html\">presidente Jair Bolsonaro<\/a>\u00a0era deputado federal e tinha grande movimenta\u00e7\u00e3o, tanto de pessoal quanto de dinheiro, dentro de seu gabinete.<\/p>\n<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<p class=\"\">Segundo den\u00fancia da Folha de S.Paulo, as movimenta\u00e7\u00f5es atingem cerca de um ter\u00e7o das mais de 100 pessoas que passaram pelo gabinete de\u00a0<strong>Bolsonaro<\/strong>\u00a0entre os anos de 1991 e 2018. Tal modelo de gest\u00e3o incluiu ainda a exonera\u00e7\u00e3o de auxiliares que eram recontratados no mesmo dia, pr\u00e1tica que acabou proibida pela C\u00e2mara dos Deputados sob o argumento de ser lesiva aos cofres p\u00fablicos.<\/p>\n<p>Entre os exemplos de movimenta\u00e7\u00f5es, est\u00e3o inclusive alguns assessores que deixaram o gabinete do pai Jair para assumir fun\u00e7\u00e3o ao lado de\u00a0<strong>Fl\u00e1vio Bolsonaro<\/strong>\u00a0, atualmente senador pelo Republicanos-RJ, quando ele ocupava cargo na Alerj e que hoje s\u00e3o investigados pelo s\u00a0<a href=\"https:\/\/ultimosegundo.ig.com.br\/brasil\/2020-07-01\/flavio-bolsonaro-tenta-manter-investigacao-da-rachadinha-na-2-instancia.html\">uposto esquema de rachadinha<\/a>\u00a0.<\/p>\n<p>A reportagem aponta ainda que a filha de\u00a0<a href=\"https:\/\/ultimosegundo.ig.com.br\/brasil\/2020-07-03\/queiroz-diz-que-esperava-ser-assessor-de-flavio-bolsonaro-no-senado.html\">Fabr\u00edcio Queiroz<\/a>\u00a0, ex-assessor do Fl\u00e1vio que foi preso no \u00faltimo m\u00eas em uma casa na cidade de Atibaia, Nath\u00e1lia\u00a0<strong>Queiroz<\/strong>\u00a0, tamb\u00e9m consta na lista de movimenta\u00e7\u00f5es suspeitas, tendo diversas \u201coscila\u00e7\u00f5es salariais\u201d at\u00e9 ser demitida em 2018, mesmo dia em que o pai foi exonerado.<\/p>\n<p>Sobre as \u201cdemiss\u00f5es de fachada\u201d, o levantamento mostra que o\u00a0<strong>gabinete<\/strong>\u00a0de Bolsonaro registrou nada menos do que 18 exonera\u00e7\u00f5es de assessores nos 12 meses anteriores ao ato da C\u00e2mara que proibiu tal a\u00e7\u00e3o, sendo que todos foram recontratados sempre no mesmo dia da demiss\u00e3o.<\/p>\n<p>Vale ressaltar que a\u00a0<strong>C\u00e2mara<\/strong>\u00a0dos Deputados tem uma grande verba para gastos\u00a0dos parlamentares. Atualmente, cada um dos deputados recebe uma conta de mais de R$ 111 mil para contrata\u00e7\u00f5es, que devem ser de um m\u00ednimo de 5 e um m\u00e1ximo de 25. As remunera\u00e7\u00f5es tamb\u00e9m variam, indo de R$ 1.025 para as fun\u00e7\u00f5es mais simples at\u00e9 R$ 15.698 para os chefes de gabinete.<\/p>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"http:\/\/ultimosegundo.ig.com.br\/politica\/2020-07-05\/gabinete-de-bolsonaro-tinha-vaivem-suspeito-de-dinheiro-e-cargos-revela-jornal.html\" target=\"_blank\" rel=\"noopener noreferrer\">IG Pol\u00edtica<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Movimenta\u00e7\u00f5es analisadas s\u00e3o do tempo em que o presidente era deputado federal Uma intensa e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":26333,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-26332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=26332"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26332\/revisions"}],"predecessor-version":[{"id":26334,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26332\/revisions\/26334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/26333"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=26332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=26332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=26332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}