{"id":26338,"date":"2020-07-06T09:08:12","date_gmt":"2020-07-06T13:08:12","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=26338"},"modified":"2020-07-06T09:08:12","modified_gmt":"2020-07-06T13:08:12","slug":"apos-eliminar-15-dos-gafanhotos-combate-na-argentina-continua","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/apos-eliminar-15-dos-gafanhotos-combate-na-argentina-continua\/","title":{"rendered":"Ap\u00f3s eliminar 15% dos gafanhotos, combate na Argentina continua"},"content":{"rendered":"<div><iframe loading=\"lazy\" title=\"Ap\u00f3s eliminar 15% dos gafanhotos, combate na Argentina continua\" src=\"https:\/\/cdn.jwplayer.com\/players\/4YM3AOtA-mRdfRHzk.html\" width=\"100%\" height=\"100%\" frameborder=\"0\" scrolling=\"auto\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p>Assim como nos dias anteriores, o domingo, 5, foi de ca\u00e7a aos gafanhotos para as equipes do Servi\u00e7o Nacional de Sanidade e Qualidade Agroalimentar da Argentina (Senasa) na prov\u00edncia de Corrientes. Conforme o boletim do \u00f3rg\u00e3o, os t\u00e9cnicos visualizaram os insetos se deslocando no sentido norte\/noroeste, na regi\u00e3o do munic\u00edpio de Sauce. A estimativa das equipes \u00e9 de que os insetos pousaram no final da tarde em uma \u00e1rea em Curuzu Quati\u00e1, a cerca de 180 quil\u00f4metros de Uruguaiana (RS).<\/p>\n<p>\u201cNa tarde do domingo, os t\u00e9cnicos avistaram os insetos mas horas depois perderam contato visual com os gafanhotos nessa regi\u00e3o. A busca havia come\u00e7ado pela manh\u00e3, ao norte de Sauce. Quando terminaram as estradas secund\u00e1rias, o grupo come\u00e7ou a seguir para norte pela Ruta 23. No caminho, eles ainda cruzaram por alguns insetos que provavelmente se desgarraram da nuvem. A regi\u00e3o \u00e9 in\u00f3spita e de dif\u00edcil deslocamento \u2013 pela falta de estradas e muitas regi\u00f5es de vegeta\u00e7\u00e3o fechada e banhados se revezando com campos\u201d.<\/p>\n<p>Mesmo com os insetos tendo se deslocado no fim de semana em dire\u00e7\u00e3o oposta, segue o alerta na fronteira ga\u00facha com a Argentina. Conforme o fiscal agropecu\u00e1rio Juliano Ritter, da Secretaria de Agricultura do Estado, com a chegada de uma frente fria, o tempo deve esfriar no Rio Grande do Sul nesta semana \u2013 o que seria pouco convidativo para gafanhotos. Embora o vento possa mudar em dire\u00e7\u00e3o ao estado na quarta-feira, 8.<\/p>\n<h2><strong>Fim de semana<\/strong><\/h2>\n<p>Os gafanhotos voltaram a se deslocar depois de uma<strong>\u00a0aplica\u00e7\u00e3o a\u00e9rea realizada na manh\u00e3 de quinta-feira, 2<\/strong>, que eliminou cerca de 15% da nuvem. Embora o Senasa n\u00e3o tenha divulgado uma avalia\u00e7\u00e3o precisa do resultado, a estimativa foi informada pelo representante local das Confedera\u00e7\u00f5es Rurais Argentinas (CRA) Martin Rapetti. Com o frio, os gafanhotos est\u00e3o se deslocando em voos curtos desde sexta e sendo rastreados pelos t\u00e9cnicos do governo argentino.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>A opera\u00e7\u00e3o a\u00e9rea do dia 2 foi a segunda contra os gafanhotos. Ela cobriu uma \u00e1rea de 115 hectares no norte de Sauce, onde os insetos permaneceram pousados desde a segunda-feira, dia 29. A opera\u00e7\u00e3o a\u00e9rea anterior havia ocorrido no dia 26 de junho, quando a nuvem estava pousada em uma \u00e1rea de 70 hectares no interior do munic\u00edpio de Curuz\u00fa Quati\u00e1 \u2013 mais a leste na prov\u00edncia. A estimativa \u00e9 de que, na ocasi\u00e3o, outros 15% dos gafanhotos haviam sido eliminados.<\/p>\n<p>Tamb\u00e9m no \u00faltimo dia 2, representantes do Sindicato Nacional das Empresas de Avia\u00e7\u00e3o Agr\u00edcola (Sindag), do Minist\u00e9rio da Agricultura, da Secretaria de Agricultura do Rio Grande do Sul e de outras entidades brasileiras participaram de uma videoconfer\u00eancia com as entidades de avia\u00e7\u00e3o agr\u00edcola da Argentina e Uruguai, al\u00e9m de autoridades do minist\u00e9rios da Agricultura dos dois pa\u00edses. O objetivo foi nivelar as informa\u00e7\u00f5es entre os t\u00e9cnicos, autoridades e operadores aeroagr\u00edcolas.<\/p>\n<p>Um dos destaques foi a apresenta\u00e7\u00e3o do chefe do Programa Nacional de Gafanhotos e Ticuras da Argentina, Hector Em\u00edlio Medina. Ele relatou o hist\u00f3rico das a\u00e7\u00f5es de combate a gafanhotos em seu pa\u00eds desde a funda\u00e7\u00e3o do programa, em 1891. E ressaltou o aumento, desde 2015, na incid\u00eancia de grandes nuvens de gafanhotos na regi\u00e3o entre o norte argentino, o Paraguai e a Bol\u00edvia. A nuvem que atualmente est\u00e1 na prov\u00edncia de Corrientes havia sido detectada pela primeira vez em 11 de maio, quando o Servi\u00e7o de Qualidade e Sanidade Vegetal do Paraguai (Senave) alertou o governo argentino de que uma nuvem de gafanhotos estava se deslocando pela regi\u00e3o do Chaco rumo sul.<\/p>\n<p>A partir da\u00ed, os insetos seguiram por mais de mil quil\u00f4metros, com as correntes de vento e temperaturas altas para essa \u00e9poca, at\u00e9 pr\u00f3ximo \u00e0 fronteira com o Rio Grande do Sul e o Uruguai. Foi a primeira vez em mais de 70 anos que uma nuvem t\u00e3o grande chegava \u00e0 regi\u00e3o. Por conta disso, o\u00a0<a href=\"https:\/\/www.canalrural.com.br\/noticias\/gafanhotos-governo-declara-estado-emergencia\/\"><strong>Minist\u00e9rio da Agricultura do Brasil decretou emerg\u00eancia fitossanit\u00e1ria<\/strong><\/a>\u00a0para se preparar para o combate \u00e0 praga e as empresas associadas ao Sindicato Nacional das Empresas de Avia\u00e7\u00e3o Agr\u00edcola (Sindag) no estado entraram em alerta.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-3-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>Ao mesmo tempo, o sindicato aeroagr\u00edcola elaborou o texto preliminar de um plano para um programa permanente para enfretamento da praga no Brasil. Isso a partir dos protocolos do Senasa e da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Alimenta\u00e7\u00e3o e a Agricultura (FAO). O documento segue sendo avaliado pela pasta e abrange dados sobre as caracter\u00edsticas dos insetos e sua voracidade, as formas de combate em cada est\u00e1gio e a tecnologia dispon\u00edvel no pa\u00eds.<\/p>\n<p>O estudo refor\u00e7a ainda os requisitos legais para as empresas aeroagr\u00edcolas operarem, desde registros e licen\u00e7as ambientais at\u00e9 a forma\u00e7\u00e3o m\u00ednima da equipe. A elabora\u00e7\u00e3o do plano ficou a cargo de uma equipe de agr\u00f4nomos, todos com doutorados abrangendo \u00e1reas de Bioqu\u00edmica, Fisiologia, Entomologia e Tecnologias de Aplica\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assim como nos dias anteriores, o domingo, 5, foi de ca\u00e7a aos gafanhotos para as &hellip;<\/p>\n","protected":false},"author":4,"featured_media":26339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-26338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Estimativa \u00e9 de que os insetos pousaram no final da tarde do domingo, 5, em uma \u00e1rea em Curuzu Quati\u00e1, a cerca de 180 quil\u00f4metros de Uruguaiana (RS)","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=26338"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26338\/revisions"}],"predecessor-version":[{"id":26340,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26338\/revisions\/26340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/26339"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=26338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=26338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=26338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}