{"id":26614,"date":"2020-07-15T09:35:33","date_gmt":"2020-07-15T13:35:33","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=26614"},"modified":"2020-07-15T09:35:33","modified_gmt":"2020-07-15T13:35:33","slug":"cuiaba-vai-adquirir-40-mil-kits-para-testagem-da-covid-19-com-analise-realizada-pelo-ifmt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cuiaba-vai-adquirir-40-mil-kits-para-testagem-da-covid-19-com-analise-realizada-pelo-ifmt\/","title":{"rendered":"Cuiab\u00e1 vai adquirir 40 mil kits para testagem da Covid-19 com an\u00e1lise realizada pelo IFMT"},"content":{"rendered":"<p>A Prefeitura de Cuiab\u00e1 vai adquirir 40 mil novos kits para testagem em massa da popula\u00e7\u00e3o no combate ao novo Coronav\u00edrus. Do tipo RT-PCR\u2019s, o material \u00e9 um refor\u00e7o estrat\u00e9gico no combate a COVID-19 e ser\u00e3o destinados ao Laborat\u00f3rio de Biotecnologia do Instituto Federal de mato Grosso\u200a\u2014\u200acampus Bela Vista, que conduz os exames em parceria com o Munic\u00edpio deste maio.<\/p>\n<p>\u201cEssa parceria \u00e9 exatamente para ajudar a fazer as testagens em massa, de alta precis\u00e3o e que est\u00e3o obtendo resultado no combate ao v\u00edrus. Precisamos avan\u00e7ar nesse quesito e tornar mais assertiva as a\u00e7\u00f5es da Prefeitura, agindo nas regi\u00f5es de maior incid\u00eancia, al\u00e9m de proteger a popula\u00e7\u00e3o com outras medidas\u201d, comentou o prefeito de Cuiab\u00e1, Emanuel Pinheiro.<\/p>\n<p>A parceria entre a institui\u00e7\u00e3o de ensino e a Prefeitura de Cuiab\u00e1 no combate ao novo Coronav\u00edrus teve in\u00edcio ainda em mar\u00e7o, com a fabrica\u00e7\u00e3o de \u00e1lcool 70%. Em maio, a institui\u00e7\u00e3o come\u00e7ou a realizar os exames laboratoriais de diagn\u00f3stico da COVID-19. At\u00e9 esta segunda-feira (13), a equipe do Campus Cuiab\u00e1\u200a\u2014\u200aBela Vista realizou 3.500 an\u00e1lises das cinco mil adquiridas inicialmente pela Prefeitura.<\/p>\n<p>Na ocasi\u00e3o, a Prefeitura de Cuiab\u00e1 adquiriu um equipamento RT-PCR, ideal para a an\u00e1lise das amostras coletadas nas unidades de sa\u00fade p\u00fablicas. O equipamento foi doado ao Campus e segue com utiliza\u00e7\u00e3o permanente do laborat\u00f3rio.<\/p>\n<p><strong>Novo laborat\u00f3rio<\/strong><\/p>\n<p>Al\u00e9m dos exames j\u00e1 realizados, um novo laborat\u00f3rio est\u00e1 em fase de constru\u00e7\u00e3o para amplia\u00e7\u00e3o dos exames na Capital. O Prefeito Emanuel Pinheiro visitou nesta segunda-feira (14) as obras localizadas no Campus Cuiab\u00e1\u200a\u2014\u200aBela Vista.<\/p>\n<p>A estrutura, viabilizada por meio de parceria entre Prefeitura de Cuiab\u00e1, Minist\u00e9rio P\u00fablico Estadual, Minist\u00e9rio P\u00fablico Federal, Campus Cuiab\u00e1\u200a\u2014\u200aBela Vista do IFMT e deputado federal Emanuel Pinheiro Neto, ser\u00e1 constru\u00edda na modalidade modular, por isso a previs\u00e3o \u00e9 de que esteja finalizada e pronta para uso em 45 dias, a partir do in\u00edcio das obras.<\/p>\n<p>A estrutura e terraplanagem, no valor de R$100 mil ser\u00e1 ofertada pelo IFMT\u200a\u2014\u200acampus Bela Vista. A institui\u00e7\u00e3o \u00e9 quem vai operar o local, com sua equipe de profissionais volunt\u00e1rios. O Minist\u00e9rio P\u00fablico Federal far\u00e1 o investimento de R$ 1 milh\u00e3o para custear o restante das obras. J\u00e1 a Prefeitura de Cuiab\u00e1 e o deputado federal Emanuel Pinheiro Neto contribuir\u00e3o com os equipamentos e aquisi\u00e7\u00e3o dos kits para testagem.<\/p>\n<p>No novo laborat\u00f3rio ser\u00e3o realizados os testes de IgG e IgM que, diferente do exame RT-PCR j\u00e1 realizado no Campus, permite mensurar a quantidade de anticorpos do novo Coronavirus em amostras de sangue, sendo poss\u00edvel diagnosticar se o paciente tem ou j\u00e1 contraiu o v\u00edrus anteriormente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 \u00a0<a href=\"https:\/\/odocumento.com.br\/\">Odocumento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1 vai adquirir 40 mil novos kits para testagem em massa da &hellip;<\/p>\n","protected":false},"author":4,"featured_media":26615,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-26614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"A parceria entre as duas institui\u00e7\u00f5es teve in\u00edcio ainda em mar\u00e7o, com a fabrica\u00e7\u00e3o de \u00e1lcool 70%","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=26614"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26614\/revisions"}],"predecessor-version":[{"id":26616,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26614\/revisions\/26616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/26615"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=26614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=26614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=26614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}