{"id":26742,"date":"2020-07-19T13:27:32","date_gmt":"2020-07-19T17:27:32","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=26742"},"modified":"2020-07-19T13:27:32","modified_gmt":"2020-07-19T17:27:32","slug":"nuvem-de-gafanhotos-volta-a-se-movimentar-na-argentina-confira-a-nova-localizacao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/nuvem-de-gafanhotos-volta-a-se-movimentar-na-argentina-confira-a-nova-localizacao\/","title":{"rendered":"Nuvem de gafanhotos volta a se movimentar na Argentina; confira a nova localiza\u00e7\u00e3o"},"content":{"rendered":"<p>A nuvem de gafanhotos que se movimenta pela fronteira entre Brasil e Argentina h\u00e1 algumas semanas tem uma nova localiza\u00e7\u00e3o, informou o Servi\u00e7o Nacional de Sanidade e Qualidade Agroalimentaria (Senasa).<\/p>\n<p>Segundo o servi\u00e7o argentino, a nuvem se moveu 33 quil\u00f4metros ao sul e est\u00e1 em Sauce, a 122 quil\u00f4metros da cidade ga\u00facha de Barra do Quara\u00ed. De acordo com o fiscal estadual agropecu\u00e1rio do Rio Grande do Sul, Juliano Ritter, o Brasil continua acompanhando a movimenta\u00e7\u00e3o dos insetos.<\/p>\n<p>As equipes do Senasa realizaram tratamento fitossanit\u00e1rio para diminuir a densidade populacional da nuvem de gafanhotos. A entidade est\u00e1 acompanhando de perto o deslocamento dos insetos e alerta que o Servi\u00e7o Meteorol\u00f3gico Nacional (SMN) de Argentina previu aumento das temperaturas e ventos soprando de norte, o que ocasionou esse deslocamento para o sul.<\/p>\n<h3><strong>Nuvem paraguaia<\/strong><\/h3>\n<p>A segunda nuvem de gafanhotos que deixou o Brasil em alerta se movimentou nesta sexta-feira, 17. De acordo com o Servi\u00e7o de Qualidade e Sanidade Vegetal (Senave), os insetos, que estavam em \u00e1reas de Madrej\u00f3n e 4 de Mayio, no Paraguai, seguiram para o sudeste, em dire\u00e7\u00e3o a Teniente Pico, no departamento de Boquer\u00f3n, tamb\u00e9m no pa\u00eds.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>Segundo o \u00f3rg\u00e3o paraguaio, equipes t\u00e9cnicas permanecem na \u00e1rea e indicam que os insetos continuam em constante movimento. \u201cEsse monitoramento permanente \u00e9 realizado para localiz\u00e1-los e poder aplicar os controles fitossanit\u00e1rios correspondentes\u201d, diz.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nuvem de gafanhotos que se movimenta pela fronteira entre Brasil e Argentina h\u00e1 algumas &hellip;<\/p>\n","protected":false},"author":4,"featured_media":26743,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-26742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"De acordo com o fiscal estadual agropecu\u00e1rio do Rio Grande do Sul, Juliano Ritter, o Brasil continua acompanhando a movimenta\u00e7\u00e3o dos insetos","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=26742"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26742\/revisions"}],"predecessor-version":[{"id":26744,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26742\/revisions\/26744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/26743"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=26742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=26742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=26742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}