{"id":26923,"date":"2020-07-25T07:28:42","date_gmt":"2020-07-25T11:28:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=26923"},"modified":"2020-07-24T20:37:04","modified_gmt":"2020-07-25T00:37:04","slug":"confira-a-programacao-de-zeladoria-montado-pela-limpurb-para-este-fim-de-semana","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/confira-a-programacao-de-zeladoria-montado-pela-limpurb-para-este-fim-de-semana\/","title":{"rendered":"Confira a programa\u00e7\u00e3o de zeladoria montado pela Limpurb para este fim de semana"},"content":{"rendered":"<p>A Prefeitura de Cuiab\u00e1 preparou uma nova e extensa programa\u00e7\u00e3o de zeladoria para este fim de semana. Coordenados pela Empeza Cuiabana de Zeladoria e Servi\u00e7os Urbanos (Limpurb), os trabalhos foram intensificados e abrangem diferentes regi\u00f5es da cidade, onde ser\u00e3o realizados diversos servi\u00e7os relacionados a limpeza p\u00fablica.<\/p>\n<p>O cronograma come\u00e7ou a ser colocado em pr\u00e1tica j\u00e1 nesta sexta-feira (24), com uma equipe atuando na Avenida Carlos Ador de Souza, no bairro S\u00e3o Jo\u00e3o Del Rey, no trecho situado entre a rotat\u00f3ria da Avenida Dr. Meirelles e a entrada dos residenciais Nico Baracat I e II. Na via \u00e9 executada a varri\u00e7\u00e3o, ro\u00e7agem, poda de \u00e1rvores e pintura de meio-fio.<\/p>\n<p>Paralelamente, a Trincheira Jurumirim tamb\u00e9m come\u00e7ou a receber, nesta sexta-feira, servi\u00e7os de zeladoria, que ser\u00e3o continuados no s\u00e1bado (25). \u201cImplantamos uma programa\u00e7\u00e3o de fim de semana que engloba um grande conjunto de servi\u00e7os. S\u00e3o ajustes necess\u00e1rios que fazemos em nossa rotina de trabalho, para que Cuiab\u00e1 siga evoluindo nesse quesito\u201d, explica o secret\u00e1rio da Limpurb, Anderson Matos.<\/p>\n<p><strong>MUTIR\u00d5ES<\/strong><\/p>\n<p>Al\u00e9m das interven\u00e7\u00f5es iniciadas nesta sexta-feira, a programa\u00e7\u00e3o montada pelo Munic\u00edpio conta ainda com a realiza\u00e7\u00e3o de dois mutir\u00f5es no s\u00e1bado. O primeiro \u00e9 o tradicional Mutir\u00e3o da Limpeza, que todo fim de semana atende uma nova comunidade. Para esta edi\u00e7\u00e3o, o bairro contemplado \u00e9 o Jardim Tropical, localizado na regi\u00e3o Leste da Capital.<\/p>\n<p>A a\u00e7\u00e3o contar\u00e1 com cerca de 150 trabalhadores, atuando no no per\u00edodo das 7h \u00e0s 11h. Na oportunidade, a comunidade receber\u00e1 os servi\u00e7os de limpeza das ruas, pintura de meio-fio, ro\u00e7agem, capina\u00e7\u00e3o, poda de \u00e1rvores, manuten\u00e7\u00e3o da ilumina\u00e7\u00e3o p\u00fablica, al\u00e9m dos caminh\u00f5es do Cata-treco e, igualmente, a retirada de todos os bols\u00f5es de lixo encontrados no local.<\/p>\n<p>Tamb\u00e9m acontece no s\u00e1bado o Mutir\u00e3o Contra Bols\u00f5es de Lixo. Para este fim de semana, a Limpurb dar\u00e1 continuidade ao trabalho iniciado na estrada de acesso a Ponte de Ferro, para a elimina\u00e7\u00e3o de aproximadamente um quil\u00f4metro de bols\u00e3o de lixo. Al\u00e9m disso, est\u00e1 no planejamento, para o mesmo dia, iniciar o processo em uma \u00e1rea situada no bairro Dr. F\u00e1bio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por: \u00a0 Bruno Vicente \u00a0 \u00a0| \u00a0 Foto: \u00a0 Davi Valle \u00a0 | \u00a0 Fonte: \u00a0<a href=\"https:\/\/www.cuiaba.mt.gov.br\/\">Prefeitura de Cuiab\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1 preparou uma nova e extensa programa\u00e7\u00e3o de zeladoria para este fim &hellip;<\/p>\n","protected":false},"author":4,"featured_media":26924,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,59,77],"tags":[],"class_list":["post-26923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news","category-destaque","category-estudo"],"wps_subtitle":"Os trabalhos foram intensificados e abrangem diferentes regi\u00f5es da cidade","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=26923"}],"version-history":[{"count":2,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26923\/revisions"}],"predecessor-version":[{"id":26926,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/26923\/revisions\/26926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/26924"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=26923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=26923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=26923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}