{"id":27068,"date":"2020-07-30T09:55:10","date_gmt":"2020-07-30T13:55:10","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=27068"},"modified":"2020-07-30T09:55:10","modified_gmt":"2020-07-30T13:55:10","slug":"leite-preco-em-julho-subiu-25-ante-mesmo-periodo-de-2019-diz-cepea","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/leite-preco-em-julho-subiu-25-ante-mesmo-periodo-de-2019-diz-cepea\/","title":{"rendered":"Leite: pre\u00e7o em julho subiu 25% ante mesmo per\u00edodo de 2019, diz Cepea"},"content":{"rendered":"<p>O pre\u00e7o do leite ao produtor em julho, referente \u00e0 capta\u00e7\u00e3o de junho, registrou expressivas altas de 16,1% em rela\u00e7\u00e3o ao m\u00eas anterior e de 25% em compara\u00e7\u00e3o com igual m\u00eas do ano passado (deflacionado pelo IPCA de junho\/20), considerando a \u201cM\u00e9dia Brasil\u201d, que inclui os principais Estados produtores.<\/p>\n<p>A cota\u00e7\u00e3o de R$ 1,7573\/litro \u00e9 o maior valor registrado para um m\u00eas de julho e o segundo mais alto de toda a s\u00e9rie hist\u00f3rica do Centro de Estudos Avan\u00e7ados em Economia Aplicada (Cepea\/Esalq\/USP), desde 2004, atr\u00e1s apenas da m\u00e9dia de agosto\/16 (R$ 1,7751\/litro).<\/p>\n<p>Segundo o Cepea, a eleva\u00e7\u00e3o nos pre\u00e7os deve-se \u00e0 maior competi\u00e7\u00e3o entre as ind\u00fastrias de latic\u00ednios para garantir a compra de mat\u00e9ria-prima em junho. Os pesquisadores explicam que a concorr\u00eancia acirrada, por sua vez, esteve atrelada \u00e0 necessidade de se refazer estoques de derivados l\u00e1cteos.<\/p>\n<p>\u201cTipicamente, as ind\u00fastrias empenham esfor\u00e7os nessa dire\u00e7\u00e3o antes de abril, prevendo que a capta\u00e7\u00e3o caia nos meses posteriores. Contudo, neste ano, as perspectivas negativas sobre o consumo nos m\u00e9dio e longo prazos diante da pandemia da covid-19 aumentaram o n\u00edvel de incerteza em abril e diminu\u00edram os investimentos das ind\u00fastrias em estoques\u201d, informa o Cepea.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>Com a rea\u00e7\u00e3o no consumo, ancorada nos programas de aux\u00edlio emergencial, as vendas de l\u00e1cteos se fortaleceram em maio e junho, reduzindo ainda mais os estoques. Diante disso, houve expressivas altas nos pre\u00e7os dos derivados l\u00e1cteos em junho: de 17,7% no caso do UHT, de 23% para a mussarela e de 10,9% no leite em p\u00f3. No campo, a oferta restrita em junho resultou em disparada no valor do leite spot. Na m\u00e9dia de junho, o pre\u00e7o do leite spot em Minas Gerais ficou 45% acima do de maio, em termos nominais, chegando a R$ 2,28\/litro.<\/p>\n<p>O Cepea destaca que existe uma tend\u00eancia t\u00edpica de aumento das cota\u00e7\u00f5es ao produtor entre mar\u00e7o e agosto, por causa da sazonalidade da produ\u00e7\u00e3o. Neste per\u00edodo, a capta\u00e7\u00e3o de leite \u00e9 prejudicada pela baixa disponibilidade de pastagens, em decorr\u00eancia da diminui\u00e7\u00e3o das chuvas no Sudeste e no Centro-Oeste.<\/p>\n<p>No entanto, o \u00cdndice de Capta\u00e7\u00e3o Leiteira (ICAP-L) do Cepea registrou alta de 4,5% frente a maio na \u201cM\u00e9dia Brasil\u201d, puxado pelos aumentos de 10% no volume captado no Rio Grande do Sul, de 7% em Santa Catarina e de 7,4% no Paran\u00e1. Segundo o Cepea, a maior capta\u00e7\u00e3o no Sul esteve relacionada \u00e0s melhores condi\u00e7\u00f5es clim\u00e1ticas e tamb\u00e9m \u00e0 amplia\u00e7\u00e3o do fornecimento de concentrado e silagem, estimulados pelos elevados n\u00edveis de pre\u00e7os do leite.<\/p>\n<p>Os pesquisadores do Cepea ressaltam, entretanto, que, comparado ao ano anterior, os custos de produ\u00e7\u00e3o leiteira est\u00e3o mais elevados. Pesquisas do Cepea mostram que, com o recuo nas cota\u00e7\u00f5es do milho em junho, melhorou para o pecuarista a rela\u00e7\u00e3o de troca, sendo necess\u00e1rios 35,2 litros de leite para a aquisi\u00e7\u00e3o de uma saca de 60 kg de milho. Entretanto, em junho de 2019, eram necess\u00e1rios apenas 24,9 litros para uma saca de milho. Dessa forma, o poder de compra do produtor de leite diminuiu quase 30% na compara\u00e7\u00e3o anual.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pre\u00e7o do leite ao produtor em julho, referente \u00e0 capta\u00e7\u00e3o de junho, registrou expressivas &hellip;<\/p>\n","protected":false},"author":4,"featured_media":27069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-27068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"De acordo com levantamento, a eleva\u00e7\u00e3o nos pre\u00e7os deve-se \u00e0 maior competi\u00e7\u00e3o entre as ind\u00fastrias de latic\u00ednios para garantir a compra de mat\u00e9ria-prima em junho","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=27068"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27068\/revisions"}],"predecessor-version":[{"id":27070,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27068\/revisions\/27070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/27069"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=27068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=27068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=27068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}