{"id":27214,"date":"2020-08-05T10:20:58","date_gmt":"2020-08-05T14:20:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=27214"},"modified":"2020-08-05T10:20:58","modified_gmt":"2020-08-05T14:20:58","slug":"bovino-para-reposicao-em-julho-precos-subiram-mais-8-diz-scot","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/bovino-para-reposicao-em-julho-precos-subiram-mais-8-diz-scot\/","title":{"rendered":"Bovino para reposi\u00e7\u00e3o: em julho, pre\u00e7os subiram mais 8%, diz Scot"},"content":{"rendered":"<p>Na m\u00e9dia de todas as categorias e estados monitorados pela Scot Consultoria, entre machos e f\u00eameas anelorados e mesti\u00e7os, os pre\u00e7os do bovino para reposi\u00e7\u00e3o fecharam com alta de 2,1% na \u00faltima semana de julho. Ao longo do m\u00eas a valoriza\u00e7\u00e3o acumulada foi de 8,2%.<\/p>\n<p>De acordo com a consultoria, o mercado do boi gordo mais firme na \u00faltima semana aumentou a procura por animais de reposi\u00e7\u00e3o. As categorias mais eradas s\u00e3o as mais procuradas, mas devido \u00e0 oferta restrita e os pre\u00e7os acima das refer\u00eancias, os neg\u00f3cios flu\u00edram com dificuldade nos \u00faltimos dias.<\/p>\n<p>Para o boi magro, o destaque da semana ficou para Goi\u00e1s e Mato Grosso, com altas de 5,5% e 3,8%, respectivamente, na \u00faltima semana. J\u00e1 para o garrote anelorado, nesse mesmo intervalo, a alta mais significativa ficou para o Par\u00e1, valoriza\u00e7\u00e3o de 4,2%.<\/p>\n<p>Para o curto prazo, a tend\u00eancia \u00e9 de que a procura por reposi\u00e7\u00e3o permane\u00e7a em bom ritmo, apoiada na firmeza do mercado do boi gordo, que tende a seguir positivo nos pr\u00f3ximos dias.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na m\u00e9dia de todas as categorias e estados monitorados pela Scot Consultoria, entre machos e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":27215,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-27214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"De acordo com a consultoria, o mercado do boi gordo mais firme na \u00faltima semana aumentou a procura por animais de reposi\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=27214"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27214\/revisions"}],"predecessor-version":[{"id":27216,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27214\/revisions\/27216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/27215"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=27214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=27214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=27214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}