{"id":27324,"date":"2020-08-10T09:43:12","date_gmt":"2020-08-10T13:43:12","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=27324"},"modified":"2020-08-10T09:43:12","modified_gmt":"2020-08-10T13:43:12","slug":"polinizacao-assistida-e-inteligente-aumenta-em-20-producao-de-cafe-diz-startup","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/polinizacao-assistida-e-inteligente-aumenta-em-20-producao-de-cafe-diz-startup\/","title":{"rendered":"Poliniza\u00e7\u00e3o assistida e inteligente aumenta em 20% produ\u00e7\u00e3o de caf\u00e9, diz startup"},"content":{"rendered":"<p>Lavouras de caf\u00e9 que receberam poliniza\u00e7\u00e3o assistida e inteligente promovida pela startup Agrobee, na safra 2019\/20200, registraram aumento de 20% na produtividade. O dado foi mencionado na quinta-feira, 6, durante a live \u201cMulheres no Agroneg\u00f3cio Sustent\u00e1vel atrav\u00e9s do Processo de Poliniza\u00e7\u00e3o com Abelhas\u201d, promovido pela\u00a0<a href=\"https:\/\/www.brazilletsbee.com.br\/\"><strong>Associa\u00e7\u00e3o Brasileira de Exportadores de Mel (Abemel)<\/strong><\/a>.<\/p>\n<p>A ministra da Agricultura, Tereza Cristina, participou da transmiss\u00e3o ao vivo, que discutiu a import\u00e2ncia do trabalho das abelhas para aumentar a produ\u00e7\u00e3o de culturas como o caf\u00e9 e a soja. \u201cA poliniza\u00e7\u00e3o ser usada como bioinsumo \u00e9 uma coisa nova, temos um espa\u00e7o enorme para trabalhar mais esse assunto\u201d, disse.<\/p>\n<p>Para a presidente da Abemel, Andressa Berretta, as abelhas podem ser um importante bioinsumo para o agroneg\u00f3cio brasileiro. \u201cAs abelhas podem ser essenciais como pol\u00edticas p\u00fablicas para ajudar a criar a consci\u00eancia de como podemos evitar a gera\u00e7\u00e3o de carbono para o ambiente\u201d.<\/p>\n<p>A diretora-executiva da\u00a0<a href=\"https:\/\/bsca.com.br\/index\/home\"><strong>Associa\u00e7\u00e3o Brasileira de Caf\u00e9s Especiais (BSCA)<\/strong><\/a>, Vanusia Nogueira, ressaltou que, al\u00e9m do aumento da produtividade proporcionado pelo uso de polinizadores na cultura do caf\u00e9, a pr\u00e1tica possibilita a redu\u00e7\u00e3o do uso de outros recursos e pode alavancar o valor agregado do produto. \u201cEsse aumento de produtividade fica totalmente em linha com tudo o que o agro brasileiro tem defendido e buscado mostrar para o mundo: que n\u00f3s temos uma agricultura extremamente sustent\u00e1vel e que podemos aumentar a produtividade, o n\u00edvel de alimentos que entregamos para o mundo sem necessariamente aumentar as \u00e1reas que precisamos para fazer isso\u201d, disse. \u201cOs produtores j\u00e1 est\u00e3o animados em se engajar nesse processo a partir da pr\u00f3xima florada, em setembro\u201d, concluiu.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<h3><strong>Valor econ\u00f4mico<\/strong><\/h3>\n<p>O servi\u00e7o ecossist\u00eamico prestado pelos animais polinizadores \u00e0 agricultura brasileira contribuiu com um valor econ\u00f4mico estimado de R$ 43 bilh\u00f5es em 2018. A estimativa se refere aos valores que seriam gastos pelos agricultores caso os polinizadores n\u00e3o contribu\u00edssem para a produ\u00e7\u00e3o de alimentos. A soja responde por 60% do valor estimado, seguida pelo caf\u00e9 (12%), laranja (5%) e ma\u00e7\u00e3 (4%).<\/p>\n<p>Os dados s\u00e3o do Relat\u00f3rio Tem\u00e1tico sobre Poliniza\u00e7\u00e3o, Polinizadores e Produ\u00e7\u00e3o de Alimento no Brasil, fruto da parceria entre a Plataforma Brasileira de Biodiversidade e Servi\u00e7os Ecossist\u00eamicos e a Rede Brasileira de Intera\u00e7\u00f5es Planta-Polinizador. Segundo o estudo, a interven\u00e7\u00e3o de polinizadores em cultivos de caf\u00e9 favorece um aumento de 30% no rendimento desse cultivo.<\/p>\n<p>As abelhas s\u00e3o o grupo de polinizadores mais abundante na agricultura, pois visitam mais de 90% dos 107 principais cultivos agr\u00edcolas j\u00e1 estudados no mundo.<\/p>\n<h3><strong>Produ\u00e7\u00e3o e exporta\u00e7\u00e3o de mel<\/strong><\/h3>\n<p>A produ\u00e7\u00e3o de mel no Brasil foi de 42,35 mil toneladas em 2018, com valor de produ\u00e7\u00e3o de R$ 502,84 milh\u00f5es. A regi\u00e3o Sul \u00e9 respons\u00e1vel por 38,9% do total produzido, e a regi\u00e3o Nordeste, 33,6%. Os dados s\u00e3o da Pesquisa da Pecu\u00e1ria Municipal, do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE).<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-3-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>Em 2019, o Brasil exportou 30 mil toneladas de mel natural, com valor de US$ 68,3 milh\u00f5es. Em 2020, as exporta\u00e7\u00f5es subiram 35,7%, em compara\u00e7\u00e3o ao primeiro semestre de 2019.<\/p>\n<p>Os Estados Unidos s\u00e3o respons\u00e1veis por 78% das aquisi\u00e7\u00f5es de mel do Brasil, em valor. Em 2019, foram exportados para o pa\u00eds 24,1 mil toneladas de mel, com US$ 54,2 milh\u00f5es. O segundo pa\u00eds importador \u00e9 a Alemanha, com 1,8 mil toneladas e US$ 4,7 milh\u00f5es em valor.<\/p>\n<p>Em 2019, o Kuwait abriu o mercado de mel para o Brasil. Desde 2016, era aguardada a autoriza\u00e7\u00e3o pelo pa\u00eds \u00e1rabe.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 \u00a0<a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lavouras de caf\u00e9 que receberam poliniza\u00e7\u00e3o assistida e inteligente promovida pela startup Agrobee, na safra &hellip;<\/p>\n","protected":false},"author":4,"featured_media":27325,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-27324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=27324"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27324\/revisions"}],"predecessor-version":[{"id":27326,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27324\/revisions\/27326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/27325"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=27324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=27324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=27324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}