{"id":27757,"date":"2020-08-26T10:48:18","date_gmt":"2020-08-26T14:48:18","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=27757"},"modified":"2020-08-26T10:48:18","modified_gmt":"2020-08-26T14:48:18","slug":"e-fundamental-que-a-iniciativa-privada-participe-da-conservacao-da-amazonia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/e-fundamental-que-a-iniciativa-privada-participe-da-conservacao-da-amazonia\/","title":{"rendered":"\u2018\u00c9 fundamental que a iniciativa privada participe da conserva\u00e7\u00e3o da Amaz\u00f4nia\u2019"},"content":{"rendered":"<p>O ministro do Meio Ambiente, Ricardo Salles, disse nesta ter\u00e7a-feira, 25, ser fundamental que a iniciativa privada participe da conserva\u00e7\u00e3o da Amaz\u00f4nia. Em videoconfer\u00eancia promovida pela Sociedade Nacional da Agricultura (SNA) sobre a ocupa\u00e7\u00e3o da regi\u00e3o, Salles destacou que o agroneg\u00f3cio exportador, que se beneficia da Amaz\u00f4nia e quer preservar sua imagem de sustentabilidade frente ao mundo, deveria \u201cpartilhar parte de sua receita com exporta\u00e7\u00f5es\u201d para ajudar a preservar a regi\u00e3o.<\/p>\n<p>Segundo Salles, o propriet\u00e1rio de terras na Amaz\u00f4nia s\u00f3 pode explorar economicamente 20% de sua \u00e1rea, em muitos casos, tornando invi\u00e1vel a sua sobreviv\u00eancia. Para ele ter incentivo de manter intacta a floresta, a iniciativa privada deveria colaborar. E n\u00e3o s\u00f3 o setor agropecu\u00e1rio, conforme o ministro.<\/p>\n<p>\u201cQuem n\u00e3o vive na Amaz\u00f4nia mas dela se beneficia deveria colaborar com essa preserva\u00e7\u00e3o\u201d, enfatizou. De outro modo, ele disse que o sistema at\u00e9 ent\u00e3o vigente de atua\u00e7\u00e3o na regi\u00e3o de verbas estatais e do terceiro setor \u201cclaramente n\u00e3o deu certo e n\u00e3o reduziu a pobreza na regi\u00e3o\u201d.<\/p>\n<p>\u201cMuita gente fez palestra, viajou [em fun\u00e7\u00e3o das a\u00e7\u00f5es na Amaz\u00f4nia], mas a regi\u00e3o continuou pobre.\u201d Assim, para Salles, qualquer plano que se fizer sobre a Amaz\u00f4nia, al\u00e9m de se respeitarem as particularidades de cada regi\u00e3o dentro do bioma, deve levar em conta o reconhecimento do papel da iniciativa privada no desenvolvimento e na conserva\u00e7\u00e3o da Amaz\u00f4nia.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>\u201cVivemos muitos anos com vis\u00e3o de planejamento estatal e destina\u00e7\u00e3o de recursos estatais ou de capta\u00e7\u00e3o internacional (como o Fundo Amaz\u00f4nia) mas, mesmo assim, geridos por governos\u201d, lembrou o ministro. \u201cE houve uma esp\u00e9cie de desconsidera\u00e7\u00e3o, na pr\u00e1tica, do papel do setor privado na Amaz\u00f4nia.\u201d<\/p>\n<p>Segundo ele, para atrair o capital privado \u00e0 regi\u00e3o, deve-se garantir inicialmente a seguran\u00e7a jur\u00eddica quanto \u00e0 quest\u00e3o fundi\u00e1ria da regi\u00e3o, regularizando a posse de terra. \u201cEm segundo lugar, deve-se remunerar a reserva legal por meio do pagamento por servi\u00e7os ambientais, e isso est\u00e1 num programa recentemente lan\u00e7ado pelo governo, o Floresta Mais\u201d, disse, e mencionou novamente a necessidade de quem se beneficia do bioma mas nele n\u00e3o reside, contribuir.<\/p>\n<p>\u201cSe o Brasil como um todo e o resto do mundo se beneficiam da Amaz\u00f4nia, nada mais natural do que pagar por isso; porque est\u00e3o usufruindo\u201d, finalizou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Meio Ambiente, Ricardo Salles, disse nesta ter\u00e7a-feira, 25, ser fundamental que a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":27758,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-27757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Para o ministro Ricardo Salles, \u00e9 preciso ter incentivo de manter intacta a floresta, a iniciativa privada deveria colaborar, e n\u00e3o s\u00f3 o setor agropecu\u00e1rio","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=27757"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27757\/revisions"}],"predecessor-version":[{"id":27759,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27757\/revisions\/27759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/27758"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=27757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=27757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=27757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}