{"id":27834,"date":"2020-08-28T08:59:56","date_gmt":"2020-08-28T12:59:56","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=27834"},"modified":"2020-08-28T08:59:56","modified_gmt":"2020-08-28T12:59:56","slug":"deputado-apresenta-a-mesa-diretora-da-camara-representacao-contra-flordelis","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/deputado-apresenta-a-mesa-diretora-da-camara-representacao-contra-flordelis\/","title":{"rendered":"Deputado apresenta \u00e0 Mesa Diretora da C\u00e2mara representa\u00e7\u00e3o contra Flordelis"},"content":{"rendered":"<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<div>\n<p>O deputado\u00a0<a href=\"https:\/\/www.camara.leg.br\/deputados\/204547\">Leo Motta (PSL-MG)<\/a>\u00a0apresentou representa\u00e7\u00e3o \u00e0 Mesa Diretora da C\u00e2mara contra a deputada\u00a0<a href=\"https:\/\/www.camara.leg.br\/deputados\/204447\">Flordelis (PSD-RJ)<\/a>\u00a0\u201cpor atos incompat\u00edveis com o\u00a0<span id=\"4090\" class=\"termoGlossario\" title=\"Conjunto de princ\u00edpios \u00e9ticos e normas de conduta que devem orientar o comportamento do parlamentar no exerc\u00edcio de seu mandato. \" data-toggle=\"tooltip\" data-placement=\"top\">decoro parlamentar<\/span>\u201c. No documento, ele cita\u00a0 inqu\u00e9rito da Pol\u00edcia Civil do Rio de Janeiro que aponta a deputada como mandante do assassinato do marido, o pastor Anderson do Carmo de Souza.<\/p>\n<p>Anderson foi executado com mais de 30 tiros na porta da casa do casal em Niter\u00f3i (RJ). Leo Motta ressalta que a deputada Flordelis \u00e9 uma das 11 pessoas denunciadas pelo Minist\u00e9rio P\u00fablico do Rio de Janeiro.<\/p>\n<p>Como se trata de iniciativa individual de deputado, a representa\u00e7\u00e3o ter\u00e1 de ser analisada pela Corregedoria e pela Mesa Diretora da C\u00e2mara. Apenas representa\u00e7\u00f5es feitas por partido pol\u00edtico s\u00e3o encaminhadas diretamente ao Conselho de \u00c9tica e Decoro Parlamentar.<\/p>\n<p class=\"content-text__container\" data-track-category=\"Link no Texto\" data-track-links=\"\">A Ag\u00eancia C\u00e2mara n\u00e3o conseguiu contato com a deputada. Depois do crime, ela disse que o marido foi v\u00edtima de um assalto frustrado. Ap\u00f3s a apresenta\u00e7\u00e3o da den\u00fancia, seu advogado, Anderson Rollemberg, afirmou \u00e0 imprensa:\u00a0 \u201cA deputada est\u00e1 muito aborrecida e chateada com tudo que est\u00e1 ocorrendo porque tem com ela a\u00a0 inoc\u00eancia. Jamais foi mandante desse crime b\u00e1rbaro.\u201d<\/p>\n<p><a href=\"https:\/\/www2.camara.leg.br\/comunicacao\/assessoritode-imprensa\/guia-para-jornalistas\/perda-de-mandato\">Saiba mais sobre o rito da perda de mandato<\/a><\/p>\n<p>Da Reda\u00e7\u00e3o \u2013 GM<\/p>\n<\/div>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"https:\/\/www.camara.leg.br\/noticias\/688167-deputado-apresenta-a-mesa-diretora-da-camara-representacao-contra-flordelis\/\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00e2mara dos Deputados Federais<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O deputado\u00a0Leo Motta (PSL-MG)\u00a0apresentou representa\u00e7\u00e3o \u00e0 Mesa Diretora da C\u00e2mara contra a deputada\u00a0Flordelis (PSD-RJ)\u00a0\u201cpor atos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":27835,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-27834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=27834"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27834\/revisions"}],"predecessor-version":[{"id":27836,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/27834\/revisions\/27836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/27835"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=27834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=27834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=27834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}