{"id":28278,"date":"2020-09-15T10:46:42","date_gmt":"2020-09-15T14:46:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=28278"},"modified":"2020-09-15T10:46:42","modified_gmt":"2020-09-15T14:46:42","slug":"peste-suina-africana-entenda-o-caso-na-alemanha-e-os-reflexos-no-brasil","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/peste-suina-africana-entenda-o-caso-na-alemanha-e-os-reflexos-no-brasil\/","title":{"rendered":"Peste su\u00edna africana: entenda o caso na Alemanha e os reflexos no Brasil"},"content":{"rendered":"<p>Um javali selvagem foi encontrado morto no leste da Alemanha, na semana passada, a poucos quil\u00f4metros da fronteira com a Pol\u00f4nia. Autoridades sanit\u00e1rias desconfiaram que o animal poderia ter morrido de peste su\u00edna africana, j\u00e1 que a doen\u00e7a est\u00e1 presente em pa\u00edses do leste europeu desde 2014.\u00a0<a href=\"https:\/\/www.canalrural.com.br\/noticias\/pecuaria\/alemanha-peste-suina-africana-javali\/\"><strong>A confirma\u00e7\u00e3o veio na quinta-feira<\/strong><\/a>, 10, e deixou o mundo em alerta.<\/p>\n<p>A Alemanha \u00e9 o maior produtor de carne su\u00edna da Uni\u00e3o Europeia e responde por 14% das exporta\u00e7\u00f5es para o mercado chin\u00eas, maior consumidor mundial da prote\u00edna. O temor \u00e9 que a peste possa se espalhar e dizimar o plantel local, como aconteceu anos antes na China. S\u00f3 em 2019, o pa\u00eds asi\u00e1tico perdeu 40% dos seus animais por conta da doen\u00e7a.<\/p>\n<p>Os pre\u00e7os do su\u00edno \u2014 e at\u00e9 do milho, insumo importante da cria\u00e7\u00e3o \u2014 j\u00e1 foram influenciados pela not\u00edcia, reagindo com alta. \u201cSem a Alemanha no mercado, provavelmente os pre\u00e7os que j\u00e1 estavam pressionados sustentados pelos pr\u00f3ximos cinco meses, at\u00e9 a situa\u00e7\u00e3o [na Alemanha] se regularizar\u201d, afirmou o analista Yago Travagini, da Agrifatto. \u201cJ\u00e1 vimos, nos Estados Unidos, as cota\u00e7\u00f5es baterem o limite de alta duas vezes seguidas\u201d, contou.<\/p>\n<h3><strong>Embargos<\/strong><\/h3>\n<p>Apesar de n\u00e3o haver indicativo de que a doen\u00e7a tenha atingido unidades produtoras da Alemanha, pa\u00edses compradores e\/ou produtores de su\u00ednos, como China, Brasil, Argentina, Coreia do Sul e Jap\u00e3o,\u00a0<a href=\"https:\/\/www.canalrural.com.br\/noticias\/pecuaria\/suino\/carne-suina-brasil-china-importacoes-alemanha\/\"><strong>anunciaram a suspens\u00e3o das importa\u00e7\u00f5es<\/strong><\/a>, at\u00e9 que se esclare\u00e7a a dimens\u00e3o do problema.<\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-2-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>\u201cPor enquanto, os produtos de risco [carne<em>\u00a0in natura<\/em>\u00a0e semi-processada] n\u00e3o ser\u00e3o mais importados para o Brasil\u201d, disse o secret\u00e1rio de Defesa Agropecu\u00e1ria do\u00a0<a href=\"https:\/\/www.gov.br\/agricultura\/pt-br\/\"><strong>Minist\u00e9rio da Agricultura<\/strong><\/a>, Jos\u00e9 Guilherme Leal, em entrevista exclusiva ao Canal Rural. \u201cEles v\u00e3o ter que explicar como est\u00e1 a biosseguran\u00e7a das unidades industriais, para que a gente possa avaliar a retirada da suspens\u00e3o\u201d, completou.<\/p>\n<p>Leal destaca que trata-se de uma medida preventiva, visando proteger a condi\u00e7\u00e3o sanit\u00e1ria do Brasil, que \u00e9 livre de peste su\u00edna africana, e do continente. \u201cA parte da gen\u00e9tica \u00e9 muito bem controlada, h\u00e1 uma situa\u00e7\u00e3o quarenten\u00e1ria. Os produtos para consumo, quando tem risco, como agora, s\u00e3o suspensos. E h\u00e1 a preocupa\u00e7\u00e3o da vigil\u00e2ncia agropecu\u00e1ria contra o ingresso de res\u00edduos de bordo em aeronaves\u201d, contou.<\/p>\n<p>O\u00a0<a href=\"https:\/\/www.argentina.gob.ar\/senasa\"><strong>Servi\u00e7o Nacional de Sa\u00fade e Qualidade Agroalimentar da Argentina (Senasa)<\/strong><\/a>, inclusive, est\u00e1 analisando interromper as compras de outros pa\u00edses da Europa. \u201cDa mesma forma, analisa-se a suspens\u00e3o de importa\u00e7\u00e3o dos restantes pa\u00edses europeus at\u00e9 que haja comunicado \u00e0 Argentina sobre as medidas de mitiga\u00e7\u00e3o de risco estabelecidas para esta notifica\u00e7\u00e3o e o refor\u00e7o e adapta\u00e7\u00e3o das a\u00e7\u00f5es de vigil\u00e2ncia, de acordo com as recomenda\u00e7\u00f5es internacionais da Organiza\u00e7\u00e3o Mundial de Sa\u00fade Animal (OIE)\u201d, disse, em comunicado.<\/p>\n<h3><strong>Oportunidade para a carne brasileira<\/strong><\/h3>\n<p>A suspens\u00e3o das compras de produtos da Alemanha pelos pa\u00edses asi\u00e1ticos pode acabar favorecendo as carnes brasileiras, que ganharam bastante espa\u00e7o ap\u00f3s a peste su\u00edna africana afetar a produ\u00e7\u00e3o da China. A avalia\u00e7\u00e3o \u00e9 da\u00a0<a href=\"https:\/\/abpa-br.org\/\"><strong>Associa\u00e7\u00e3o Brasileira de Prote\u00edna Animal (ABPA).<\/strong><\/a><\/p>\n<div class=\"ad ad-float ad-300-250\">\n<div id=\"banner-300x250-3-area\">\n<h3><\/h3>\n<\/div>\n<\/div>\n<p>O presidente da entidade, Ricardo Santin, afirmou em entrevista ao Canal Rural, que o Brasil tem capacidade de atender ao aumento da demanda externa sem prejudicar os consumidores internos. \u201cNos primeiros oito meses do ano, as exporta\u00e7\u00f5es aumentaram 44% em volume. Mas n\u00e3o diminu\u00edram a disponibilidade do mercado interno. Ent\u00e3o, o Brasil tem condi\u00e7\u00f5es, sim, se for chamado, de aumentar um pouco mais a sua produ\u00e7\u00e3o, sem prejudicar nosso mercado interno\u201d, analisou.<\/p>\n<p>O suinocultor est\u00e1 pronto para mais esse desafio, segundo o presidente da\u00a0<a href=\"https:\/\/www.accs.org.br\/home\/\"><strong>Associa\u00e7\u00e3o Catarinense dos Criadores de Su\u00ednos (ACCS)<\/strong><\/a>, Losivanio de Lorenzi. \u201cEstamos preparados. O nosso modelo de integra\u00e7\u00e3o, seja nas cooperativas ou nas ind\u00fastrias, faz com que consigamos nos adaptar muito rapidamente para atender as exig\u00eancias desses novos mercados\u201d, disse.<\/p>\n<p>No entanto, de acordo com o analista Fernando Iglesias, da consultoria Safras &amp; Mercado, as exporta\u00e7\u00f5es de su\u00ednos por parte do Brasil n\u00e3o devem aumentar expressivamente. \u201cO que impediria o Brasil de exportar lotes ainda mais expressivos de carne su\u00edna ao mercado chin\u00eas \u00e9 a quest\u00e3o da ractopamina, que \u00e9 uma suplementa\u00e7\u00e3o usada no desenvolvimento dos animais, que n\u00e3o \u00e9 bem vista pelo mercado de maneira geral. Para que o Brasil consiga exportar volumes ainda maiores, seria necess\u00e1rio que novas unidades fossem habilitadas, sendo que as que j\u00e1 est\u00e3o habilitadas hoje j\u00e1 operam perto da capacidade m\u00e1xima, e n\u00e3o t\u00eam condi\u00e7\u00f5es de expandir os volumes exportados no momento\u201d, disse.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um javali selvagem foi encontrado morto no leste da Alemanha, na semana passada, a poucos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":28279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-28278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Com embargos \u00e0 carne su\u00edna alem\u00e3 por parte de grandes compradores, como a China, produtores brasileiros vislumbram poss\u00edveis aumentos nas exporta\u00e7\u00f5es","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=28278"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28278\/revisions"}],"predecessor-version":[{"id":28280,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28278\/revisions\/28280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/28279"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=28278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=28278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=28278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}