{"id":28648,"date":"2020-09-29T07:51:40","date_gmt":"2020-09-29T11:51:40","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=28648"},"modified":"2020-09-29T07:51:40","modified_gmt":"2020-09-29T11:51:40","slug":"comissao-de-orcamento-sera-instalada-hoje","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/comissao-de-orcamento-sera-instalada-hoje\/","title":{"rendered":"Comiss\u00e3o de Or\u00e7amento ser\u00e1 instalada hoje"},"content":{"rendered":"<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<div>\n<p>A\u00a0<span id=\"4053\" class=\"termoGlossario\" title=\"Comiss\u00e3o de deputados e senadores respons\u00e1vel pela an\u00e1lise das propostas or\u00e7ament\u00e1rias elaboradas pelo Executivo: Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO), Lei Or\u00e7ament\u00e1ria Anual (LOA) e Plano Plurianual (PPA).\" data-toggle=\"tooltip\" data-placement=\"top\">Comiss\u00e3o Mista\u00a0de Or\u00e7amento<\/span>\u00a0(CMO), respons\u00e1vel por debater e votar as leis or\u00e7ament\u00e1rias para 2021, ser\u00e1 instalada \u00e0s 9 horas. De acordo com informa\u00e7\u00f5es prestadas pela Presid\u00eancia do Senado, a reuni\u00e3o ser\u00e1 semipresencial. Os membros v\u00e3o eleger o presidente do colegiado, que dever\u00e1 ser um deputado, seguindo a regra de altern\u00e2ncia para ocupa\u00e7\u00e3o do cargo entre C\u00e2mara e Senado.<\/p>\n<p>O colegiado, que dever\u00e1 funcionar de forma remota por causa da pandemia, \u00e9 composto por 40 titulares, sendo 30 deputados e 10 senadores escolhidos pelos l\u00edderes partid\u00e1rios.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/internet\/comissao\/index\/mista\/orca\/Espelho2020.pdf\">Confira os nomes dos integrantes j\u00e1 indicados para a comiss\u00e3o<\/a><\/p>\n<p>Entre as fun\u00e7\u00f5es da comiss\u00e3o est\u00e1 a an\u00e1lise e vota\u00e7\u00e3o do Projeto de Lei Or\u00e7ament\u00e1ria Anual (<span id=\"4123\" class=\"termoGlossario\" title=\"Comumente denominada or\u00e7amento, \u00e9 a lei que cont\u00e9m a discrimina\u00e7\u00e3o da receita e da despesa p\u00fablica para o ano. \u00c9 elaborada pelo Executivo e votada pelo Congresso Nacional.\" data-toggle=\"tooltip\" data-placement=\"top\">LOA<\/span>) de 2021, o\u00a0<a href=\"https:\/\/www.camara.leg.br\/noticias\/688688-proposta-de-orcamento-reforca-teto-dos-gastos-e-preve-salario-minimo-de-r-1-067\/\">PLN 28\/20<\/a>, enviado pelo governo federal no final de agosto. O relator da proposta \u00e9 o senador Marcio Bittar (MDB-RO), que ter\u00e1 a miss\u00e3o de apresentar um relat\u00f3rio com a previs\u00e3o de receitas e despesas da Uni\u00e3o para o ano que vem enfrentando os impactos econ\u00f4micos e sociais da pandemia de Covid-19.<\/p>\n<p><strong>LDO<\/strong><br \/>\nEntre outras mat\u00e9rias or\u00e7ament\u00e1rias, a CMO tamb\u00e9m \u00e9 respons\u00e1vel por analisar o projeto da Lei de Diretrizes Or\u00e7ament\u00e1rias (<span id=\"4066\" class=\"termoGlossario\" title=\"Lei que orienta a elabora\u00e7\u00e3o do or\u00e7amento do ano seguinte. Cont\u00e9m informa\u00e7\u00f5es sobre as metas e prioridades dos tr\u00eas poderes (Executivo, Legislativo e Judici\u00e1rio) e do Minist\u00e9rio P\u00fablico da Uni\u00e3o. Tamb\u00e9m define a meta fiscal para o ano seguinte. \u00c9 elaborada pelo Executivo e aprovada pelo Congresso Nacional.\" data-toggle=\"tooltip\" data-placement=\"top\">LDO<\/span>) para 2021 (<a href=\"https:\/\/www.camara.leg.br\/noticias\/654379-EXECUTIVO-ENCAMINHA-PROPOSTA-DE-LDO-PARA-2021-COM-META-FISCAL-FLEXIVEL\">PLN 9\/20<\/a>), que estabelece os par\u00e2metros do or\u00e7amento para o ano que vem e que foi enviado pelo Poder Executivo em 15 de abril.<\/p>\n<p>Diante dos efeitos da pandemia nas contas p\u00fablicas, a equipe econ\u00f4mica sugeriu na LDO a ado\u00e7\u00e3o de uma meta fiscal flex\u00edvel em 2021, diferentemente dos objetivos fixos adotados em anos anteriores.<\/p>\n<p><strong>A comiss\u00e3o<\/strong><br \/>\nCriada pela Constitui\u00e7\u00e3o de 1988, a Comiss\u00e3o de Or\u00e7amento examina e emite parecer sobre projetos or\u00e7ament\u00e1rios e contas apresentadas anualmente pelo presidente da Rep\u00fablica. Tamb\u00e9m exerce o acompanhamento e a fiscaliza\u00e7\u00e3o do Or\u00e7amento da Uni\u00e3o.<\/p>\n<p>Ela \u00e9 composta por 42 parlamentares titulares, sendo 31 deputados e 11 senadores, e possui igual n\u00famero de suplentes.<\/p>\n<p>O colegiado analisa tamb\u00e9m o Plano Plurianual (<span id=\"4404\" class=\"termoGlossario\" title=\"Instrumento de planejamento de m\u00e9dio prazo que estabelece, de forma regionalizada, as diretrizes, objetivos e metas do governo para um per\u00edodo de quatro anos. O projeto de lei do PPA deve ser encaminhado ao Congresso Nacional, pelo Poder Executivo, at\u00e9 31 de agosto do primeiro ano do mandato presidencial, vigorando at\u00e9 o primeiro ano da administra\u00e7\u00e3o seguinte. Essa periodicidade visa a garantir o m\u00ednimo de continuidade das pol\u00edticas p\u00fablicas entre dois mandatos presidenciais.\" data-toggle=\"tooltip\" data-placement=\"top\">PPA<\/span>) e os projetos de lei do Congresso Nacional que tratam de cr\u00e9ditos or\u00e7ament\u00e1rios extraordin\u00e1rios.<\/p>\n<p>Da Reda\u00e7\u00e3o \u2013 ND<br \/>\nCom informa\u00e7\u00f5es da Ag\u00eancia Senado<\/p>\n<\/div>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"https:\/\/www.camara.leg.br\/noticias\/696183-comissao-de-orcamento-sera-instalada-hoje\/\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00e2mara dos Deputados Federais<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Comiss\u00e3o Mista\u00a0de Or\u00e7amento\u00a0(CMO), respons\u00e1vel por debater e votar as leis or\u00e7ament\u00e1rias para 2021, ser\u00e1 instalada &hellip;<\/p>\n","protected":false},"author":4,"featured_media":28649,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-28648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"A comiss\u00e3o \u00e9 composta por deputados e senadores e analisa as leis or\u00e7ament\u00e1rias do governo","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=28648"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28648\/revisions"}],"predecessor-version":[{"id":28650,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28648\/revisions\/28650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/28649"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=28648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=28648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=28648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}