{"id":28829,"date":"2020-10-05T10:02:17","date_gmt":"2020-10-05T14:02:17","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=28829"},"modified":"2020-10-05T10:02:17","modified_gmt":"2020-10-05T14:02:17","slug":"preco-do-leite-em-sc-registra-em-setembro-2o-maior-patamar-da-historia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/preco-do-leite-em-sc-registra-em-setembro-2o-maior-patamar-da-historia\/","title":{"rendered":"Pre\u00e7o do leite em SC registra em setembro 2\u00ba maior patamar da hist\u00f3ria"},"content":{"rendered":"<p>A m\u00e9dia do pre\u00e7o do leite pago ao produtor de Santa Catarina em setembro ficou em R$ 1,87 por litro, de acordo com o Centro de Socioeconomia e Planejamento Agr\u00edcola (Cepa) da\u00a0<a href=\"https:\/\/www.epagri.sc.gov.br\/\"><strong>Empresa de Pesquisa Agropecu\u00e1ria e Extens\u00e3o Rural do estado (Epagri).<\/strong><\/a>\u00a0Segundo o levantamento, algumas vendas chegaram a R$ 2 por litro.<\/p>\n<p>O Conseleite catarinense havia projetado cota\u00e7\u00f5es em R$ 1,8276 no m\u00eas de setembro, segundo maior patamar desde 2007, quando tem in\u00edcio da s\u00e9rie hist\u00f3rica. O valor \u00e9 superado apenas pelo registrado em julho de 2016, quando ficou em cerca de R$ 2 por litro, levando em considera\u00e7\u00e3o a infla\u00e7\u00e3o do per\u00edodo.<\/p>\n<p>Em agosto de 2020, o produto j\u00e1 tinha alcan\u00e7ado valores bem superiores aos par\u00e2metros hist\u00f3ricos de Santa Catarina. Naquele m\u00eas, o leite teve o pre\u00e7o fixado em R$ 1,7288, um pouco acima do projetado, que era de R$ 1,6943.<\/p>\n<h3><strong>O que motivou a alta?<\/strong><\/h3>\n<p>De acordo com o analista do Cepa Tabajara Marcondes, afirma que a eleva\u00e7\u00e3o hist\u00f3rica se deve \u00e0 rela\u00e7\u00e3o ao aumento de demanda, que n\u00e3o foi acompanhado pela oferta.<\/p>\n<p>No primeiro semestre, a ind\u00fastria de l\u00e1cteos recebeu praticamente o mesmo volume de leite captado em igual per\u00edodo de 2019, acr\u00e9scimo de apenas 0,4%. As importa\u00e7\u00f5es tamb\u00e9m n\u00e3o foram altas. \u201cEmbora tenha havido aumento das importa\u00e7\u00f5es em julho e agosto, somando os volumes de 2020, as importa\u00e7\u00f5es ficam abaixo do ano passado\u201d, diz.<\/p>\n<p>J\u00e1 a demanda cresceu principalmente como reflexo da pandemia causada pela Covid-19. O isolamento social for\u00e7ou fam\u00edlias a se alimentarem mais em casa. O aux\u00edlio emergencial, pago pelo governo federal \u00e0 fam\u00edlias de baixa renda por conta da crise sanit\u00e1ria, tamb\u00e9m ajudou a incluir o alimento no card\u00e1pio de muitas fam\u00edlias que, por falta de recursos financeiros, n\u00e3o o consumiam ou o faziam em pequena quantidade.<\/p>\n<h3><strong>Redu\u00e7\u00e3o<\/strong><\/h3>\n<p>Marcondes acredita \u00e9 pouco prov\u00e1vel que os pre\u00e7os pagos aos produtores de leite catarinenses se mantenham nesse patamar elevado nos pr\u00f3ximos meses. \u201cAlguns derivados l\u00e1cteos j\u00e1 d\u00e3o sinais de queda no mercado atacadista\u201d, conta. Isso porque a oferta do produto nacional e as importa\u00e7\u00f5es come\u00e7am a crescer. A redu\u00e7\u00e3o no valor do aux\u00edlio emergencial e do n\u00famero de beneficiados tamb\u00e9m devem reduzir a demanda.<\/p>\n<p>\u201cO aumento da oferta e a diminui\u00e7\u00e3o na capacidade de compra tendem a reverter o mercado de l\u00e1cteos rapidamente nos meses finais de 2020\u201d, afirma. Nesse cen\u00e1rio, principalmente a partir de novembro, os pre\u00e7os recebidos pelos produtores dever\u00e3o ficam bem abaixo dos verificados neste m\u00eas de setembro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A m\u00e9dia do pre\u00e7o do leite pago ao produtor de Santa Catarina em setembro ficou &hellip;<\/p>\n","protected":false},"author":4,"featured_media":28830,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-28829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=28829"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28829\/revisions"}],"predecessor-version":[{"id":28831,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/28829\/revisions\/28831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/28830"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=28829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=28829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=28829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}