{"id":29191,"date":"2020-10-20T10:25:46","date_gmt":"2020-10-20T14:25:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=29191"},"modified":"2020-10-20T10:25:46","modified_gmt":"2020-10-20T14:25:46","slug":"confinamento-de-bois-em-2020-deve-bater-recorde-de-618-mi-de-cabecas-diz-dsm","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/confinamento-de-bois-em-2020-deve-bater-recorde-de-618-mi-de-cabecas-diz-dsm\/","title":{"rendered":"Confinamento de bois em 2020 deve bater recorde de 6,18 mi de cabe\u00e7as, diz DSM"},"content":{"rendered":"<p>O n\u00famero de bois gordos terminados em confinamento no Brasil deve alcan\u00e7ar o recorde de 6,188 milh\u00f5es de cabe\u00e7as em 2020, avan\u00e7o de 6% em rela\u00e7\u00e3o aos 5,856 milh\u00f5es de cabe\u00e7as verificadas no ano passado, de acordo com dados preliminares do\u00a0<strong>Censo de Confinamento DSM 2020.<\/strong><\/p>\n<p>O crescimento \u00e9 atribu\u00eddo ao\u00a0<strong>segundo giro de confinamento<\/strong>, que j\u00e1 costuma representar 65% dos animais engordados no cocho, mas neste ano ser\u00e1 ainda mais volumoso por causa da\u00a0<strong>forte valoriza\u00e7\u00e3o da arroba<\/strong>\u00a0no per\u00edodo, informa o gerente T\u00e9cnico de Confinamento da DSM, Hugo Cunha.<\/p>\n<p>Por causa da pandemia do novo coronav\u00edrus, que trouxe uma forte incerteza para os mercados e o in\u00edcio da recess\u00e3o econ\u00f4mica,<strong>\u00a0foram confinados 40% menos animais do que o que normalmente ocorre no primeiro giro do ano<\/strong>, que come\u00e7a entre mar\u00e7o e abril e termina entre junho e julho.<\/p>\n<p>\u201cCom essa diminui\u00e7\u00e3o no n\u00famero de bois fechados (nos cochos),\u00a0<strong>faltou animal para ser abatido<\/strong>\u00a0em julho e agosto e o pre\u00e7o da arroba come\u00e7ou a disparar\u201d, disse Cunha.<\/p>\n<p>De acordo com ele, no segundo semestre, embora os pre\u00e7os de insumos essenciais \u00e0 atividade, como\u00a0<strong>bois magros, milho e farelo de soja<\/strong>, tamb\u00e9m tenham come\u00e7ado a subir, as exporta\u00e7\u00f5es continuaram aquecidas. Nesse sentido, a forte demanda externa, somada aos pre\u00e7os mais altos da arroba, estimulou os pecuaristas a lotarem os confinamentos com animais para engorda at\u00e9 o fim do ano.<\/p>\n<p>O levantamento mostra que o maior avan\u00e7o do confinamento, em termos porcentuais, ocorre no\u00a0<strong>Nordeste<\/strong>, onde o n\u00famero de animais deve chegar a 148 mil cabe\u00e7as neste ano, 17% a mais do que em 2019. Contudo, o\u00a0<strong>Centro-Oeste<\/strong>\u00a0segue respons\u00e1vel pela maior parcela de bois nos cochos, somando 2,892 milh\u00f5es de cabe\u00e7as, aumento de 8% frente ao ano anterior. Em segundo lugar, est\u00e1 o\u00a0<strong>Sudeste<\/strong>, com 1,685 milh\u00e3o de animais confinados (+1,6%), seguido pelo\u00a0<strong>Norte<\/strong>, com 760 mil animais (+0,6%) e pelo\u00a0<strong>Sul<\/strong>, que deve alcan\u00e7ar 705 mil animais confinados, alta de 10,8% na mesma base comparativa.<\/p>\n<p>Em rela\u00e7\u00e3o aos estados,\u00a0<strong>Mato Grosso<\/strong>\u00a0lidera a produ\u00e7\u00e3o, enquanto\u00a0<strong>Goi\u00e1s<\/strong>\u00a0e\u00a0<strong>S\u00e3o Paul<\/strong>o ocupam a segunda e a terceira posi\u00e7\u00f5es. Em rela\u00e7\u00e3o \u00e0 oferta no mercado f\u00edsico, Cunha disse que, de fato, em anos anteriores havia mais lotes de boiada gorda terminada nos cochos dispon\u00edveis em outubro. Segundo ele, isso ocorre em virtude de um alongamento no per\u00edodo de confinamento, e n\u00e3o em raz\u00e3o do in\u00edcio tardio da atividade pelos produtores.<\/p>\n<p>\u201cO que vem acontecendo \u00e9 que os\u00a0<strong>confinadores est\u00e3o abatendo animais mais pesados<\/strong>. Se antes abatiam um animal de 19 arrobas, agora est\u00e3o esperando chegar a 21 ou 22 arrobas\u201d, diz o gerente t\u00e9cnico, acrescentando que o ciclo de engorda passa, portanto, de 90 dias para 120 dias nos cochos.<\/p>\n<p>\u201cO pecuarista brasileiro est\u00e1\u00a0<strong>aproveitando mais a carca\u00e7a<\/strong>\u00a0e, por isso, a maior concentra\u00e7\u00e3o de animais confinados no mercado vai ser no m\u00eas de novembro\u201d, projeta ele. Ainda sobre o\u00a0<strong>aumento dos dias de confinamento<\/strong>, Cunha afirmou que essa tend\u00eancia \u00e9 vantajosa mesmo que signifique maior custo com gr\u00e3os para alimenta\u00e7\u00e3o. Isso porque cerca de\u00a0<strong>73% a 75% dos custos de produ\u00e7\u00e3o<\/strong>\u00a0nos confinamentos decorrem do\u00a0<strong>gado de reposi\u00e7\u00e3o<\/strong>, enquanto cerca de 20% a 22% prov\u00eam da alimenta\u00e7\u00e3o dos animais.<\/p>\n<p>\u201c\u00c9 melhor para o produtor segurar os animais porque, apesar de perder efici\u00eancia na engorda, ele\u00a0<strong>melhora a rela\u00e7\u00e3o de troca do boi gordo com a reposi\u00e7\u00e3o<\/strong>\u201c, afirmou. Ele acrescentou que esse movimento n\u00e3o \u00e9 apenas para garantir a remunera\u00e7\u00e3o mais alta trazida pelo peso maior, mas tamb\u00e9m porque est\u00e3o\u00a0<strong>acompanhando a valoriza\u00e7\u00e3o di\u00e1ria cont\u00ednua da arroba no mercado<\/strong>. \u201cPara que ele vai abater hoje, se pode abater amanh\u00e3, quando o animal pesa mais e a arroba est\u00e1 mais valorizada?\u201d<\/p>\n<p>Cunha tamb\u00e9m refor\u00e7ou que o cen\u00e1rio do mercado f\u00edsico \u00e9 de pre\u00e7os sustentados, especialmente por causa da oferta comedida.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 \u00a0<a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O n\u00famero de bois gordos terminados em confinamento no Brasil deve alcan\u00e7ar o recorde de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":29192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-29191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Crescimento \u00e9 atribu\u00eddo ao segundo giro, que neste ano ser\u00e1 ainda mais volumoso por causa da forte valoriza\u00e7\u00e3o da arroba","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/29191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=29191"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/29191\/revisions"}],"predecessor-version":[{"id":29193,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/29191\/revisions\/29193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/29192"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=29191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=29191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=29191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}