{"id":29351,"date":"2020-10-28T09:41:55","date_gmt":"2020-10-28T13:41:55","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=29351"},"modified":"2020-10-28T09:41:55","modified_gmt":"2020-10-28T13:41:55","slug":"leite-precos-caindo-em-outubro-e-alta-dos-custos-acendem-alerta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/leite-precos-caindo-em-outubro-e-alta-dos-custos-acendem-alerta\/","title":{"rendered":"Leite: pre\u00e7os caindo em outubro e alta dos custos acendem alerta"},"content":{"rendered":"<p>Depois de quatro meses em eleva\u00e7\u00e3o, o pre\u00e7o do leite pago ao produtor do Rio Grande do Sul deve cair 5,18% em outubro frente a setembro, de acordo com o\u00a0<a href=\"http:\/\/conseleite.com.br\/\"><strong>Conseleite.<\/strong><\/a>\u00a0A previs\u00e3o \u00e9 de que o valor de refer\u00eancia m\u00e9dio recue de R$ 1,6327 para R$ 1,5482. Apesar da redu\u00e7\u00e3o, os valores seguem em patamares acima dos praticados em anos anteriores, motivados pela alta de custos no campo e na ind\u00fastria.<\/p>\n<div class=\"fl-col-group fl-node-5e7d7411591e9\" data-node=\"5e7d7411591e9\">\n<div class=\"fl-col fl-node-5e7d7411591ea\" data-node=\"5e7d7411591ea\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-rich-text fl-node-5e7d7411591eb\" data-node=\"5e7d7411591eb\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>O temor do setor \u00e9 com o impacto dessa retra\u00e7\u00e3o de pre\u00e7os frente \u00e0 eleva\u00e7\u00e3o de custos de insumos. Al\u00e9m dos gr\u00e3os, h\u00e1 diversos outros itens com cota\u00e7\u00f5es sendo reajustadas rotineiramente, como embalagens, ingredientes e medicamentos.<\/p>\n<p>Tamb\u00e9m h\u00e1 preocupa\u00e7\u00e3o, alertou o presidente do Conseleite, Rodrigo Rizzo, com a falta de itens essenciais para manter a produ\u00e7\u00e3o, j\u00e1 que produtores relatam dificuldade para aquisi\u00e7\u00e3o de produtos b\u00e1sicos como o milho, por exemplo. \u201cAinda estamos sofrendo os efeitos da seca do \u00faltimo ver\u00e3o e isso se agrava com o alerta de La Ni\u00f1a\u201d, diz.<\/p>\n<p>O vice-presidente do Conseleite, Alexandre Guerra, ponderou que a redu\u00e7\u00e3o do aux\u00edlio emergencial de R$ 600 para R$ 300 j\u00e1 traz impacto no mercado, al\u00e9m do aumento das importa\u00e7\u00f5es de l\u00e1cteos.<\/p>\n<p>Segundo Guerra, as aquisi\u00e7\u00f5es de leite importado passaram de um patamar de 10 mil toneladas por m\u00eas, antes da pandemia, para mais de 23 mil toneladas em setembro. \u201cEstivemos em reuni\u00e3o com o Minist\u00e9rio da Agricultura e pedimos para que o tema seja monitorado porque as importa\u00e7\u00f5es est\u00e3o vindo com mais for\u00e7a\u201d, alerta.<\/p>\n<p>Guerra sinalizou que a alta do pre\u00e7o no mercado interno tornou os importados mais competitivos mesmo com a valoriza\u00e7\u00e3o cambial. Com maior escala por propriedade, Argentina e Uruguai, por exemplo, v\u00eam conseguindo reduzir custos.<\/p>\n<p>O professor da Universidade de Passo Fundo (UPF) Marco Antonio Montoya afirma que h\u00e1 uma correla\u00e7\u00e3o direta entre o comportamento dos pre\u00e7os no Rio Grande do Sul e o verificado em outros estados, como Santa Catarina e Paran\u00e1, que tamb\u00e9m sinalizam retra\u00e7\u00e3o para outubro.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e7d741159214\" data-node=\"5e7d741159214\">\n<div class=\"fl-col fl-node-5e7d741159215\" data-node=\"5e7d741159215\">\n<div class=\"fl-col-content fl-node-content\"><\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e7d741159217\" data-node=\"5e7d741159217\">\n<div class=\"fl-col fl-node-5e7d741159218\" data-node=\"5e7d741159218\">\n<div class=\"fl-col-content fl-node-content\"><\/div>\n<\/div>\n<\/div>\n<div class=\"fl-col-group fl-node-5e7d7411591d8\" data-node=\"5e7d7411591d8\">\n<div class=\"fl-col fl-node-5e7d7411591da\" data-node=\"5e7d7411591da\">\n<div class=\"fl-html\">Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depois de quatro meses em eleva\u00e7\u00e3o, o pre\u00e7o do leite pago ao produtor do Rio &hellip;<\/p>\n","protected":false},"author":4,"featured_media":29352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-29351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Os valores pagos ao produtor ga\u00facho devem recuar ap\u00f3s quatro meses consecutivos subindo. Mesmo assim, seguem acima dos patamares de anos anteriores","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/29351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=29351"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/29351\/revisions"}],"predecessor-version":[{"id":29353,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/29351\/revisions\/29353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/29352"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=29351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=29351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=29351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}