{"id":30084,"date":"2020-12-03T10:38:20","date_gmt":"2020-12-03T14:38:20","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30084"},"modified":"2020-12-03T10:38:20","modified_gmt":"2020-12-03T14:38:20","slug":"morre-touro-imperador-baxter-referencia-produtiva-da-pecuaria-brasileira","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/morre-touro-imperador-baxter-referencia-produtiva-da-pecuaria-brasileira\/","title":{"rendered":"Morre touro Imperador Baxter, refer\u00eancia produtiva da pecu\u00e1ria brasileira"},"content":{"rendered":"<p>Nesta ter\u00e7a-feira, 1\u00ba de dezembro, foi confirmada a morte do touro Imperador Baxter FIV Volta Fria na Fazenda S\u00e3o Domingos, em Goi\u00e1s. Com mais de 120 mil doses de s\u00eamen comercializadas durante sua vida produtiva, o animal foi condecorado L\u00edder de Sum\u00e1rio de Prog\u00eanie e duas vezes Grande Campe\u00e3o Nacional.<\/p>\n<p>A contribui\u00e7\u00e3o do Imperador Baxter foi espetacular. Um touro que mudou o rumo da ra\u00e7a\u00a0<a href=\"https:\/\/www.canalrural.com.br\/noticias\/pecuaria\/leite\/girolando\/\"><strong>Girolando<\/strong><\/a>, na qual pudemos aliar a conforma\u00e7\u00e3o perfeita com a produ\u00e7\u00e3o excepcional. Consagra\u00e7\u00e3o, seguran\u00e7a e muito leite fazem parte da gen\u00e9tica desse reprodutor, que foi l\u00edder de PISTA, de sum\u00e1rio e vendas. Obrigado, Imperador Baxter\u201d, comenta Guilherme Marquez, Gerente de Produto Leite Nacional da Alta Genetics.<\/p>\n<h3>Hist\u00f3ria<\/h3>\n<p>Resultado de uma gen\u00e9tica de muita confiabilidade, o reprodutor \u00e9 filho de Alta Baxter com a Filipeta Cenoura Bazuah Volta Fria. Um dos grandes pontos do touro tamb\u00e9m \u00e9 seu destaque para fertilidade, nas quais as fazendas que o utilizaram conheceram altos \u00edndices de concep\u00e7\u00e3o.<\/p>\n<p>Suas filhas t\u00eam produ\u00e7\u00f5es m\u00e9dias acima de 25 quilos por dia e a\u00a0<a href=\"https:\/\/altagenetics.com.br\/\">Alta Genetics<\/a>, empresa de melhoramento gen\u00e9tico bovino, continua com estoque estrat\u00e9gico de s\u00eamen convencional e sexado do touro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira, 1\u00ba de dezembro, foi confirmada a morte do touro Imperador Baxter FIV Volta &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30085,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-30084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Com mais de 120 mil doses de s\u00eamen comercializadas durante sua vida, as filhas do animal t\u00eam produ\u00e7\u00f5es m\u00e9dias acima de 25 quilos por dia","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30084"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30084\/revisions"}],"predecessor-version":[{"id":30086,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30084\/revisions\/30086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30085"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}