{"id":30117,"date":"2020-12-04T08:42:13","date_gmt":"2020-12-04T12:42:13","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30117"},"modified":"2020-12-04T08:42:13","modified_gmt":"2020-12-04T12:42:13","slug":"boi-soja-milho-e-cafe-em-queda-veja-noticias-importantes-desta-sexta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/boi-soja-milho-e-cafe-em-queda-veja-noticias-importantes-desta-sexta\/","title":{"rendered":"Boi, soja, milho e caf\u00e9 em queda: veja not\u00edcias importantes desta sexta"},"content":{"rendered":"<ul>\n<li><strong>Arroba do boi gordo<\/strong>\u00a0recua para R$ 270 em S\u00e3o Paulo, diz Scot Consultoria<\/li>\n<li>Indicador do Cepea para o\u00a0<strong>milho<\/strong>\u00a0cai pelo sexto dia consecutivo<\/li>\n<li>Valoriza\u00e7\u00e3o do real pressiona os pre\u00e7os da\u00a0<strong>soja<\/strong><\/li>\n<li>Cota\u00e7\u00f5es do\u00a0<strong>caf\u00e9<\/strong>\u00a0seguem dire\u00e7\u00e3o do c\u00e2mbio<\/li>\n<li>No Exterior:\u00a0<strong>Covid-19 acelera nos EUA<\/strong>\u00a0e aumenta press\u00e3o por est\u00edmulos e vacinas<\/li>\n<li>No Brasil:\u00a0<strong>PIB<\/strong>\u00a0cresce 7,7% no terceiro trimestre<\/li>\n<\/ul>\n<h3><strong>Agenda:<\/strong><\/h3>\n<ul>\n<li>Brasil: venda, produ\u00e7\u00e3o e exporta\u00e7\u00f5es de m\u00e1quinas agr\u00edcolas (Anfavea)<\/li>\n<li>EUA: balan\u00e7a comercial de outubro<\/li>\n<li>EUA: cria\u00e7\u00e3o de vagas de trabalho de novembro<\/li>\n<\/ul>\n<h2><strong>Arroba do boi gordo recua para R$ 270 em S\u00e3o Paulo, diz Scot Consultoria<\/strong><\/h2>\n<p>No levantamento di\u00e1rio de pre\u00e7os da Scot Consultoria, a arroba do boi gordo em S\u00e3o Paulo recuou R$ 3 e foi para R$ 270. De acordo com a an\u00e1lise da empresa, as ind\u00fastrias fizeram boas compras ao longo da semana, que permitiram escalas de abate mais confort\u00e1veis.<\/p>\n<p>No mercado futuro, o dia tamb\u00e9m foi marcado por novas baixas nas cota\u00e7\u00f5es. O contrato para dezembro passou de R$ 264,05 para R$ 261,05 por arroba e do janeiro foi de R$ 257,05 para R$ 254,60.<\/p>\n<h2><strong>Indicador do Cepea para o milho cai pelo sexto dia consecutivo<\/strong><\/h2>\n<p>O indicador do milho do\u00a0<a href=\"https:\/\/www.cepea.esalq.usp.br\/br\"><strong>Cepea<\/strong><\/a>, calculado com base nos pre\u00e7os de Campinas (SP), recuou pelo sexto dia consecutivo. Neste per\u00edodo, a queda acumulada j\u00e1 alcan\u00e7ou 5,4%. A cota\u00e7\u00e3o passou de R$ 76,44 para R$ 75,47 por saca. A Agrifatto Consultoria observa uma melhora da oferta por parte dos produtores e, ao mesmo tempo, os compradores n\u00e3o demonstram muito interesse. Essa press\u00e3o da oferta tem levado \u00e0 queda dos pre\u00e7os.<\/p>\n<p>No mercado futuro, os contratos de milho na B3 tiveram mais um dia de baixas, e se aproximaram dos R$ 72 por saca. O vencimento de janeiro passou de R$ 74,63 para R$ 72,87 e do mar\u00e7o foi de R$ 74,43 para R$ 73,54.<\/p>\n<h2><strong>Valoriza\u00e7\u00e3o do real pressiona os pre\u00e7os da soja<\/strong><\/h2>\n<p>A queda do d\u00f3lar para o menor patamar desde julho pressionou ainda mais os pre\u00e7os da soja no mercado brasileiro. Com isso, o mercado ficou travado e, de acordo com a Safras &amp; Mercado, a negocia\u00e7\u00e3o ficou inviabilizada, apenas com cota\u00e7\u00f5es referenciais.<\/p>\n<p>Em Passo Fundo (RS), a saca caiu de R$ 149 para R$ 148. Em Cascavel (PR), foi de R$ 149 para R$ 14. Em Rondon\u00f3polis (MT), recuou de R$ 159 para R$ 153.<\/p>\n<p>No Exterior, a desvaloriza\u00e7\u00e3o da moeda norte-americana em rela\u00e7\u00e3o a seus pares teve efeito contr\u00e1rio do que aconteceu no Brasil e estimulou eleva\u00e7\u00e3o das cota\u00e7\u00f5es dos futuros da oleaginosa na Bolsa de Chicago.<\/p>\n<h2><strong>Cota\u00e7\u00f5es do caf\u00e9 seguem dire\u00e7\u00e3o do c\u00e2mbio<\/strong><\/h2>\n<p>Assim como no caso da soja, a valoriza\u00e7\u00e3o do real tamb\u00e9m pressionou os pre\u00e7os do caf\u00e9, de acordo com a Safras &amp; Mercado. A consultoria aponta que os caf\u00e9s com qualidade mais fraca recuaram, enquanto os demais permaneceram est\u00e1veis. Al\u00e9m disso, o mercado, apesar de ter um dia calmo na comercializa\u00e7\u00e3o, apresentou negocia\u00e7\u00f5es pontuais em volume mediano.<\/p>\n<p>O indicador do caf\u00e9 ar\u00e1bica do Cepea passou de R$ 593,06 para R$ 583,93 por saca, chegando ao menor valor em sete dias.<\/p>\n<p>Na Bolsa de Nova York, as cota\u00e7\u00f5es dos futuros do caf\u00e9 ar\u00e1bica avan\u00e7aram refletindo a valoriza\u00e7\u00e3o do petr\u00f3leo e a queda do d\u00f3lar no exterior.<\/p>\n<h2><strong>No Exterior: Covid-19 acelera nos EUA e aumenta press\u00e3o por est\u00edmulos e vacinas<\/strong><\/h2>\n<p>Os Estados Unidos registraram nesta quinta-feira, 3, o maior n\u00famero de \u00f3bitos por Covid-19 em um \u00fanico dia, de acordo com compila\u00e7\u00e3o feita pelo site Worldometers. Com isso, aumentou a press\u00e3o por uma nova rodada de est\u00edmulos econ\u00f4micos no pa\u00eds. O mercado tamb\u00e9m monitora atentamente not\u00edcias sobre a produ\u00e7\u00e3o e distribui\u00e7\u00e3o das vacinas.<\/p>\n<p>Na quinta, perto do final do preg\u00e3o, a farmac\u00eautica Pfizer afirmou que diminuiu as estimativas de distribui\u00e7\u00e3o de sua vacina devido a problemas encontrados na cadeia de fornecimento. O Reino Unido pretende iniciar a distribui\u00e7\u00e3o desta vacina na semana que vem, com expectativa de imunizar um ter\u00e7o da popula\u00e7\u00e3o do pa\u00eds.<\/p>\n<h2><strong>No Brasil: PIB cresce 7,7% no terceiro trimestre<\/strong><\/h2>\n<p>De acordo com o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), o PIB cresceu 7,7% no terceiro trimestre. O resultado ficou um pouco abaixo das expectativas de mercado, que projetava crescimento entre 8,6% e 9%, em virtude das revis\u00f5es mais positivas de per\u00edodos anteriores. Por\u00e9m, com esse resultado, o pa\u00eds sai da recess\u00e3o t\u00e9cnica, que ocorre ao ter dois trimestres consecutivos de retra\u00e7\u00e3o do PIB.<\/p>\n<p>A expans\u00e3o foi recorde na compara\u00e7\u00e3o trimestral, mas ainda n\u00e3o foi suficiente para recuperar as perdas causadas pela pandemia. Os maiores destaques de crescimento nesta base de compara\u00e7\u00e3o foram a ind\u00fastria, sobretudo a de transforma\u00e7\u00e3o, e os servi\u00e7os.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arroba do boi gordo\u00a0recua para R$ 270 em S\u00e3o Paulo, diz Scot Consultoria Indicador do &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-30117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"As commodities agr\u00edcolas tiveram mais um dia de desvaloriza\u00e7\u00e3o, pressionadas pela alta do real em rela\u00e7\u00e3o ao d\u00f3lar","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30117"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30117\/revisions"}],"predecessor-version":[{"id":30119,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30117\/revisions\/30119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30118"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}