{"id":30146,"date":"2020-12-05T10:25:37","date_gmt":"2020-12-05T14:25:37","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30146"},"modified":"2020-12-05T10:25:37","modified_gmt":"2020-12-05T14:25:37","slug":"milho-crescimento-da-oferta-derruba-cotacoes-no-brasil","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/milho-crescimento-da-oferta-derruba-cotacoes-no-brasil\/","title":{"rendered":"Milho: crescimento da oferta derruba cota\u00e7\u00f5es no Brasil"},"content":{"rendered":"<p>O mercado brasileiro de milho teve mais um dia de cota\u00e7\u00f5es pressionadas para baixo nesta sexta-feira. Segundo o consultor de Safras &amp; Mercado, Paulo Molinari, o mercado apresentou novamente mais ofertas e poucos compradores, levando a quedas regionais nos pre\u00e7os.<\/p>\n<p>No Porto de Santos, o pre\u00e7o ficou em R$ 70\/74 a saca. No Porto de Paranagu\u00e1 (PR), o valor chegou a R$ 70\/75 a saca.<\/p>\n<p>No Paran\u00e1, a cota\u00e7\u00e3o ficou em R$ 72\/75 a saca em Cascavel. Em S\u00e3o Paulo, a saca de milho foi negociada a R$ 68\/70 na Mogiana. Em Campinas CIF, o pre\u00e7o foi de R$ 70\/72 a saca.<\/p>\n<p>No Rio Grande do Sul, pre\u00e7o ficou em R$ 83\/85 a saca em Erechim. Em Minas Gerais, a cota\u00e7\u00e3o foi de R$ 67\/71 a saca em Uberl\u00e2ndia. Em Goi\u00e1s, o pre\u00e7o esteve em R$ 69 \u2013 R$ 71 a saca em Rio Verde \u2013 CIF. No Mato Grosso, a cota\u00e7\u00e3o ficou a R$ 63\/67 a saca em Rondon\u00f3polis.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 <a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mercado brasileiro de milho teve mais um dia de cota\u00e7\u00f5es pressionadas para baixo nesta &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30147,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-30146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"O mercado apresentou novamente mais ofertas e poucos compradores, levando a quedas regionais nos pre\u00e7os","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30146"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30146\/revisions"}],"predecessor-version":[{"id":30148,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30146\/revisions\/30148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30147"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}