{"id":30317,"date":"2020-12-13T10:44:01","date_gmt":"2020-12-13T14:44:01","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30317"},"modified":"2020-12-13T10:44:01","modified_gmt":"2020-12-13T14:44:01","slug":"barroso-pressao-fez-ministros-mudarem-voto-sobre-a-prisao-em-segunda-instancia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/barroso-pressao-fez-ministros-mudarem-voto-sobre-a-prisao-em-segunda-instancia\/","title":{"rendered":"Barroso: press\u00e3o fez ministros mudarem voto sobre a pris\u00e3o em segunda inst\u00e2ncia"},"content":{"rendered":"<div class=\"Noticia_Foto\">\n<figure class=\"foto-legenda\"><figcaption class=\"foto-legenda-citacao\">\n<div class=\"foto-legenda-citacao-text\">Segundo o ministro, a pandemia trouxe uma dimens\u00e3o pol\u00edtica que \u201cse manifesta em uma enorme falta de lideran\u00e7a e coordena\u00e7\u00e3o no seu enfrentamento no Brasil\u201d<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p class=\"\">No livro rec\u00e9m-lan\u00e7ado \u201cSem data venia: um olhar sobre o Brasil e o mundo\u201d, o ministro\u00a0<strong>Lu\u00eds Roberto Barroso<\/strong>\u00a0diz que dois colegas de Supremo Tribunal Federal (STF) que antes haviam votado pela pris\u00e3o de condenados em segunda inst\u00e2ncia cederam \u00e0 press\u00e3o \u201cdos que pretendem que tudo permane\u00e7a como sempre foi\u201d.<\/p>\n<p class=\"\">Embora n\u00e3o tenha mencionado os nomes, o\u00a0<strong>placar no STF foi alterado<\/strong>\u00a0no fim do ano passado, barrando a deten\u00e7\u00e3o ap\u00f3s senten\u00e7a de segundo grau, porque Gilmar Mendes e Dias Toffoli mudaram o entendimento que j\u00e1 tinham manifestado em julgamento anterior sobre o assunto.<\/p>\n<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<p class=\"\">Se antes tinham votado pelas penas antecipadas, em 2019 mudaram de ideia e votaram pela possibilidade de condenados aguardarem em liberdade at\u00e9 o tr\u00e2nsito em julgado \u2014 ou seja, at\u00e9 que o \u00faltimo recurso seja analisado nos tribunais. Em 2016, ambos haviam votado pela pris\u00e3o depois de condena\u00e7\u00e3o por tribunal de segunda inst\u00e2ncia.<\/p>\n<p>\u201cA mais importante altera\u00e7\u00e3o (trazida pelo STF), sem d\u00favida, foi a possibilidade de execu\u00e7\u00e3o de decis\u00f5es penais condenat\u00f3rias ap\u00f3s o julgamento em segundo grau, fechando a porta pela qual processos criminais se eternizavam at\u00e9 a prescri\u00e7\u00e3o, dando salvo-conduto aos ladr\u00f5es de casaca. Essa mudan\u00e7a, todavia, n\u00e3o duraria muito, justamente por haver se revelado extremamente eficaz\u201d, escreveu Barroso.<\/p>\n<p>Segundo o ministro, \u201ca corrup\u00e7\u00e3o contra-atacou com todas as suas for\u00e7as e aliados, at\u00e9 conseguir desfazer a medida. Ressalve-se, com o respeito devido e merecido, o ponto de vista leg\u00edtimo de quem entende que a Constitui\u00e7\u00e3o imp\u00f5e que se aguarde at\u00e9 o \u00faltimo recurso\u201d.<\/p>\n<p>Ainda no livro, Barroso afirmou que, em seguida, veio \u201ca revanche dos que pretendem que tudo permane\u00e7a como sempre foi\u201d. Ele conta que \u201ca articula\u00e7\u00e3o para derrubar a possibilidade de execu\u00e7\u00e3o das condena\u00e7\u00f5es criminais ap\u00f3s a segunda inst\u00e2ncia foi o momento mais contundente da rea\u00e7\u00e3o, logrando obter a mudan\u00e7a de posi\u00e7\u00e3o de dois ministros do Supremo Tribunal Federal que, antes, haviam sido enfaticamente favor\u00e1veis \u00e0 medida\u201d.<\/p>\n<p>A obra fala de temas que passaram pelo Supremo, como as decis\u00f5es recentes no sentido de que o governo federal, os estaduais e as prefeituras t\u00eam atribui\u00e7\u00f5es no enfrentamento da Covid-19.<\/p>\n<p>Segundo o ministro, a pandemia trouxe uma dimens\u00e3o pol\u00edtica que \u201cse manifesta em uma enorme\u00a0<strong>falta de lideran\u00e7a<\/strong>\u00a0e coordena\u00e7\u00e3o no seu enfrentamento no Brasil\u201d. Ele afirma que \u201cUni\u00e3o, estados e munic\u00edpios n\u00e3o foram capazes de construir uma estrat\u00e9gia harm\u00f4nica, inclusive e sobretudo porque, no plano federal, ignoravam-se as recomenda\u00e7\u00f5es da ci\u00eancia e da medicina\u201d.<\/p>\n<h3>\u2018Desacerto pol\u00edtico\u2019<\/h3>\n<p>Ainda segundo Barroso, o\u00a0<strong>governo federal \u00e9 respons\u00e1vel<\/strong>\u00a0pela crise atual. \u201cO desacerto pol\u00edtico, ali\u00e1s, trouxe queda vertiginosa do real \u2014 moeda que mais se desvalorizou no mundo \u2014 num enorme e constrangedor desprest\u00edgio internacional. O pa\u00eds teve tr\u00eas ministros da Sa\u00fade em curto per\u00edodo e ainda assistiu \u00e0 queda rumorosa do ministro da Justi\u00e7a, em meio a outros sobressaltos. Tudo sem mencionar uma furiosa \u2014 quando n\u00e3o criminosa \u2014 campanha de desinforma\u00e7\u00e3o por mil\u00edcias digitais que infestam as redes sociais, produzida por vozes obscurantistas, truculentas e autorit\u00e1rias\u201d, anotou.<\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"http:\/\/ultimosegundo.ig.com.br\/politica\/2020-12-13\/barroso-pressao-fez-ministros-mudarem-voto-sobre-a-prisao-em-segunda-instancia.html\" target=\"_blank\" rel=\"noopener noreferrer\">IG Pol\u00edtica<\/a><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o ministro, a pandemia trouxe uma dimens\u00e3o pol\u00edtica que \u201cse manifesta em uma enorme &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-30317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30317"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30317\/revisions"}],"predecessor-version":[{"id":30319,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30317\/revisions\/30319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30318"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}