{"id":30460,"date":"2020-12-17T10:03:00","date_gmt":"2020-12-17T14:03:00","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30460"},"modified":"2020-12-17T10:03:00","modified_gmt":"2020-12-17T14:03:00","slug":"nova-ferroeste-com-potencial-de-carga-em-40-mi-de-toneladas-projeto-avanca-em-ms","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/nova-ferroeste-com-potencial-de-carga-em-40-mi-de-toneladas-projeto-avanca-em-ms\/","title":{"rendered":"Nova Ferroeste: com potencial de carga em 40 mi de toneladas, projeto avan\u00e7a em MS"},"content":{"rendered":"<p>O projeto da Nova Ferroeste que prev\u00ea ligar Mato Grosso do Sul ao porto de Paranagu\u00e1 tem capacidade potencial de carga estimado em 40 milh\u00f5es de toneladas para exporta\u00e7\u00e3o, sendo 18 milh\u00f5es no Estado. O n\u00famero \u00e9 resultado do estudo de Viabilidade Econ\u00f4mica e Ambiental (Evetea), apresentado nesta quarta-feira, 16, ao Governo do Mato Grosso do Sul, Paran\u00e1 e Minist\u00e9rio da Agricultura e Pecu\u00e1ria.<\/p>\n<p>A pr\u00f3xima etapa do projeto ser\u00e1 a contrata\u00e7\u00e3o do Estudo de Impacto Ambiental e Relat\u00f3rio de Impacto Ambiental (EIA\/RIMA), que \u00e9 a pesquisa que viabiliza ou n\u00e3o a implanta\u00e7\u00e3o de um empreendimento pr\u00f3ximo de \u00e1reas preservadas. Em janeiro come\u00e7am as reuni\u00f5es t\u00e9cnicas para definir o tra\u00e7ado da rota entre Cascavel at\u00e9 Foz do Igua\u00e7u e at\u00e9 Maracaju.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.semagro.ms.gov.br\/wp-content\/uploads\/2020\/12\/ferroeste_dezembro-1024x566-1.png\" alt=\"\" width=\"675\" height=\"373\" \/><\/p>\n<p>Com o avan\u00e7o do projeto, a previs\u00e3o \u00e9 que ele v\u00e1 para leil\u00e3o na B3 em novembro de 2021. A empresa que arrematar ter\u00e1 o estudo de viabilidade e licenciamento ambiental prontos, com obriga\u00e7\u00e3o de construir os dois ramais.<\/p>\n<p>A proposta inicial previa a constru\u00e7\u00e3o de um terminal em Maracaju, mas segundo o secret\u00e1rio Jaime Verruck, titular da Semagro (Secretaria de Meio Ambiente, Desenvolvimento Econ\u00f4mico, Produ\u00e7\u00e3o e Agricultura Familiar), Mato Grosso do Sul far\u00e1 um estudo t\u00e9cnico para definir um ramal intermedi\u00e1rio.<\/p>\n<p>\u201cExiste um posicionamento de Governo do Estado que entre o trecho de Gua\u00edra e Maracaju existe a necessidade de ter um outro terminal. Porque tem volume de carga, e tem todas aquelas industrias de etanol. A partir de janeiro n\u00f3s vamos fazer o estudo sobre onde seria localizado sob o ponto de vista t\u00e9cnico, outro terminal\u201d, explica.<\/p>\n<p>O governador Reinaldo Azambuja classificou a ferrovia como um projeto estruturante que aumenta a competitividade para os dois estados. \u201cMaracaju \u00e9 o ponto de conex\u00e3o da Malha Oeste com a futura Ferroeste. N\u00f3s temos a\u00ed o potencial de min\u00e9rio, produ\u00e7\u00e3o de etanol e principalmente, atrav\u00e9s da refinaria do Paran\u00e1, a importa\u00e7\u00e3o do diesel e gasolina. Ent\u00e3o \u00e9 uma nova ferrovia com uma conex\u00e3o extremamente competitiva aos nossos estados\u201d.<\/p>\n<p>A ministra de Agricultura, Pecu\u00e1ria e Abastecimento, Tereza Cristina destacou o entusiasmo com o projeto e se colocou \u00e0 disposi\u00e7\u00e3o. \u201cA ferrovia surge com esse potencial inicial, mas depois outras cargas v\u00e3o chegando e se incorporando. Se a ferrovia tem boa gest\u00e3o, com certeza vai agregar outras cargas. Esse \u00e9 um projeto que o governador Azambuja e o governador Ratinho tem que deixar para a hist\u00f3ria das suas gest\u00f5es. Estou absolutamente a disposi\u00e7\u00e3o para ajuda-los\u201d.<\/p>\n<p>Ratinho Junior, governador do Paran\u00e1, falou sobre os estudos do novo ramal ferrovi\u00e1rio, que ligar\u00e1 Maracaju (MS) ao Porto de Paranagu\u00e1. \u201cA import\u00e2ncia desse encontro entre Paran\u00e1 e Mato Grosso do Sul, juntamente com os minist\u00e9rios, est\u00e1 no alinhamento, na demonstra\u00e7\u00e3o da vontade pol\u00edtica com rela\u00e7\u00e3o ao projeto ferrovi\u00e1rio para os dois estados e para o Brasil\u201d, afirmou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 \u00a0<a href=\"https:\/\/www.canalrural.com.br\/\">Canal Rural<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto da Nova Ferroeste que prev\u00ea ligar Mato Grosso do Sul ao porto de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30461,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-30460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"O projeto prev\u00ea ligar Mato Grosso do Sul ao porto de Paranagu\u00e1. O governador Reinaldo Azambuja prev\u00ea crescimento na competitividade entre os estados","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30460"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30460\/revisions"}],"predecessor-version":[{"id":30462,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30460\/revisions\/30462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30461"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}