{"id":30819,"date":"2021-01-05T18:32:47","date_gmt":"2021-01-05T22:32:47","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30819"},"modified":"2021-01-05T18:32:47","modified_gmt":"2021-01-05T22:32:47","slug":"botelho-avalia-expectativas-para-2021-e-encerra-ano-com-50-leis-de-sua-autoria","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/botelho-avalia-expectativas-para-2021-e-encerra-ano-com-50-leis-de-sua-autoria\/","title":{"rendered":"Botelho avalia expectativas para 2021 e encerra ano com 50 leis de sua autoria"},"content":{"rendered":"<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<div class=\"template-border-midia\">\n<p>Autor de 50 leis ordin\u00e1rias para melhorar as condi\u00e7\u00f5es de vida da popula\u00e7\u00e3o mato-grossense, o presidente da Assembleia Legislativa (ALMT), deputado Eduardo Botelho (DEM), se diz otimista com o ano novo, depois de 2020 que, segundo ele, foi um ano extremamente desafiador, em que a atua\u00e7\u00e3o da ALMT fez toda a diferen\u00e7a, aprovando medidas urgentes e necess\u00e1rias para o combate \u00e0 pandemia da Covid-19, bem como \u00e0 retomada do desenvolvimento do estado com investimentos importantes em todas as cidades. Em 2020 foram sancionadas 13 leis de Botelho voltadas ao enfrentamento da pandemia.<\/p>\n<p>\u201cAs expectativas s\u00e3o as melhores, pois a partir do ano que vem o governo adquire a capacidade de investimentos, fruto do trabalho da Assembleia Legislativa que melhorou e aprovou os projetos necess\u00e1rios para fortalecer a capacidade financeira do estado. Dessa forma, demos condi\u00e7\u00f5es de o governo retomar o caminho do desenvolvimento, a exemplo do Programa Mais MT, com investimentos em diversos setores na ordem de R$ 9,5 bilh\u00f5es. Queremos um ano melhor, com mais gera\u00e7\u00e3o de emprego, com menos problemas na sa\u00fade e perdas para todos, com o controle da pandemia\u201d, afirmou o presidente.<\/p>\n<p>Botelho, que tamb\u00e9m sofreu com a forma grave da Covid-19, destacou o trabalho parlamentar, que ajudou a salvar vidas e amenizar o sofrimento de in\u00fameras v\u00edtimas. Ele \u00e9 autor de medidas que v\u00e3o desde o descarte correto de m\u00e1scaras e outros equipamentos de prote\u00e7\u00e3o individual; atendimento m\u00e9dico atrav\u00e9s da telemedicina; institui\u00e7\u00e3o do Selo de Estabelecimento Seguro, al\u00e9m da inclus\u00e3o de produtos da agricultura familiar na cesta b\u00e1sica.<\/p>\n<p>A\u00e7\u00f5es que refor\u00e7am que, embora conturbado, o ano legislativo foi encerrado com significativa produ\u00e7\u00e3o legislativa, marcado pela realiza\u00e7\u00e3o de sess\u00f5es remotas, como medida de prote\u00e7\u00e3o e combate ao coronav\u00edrus. E esse trabalho desde o in\u00edcio da atual legislatura fortaleceu e reoxigenou Mato Grosso, especialmente, com a aprova\u00e7\u00e3o do pacote de ajustes fiscais e administrativo, a\u00e7\u00f5es que reascende as esperan\u00e7as de um ano novo significativamente melhor, conforme prev\u00ea Botelho, ao citar avan\u00e7os como o pagamento a servidores e fornecedores em dia; al\u00e9m do lan\u00e7amento de diversas frentes de trabalho em todo o estado.<\/p>\n<p><strong>PEQUENOS PRODUTORES<\/strong>\u00a0\u2013 Somente para a Agricultura Familiar ser\u00e3o investidos R$ 185 milh\u00f5es, para aquisi\u00e7\u00e3o de equipamentos e m\u00e1quinas; assist\u00eancia t\u00e9cnica \u00e0s cadeias produtivas e implanta\u00e7\u00e3o de assist\u00eancia t\u00e9cnica on-line. E mais R$ 80 milh\u00f5es para o Regulariza Mais, que engloba a regulariza\u00e7\u00e3o fundi\u00e1ria urbana e rural, al\u00e9m do Programa Terra a Limpo.<\/p>\n<p>O Mais MT foi dividido em 12 eixos: Seguran\u00e7a P\u00fablica; Sa\u00fade; Educa\u00e7\u00e3o; Social e Habita\u00e7\u00e3o, Desenvolvimento, Emprego e Renda, Infraestrutura, Turismo, Cultura, Esporte e Lazer; Simplifica MT; Efici\u00eancia P\u00fablica; Meio Ambiente e Agricultura Familiar e Regulariza\u00e7\u00e3o Fundi\u00e1ria.<\/p>\n<p>\u201cTivemos um ano bem diferente, mas conseguimos driblar as dificuldades, aos poucos vamos superando a Covid-19 e retomando o crescimento do estado. A Assembleia Legislativa foi decisiva nas a\u00e7\u00f5es que ajudaram a superar o ano dif\u00edcil que tivemos. Agora, no caminho do desenvolvimento e mais pr\u00f3ximos da vacina da Covid-19, tenho certeza de que teremos um ano novo muito melhor\u201d, afirmou Botelho.<\/p>\n<p>Autor de 50 Leis Ordin\u00e1rias e 01 Lei Complementar, 85 Resolu\u00e7\u00f5es e 03 Emendas Constitucionais, Botelho apresentou novas a\u00e7\u00f5es em 2020. Confira no site www.eduardobotelho.com.br ou www.al.mt.gov.br\/deputados<\/p>\n<p>Atividade em 2020:<\/p>\n<p>781 \u2013 Indica\u00e7\u00f5es<\/p>\n<p>222 \u2013 Mo\u00e7\u00f5es de Aplausos<\/p>\n<p>59 \u2013 Projetos de leis<\/p>\n<p>29 \u2013 Projetos de Resolu\u00e7\u00e3o<\/p>\n<p>04 \u2013 Requerimentos<\/p>\n<p>87 \u2013 Mo\u00e7\u00f5es de Congratula\u00e7\u00e3o<\/p>\n<p>02 \u2013 Propostas de Emenda Constitucional<\/p>\n<p><strong>ALGUMAS LEIS DE BOTELHO<\/strong><\/p>\n<p>Lei Ordin\u00e1ria \u2013 11238\/2020<\/p>\n<p>Disp\u00f5e sobre a isen\u00e7\u00e3o do pagamento de taxas de inscri\u00e7\u00e3o em concursos p\u00fablicos aos volunt\u00e1rios da Justi\u00e7a Eleitoral e jurados que atuarem no Tribunal do J\u00fari, no \u00e2mbito do estado de Mato Grosso, e adota outras provid\u00eancias.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11210\/2020<\/p>\n<p>Autoriza o Poder Executivo a adquirir, preferencialmente, produtos da Agricultura Familiar para incluir nas cestas b\u00e1sicas dos programas assistenciais e distribu\u00ed-los \u00e0 popula\u00e7\u00e3o de baixa renda, enquanto perdurar a pandemia da Covid-19\/ Coronav\u00edrus e d\u00e1 outras provid\u00eancias.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11208\/2020<\/p>\n<p>Regulamenta em Mato Grosso a Lei Federal 13.989\/2020, que disp\u00f5e sobre o uso da Telemedicina durante a crise causada pelo Coronav\u00edrus (sars-cov-2).<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11175\/2020<\/p>\n<p>Estabelece o descarte correto de m\u00e1scara de prote\u00e7\u00e3o individual e outros equipamentos de prote\u00e7\u00e3o individual \u2013 EPI\u2019s em vias e logradouros p\u00fablicos, bem como a sua separa\u00e7\u00e3o em recipientes de lixo domiciliar e comercial, como medidas de preven\u00e7\u00e3o e redu\u00e7\u00e3o de riscos de adquirir ou transmitir a Covid-19, na forma que indica, e d\u00e1 outras provid\u00eancias.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11174\/2020<\/p>\n<p>Institui o Selo Estabelecimento Seguro e Saud\u00e1vel, que ir\u00e1 reconhecer as empresas de Mato Grosso que cumpram as recomenda\u00e7\u00f5es da Secretaria de Estado de Sa\u00fade para evitar a contamina\u00e7\u00e3o dos espa\u00e7os com Covid-19.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11167\/2020<\/p>\n<p>Estabelece \u201cfila zero\u201d nos hospitais p\u00fablicos e privados quando houver decreta\u00e7\u00e3o de estado de calamidade p\u00fablica em raz\u00e3o de epidemias, pandemias e endemias no estado de mato grosso e d\u00e1 outras provid\u00eancias.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11166\/2020<\/p>\n<p>Assegura aos pacientes com doen\u00e7a renal cr\u00f4nica em tratamento de hemodi\u00e1lise e di\u00e1lise e aos pacientes com neoplasia maligna em tratamento de quimioterapia e radioterapia atendimento priorit\u00e1rio para vacina, testes r\u00e1pidos e\/ou RT-PCR e sorol\u00f3gico para diagn\u00f3stico do Coronav\u00edrus\/Covid-19 ou outras doen\u00e7as virais, relacionadas \u00e0 pandemia, epidemia ou endemia.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11079\/2020<\/p>\n<p>Reconhece Nobres como a capital mato-grossense do ecoturismo sustent\u00e1vel.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 11035\/2019<\/p>\n<p>Disp\u00f5e sobre o oferecimento de atendimento psicol\u00f3gico ou psicopedag\u00f3gico nas escolas p\u00fablicas e privadas do estado de Mato Grosso e d\u00e1 outras provid\u00eancias.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 10970\/2019<\/p>\n<p>Institui a implanta\u00e7\u00e3o de cursos \u00e0 mulher gestante sobre cuidados e atendimentos emergenciais a crian\u00e7as de zero a seis anos na rede hospitalar p\u00fablica do estado de mato grosso.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 10927\/2019<\/p>\n<p>Determina a disponibiliza\u00e7\u00e3o de tratamento para Retinoblastoma em unidade hospitalar p\u00fablica estadual e unidades privadas conveniadas com o Mato Grosso.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 10902\/2019<\/p>\n<p>Disp\u00f5e sobre a institui\u00e7\u00e3o do programa feira da mulher do campo e d\u00e1 outras provid\u00eancias.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 10837\/2019<\/p>\n<p>Cria o Selo de Produtos de Origem Quilombola, provenientes de \u00e1reas j\u00e1 reconhecidas ou em processo de reconhecimento.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 10676\/2018<\/p>\n<p>Torna obrigat\u00f3rio que todos os hospitais e maternidades de Mato Grosso tenham sala adequada para a realiza\u00e7\u00e3o de parto natural ou humanizado.<\/p>\n<p>Lei Ordin\u00e1ria \u2013 10580\/2017<\/p>\n<p>Institui a pol\u00edtica estadual de qualifica\u00e7\u00e3o t\u00e9cnica e profissional \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica e familiar.<\/p>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\"><i>Foto: MAURICIO BARBANT\u00a0 \u00a0 \u00a0|\u00a0 \u00a0\u00a0<\/i>Fonte:\u00a0<a href=\"https:\/\/www.al.mt.gov.br\/midia\/texto\/botelho-avalia-expectativas-para-2021-e-encerra-ano-com-50-leis-de-sua-autoria\/visualizar#73\" target=\"_blank\" rel=\"noopener noreferrer\">ALMT<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Autor de 50 leis ordin\u00e1rias para melhorar as condi\u00e7\u00f5es de vida da popula\u00e7\u00e3o mato-grossense, o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-30819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30819"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30819\/revisions"}],"predecessor-version":[{"id":30821,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30819\/revisions\/30821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30820"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}