{"id":30833,"date":"2021-01-06T10:21:42","date_gmt":"2021-01-06T14:21:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30833"},"modified":"2021-01-06T10:21:42","modified_gmt":"2021-01-06T14:21:42","slug":"botelho-destaca-estudo-tecnico-do-projeto-que-altera-modal-vlt-para-brt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/botelho-destaca-estudo-tecnico-do-projeto-que-altera-modal-vlt-para-brt\/","title":{"rendered":"Botelho destaca estudo t\u00e9cnico do projeto que altera modal VLT para BRT"},"content":{"rendered":"<p>O retorno dos trabalhos em Plen\u00e1rio na Assembleia Legislativa foi marcado pela limpeza da pauta com a segunda vota\u00e7\u00e3o da Mensagem 126\/20, que estima a receita e fixa a despesa do Estado de Mato Grosso para o exerc\u00edcio financeiro de 2021 &#8211; Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA 913\/2020). Tamb\u00e9m aprova\u00e7\u00e3o do requerimento para tramita\u00e7\u00e3o em car\u00e1ter de urg\u00eancia, urgent\u00edssima do Projeto de Lei 01\/21 \u2013 Mensagem 173 que acrescenta dispositivo \u00e0 Lei 9647\/11, que autoriza o Governo do Estado a implantar em Cuiab\u00e1 o BRT (Bus Rapid Transit \u2013 \u00d4nibus de Tr\u00e2nsito R\u00e1pido), devido \u00e0 necessidade de alterar o projeto aprovado anteriormente, em 2011, que autorizava a implanta\u00e7\u00e3o do Ve\u00edculo Leve sobre Trilhos \u2013 VLT.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante a primeira vota\u00e7\u00e3o, o presidente da ALMT, deputado Eduardo Botelho (DEM) concedeu pedido de vistas, por 24 horas, ao deputado L\u00fadio Cabral (PT). O projeto autoriza o Poder Executivo a alterar, mediante aditivo, os contratos de financiamento firmados com a Caixa Econ\u00f4mica Federal, para prever o BRT movido \u00e0 eletricidade como alternativa ao VLT. Pr\u00f3xima sess\u00e3o ser\u00e1 nesta quarta-feira (06.01), \u00e0s 10 horas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cChegou o projeto em regime de urg\u00eancia para autorizar o governo a fazer a mudan\u00e7a do modal VLT para o BRT porque na \u00e9poca do VLT foi feito um projeto de lei aqui. Agora, vamos fazer outro projeto voltando para o BRT. O governo pediu urg\u00eancia, urgent\u00edssima e quando isso acontece a Casa decide se aprova ou n\u00e3o\u201d, explicou o parlamentar, ao acrescentar que a Revis\u00e3o Geral Anual dos servidores voltar\u00e1 \u00e0 pauta ap\u00f3s a posse da Mesa Diretora, no dia 1\u00ba de fevereiro.<\/p>\n<p>O presidente afirmou que o governo fez a mudan\u00e7a de modal baseado em estudos t\u00e9cnicos, que ser\u00e3o analisados pelas comiss\u00f5es permanentes da Casa de Leis.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cVamos colocar nas comiss\u00f5es para analisar se h\u00e1 pol\u00eamica ou n\u00e3o. Vamos fazer de acordo com o andamento das comiss\u00f5es. O projeto j\u00e1 vem com estudo t\u00e9cnico, que foi feito sem a interfer\u00eancia de ningu\u00e9m. Eu por exemplo n\u00e3o sabia dessa mudan\u00e7a, fiquei sabendo quando o governador nos chamou l\u00e1 e mostrou que o BRT \u00e9 o mais vi\u00e1vel. Se caso o governo optasse pelo VLT n\u00e3o havia garantia de que em 10 anos estaria conclu\u00eddo. Ent\u00e3o, optou pela conclus\u00e3o plaus\u00edvel que \u00e9 o BRT\u201d, declarou.<\/p>\n<p>&nbsp;<\/p>\n<p>LOA \u2013 Sobre o or\u00e7amento estadual, Botelho informou que o projeto e as emendas foram debatidos \u00e0 exaust\u00e3o, tanto que as emendas acatadas n\u00e3o dar\u00e3o preju\u00edzos ao governo. \u201cS\u00e3o emendas que apenas mudam recursos de secretaria. Eu coloquei emenda de R$ 10 milh\u00f5es para a Ager e R$ 2 milh\u00f5es para a Secretaria de Cultura porque acho que l\u00e1 precisa de recursos, isso n\u00e3o vai alterar em nada para o Executivo\u201d. Botelho disse que Mato Grosso ter\u00e1 um or\u00e7amento maior que o previsto ficando entre R$ 23 a R$ 25 bilh\u00f5es, al\u00e9m dos recursos do FEX.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por:\u00a0\u00a0ITIMARA FIGUEIREDO\u00a0 \u00a0|\u00a0 \u00a0\u00a0<i>Foto: MAURICIO BARBANT\u00a0 \u00a0 \u00a0|\u00a0 \u00a0 Fonte:\u00a0 www.al.mt.gov.br<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O retorno dos trabalhos em Plen\u00e1rio na Assembleia Legislativa foi marcado pela limpeza da pauta &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30834,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-30833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Parlamentares tamb\u00e9m aprovaram o or\u00e7amento estadual. RGA voltar\u00e1 volta ser discutida em fevereiro","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30833"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30833\/revisions"}],"predecessor-version":[{"id":30835,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30833\/revisions\/30835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30834"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}