{"id":30853,"date":"2021-01-06T10:49:00","date_gmt":"2021-01-06T14:49:00","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30853"},"modified":"2021-01-06T10:49:00","modified_gmt":"2021-01-06T14:49:00","slug":"ate-janeiro-brasil-ja-registra-23-casos-de-ferrugem-asiatica-na-soja","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/ate-janeiro-brasil-ja-registra-23-casos-de-ferrugem-asiatica-na-soja\/","title":{"rendered":"At\u00e9 janeiro: Brasil j\u00e1 registra 23 casos de ferrugem asi\u00e1tica na soja"},"content":{"rendered":"<p>O Brasil j\u00e1 registra 23 casos de ferrugem asi\u00e1tica na soja na safra 2020\/2021, segundo levantamento do Cons\u00f3rcio Antiferrugem, liderado pela Embrapa. Na mesma \u00e9poca do ano passado o pa\u00eds tinha 26 casos da doen\u00e7a j\u00e1 confirmados. Importantes munic\u00edpios produtores de soja do pa\u00eds est\u00e3o na lista de casos confirmados da doen\u00e7a.<\/p>\n<p>No dia 4 de janeiro, o site do cons\u00f3rcio confirmou os mais recentes casos de ferrugem asi\u00e1tica na soja, um em Mato Grosso do Sul e outro no Paran\u00e1, subindo o total para 23 nesta safra.<\/p>\n<p>At\u00e9 o momento, o\u00a0<strong>Paran\u00e1 lidera<\/strong>\u00a0como o estado com mais casos da doen\u00e7a, 6 no total. Entre os munic\u00edpios o destaque negativo fica com\u00a0<strong>Castro<\/strong>, que j\u00e1 acumula dois casos da doen\u00e7a nesta safra de soja. Depois ainda aparecem com 1 caso cada:\u00a0<strong>Arapoti, Carambe\u00ed, Terra Roxa e Londrina<\/strong>.<\/p>\n<p><strong>Mato Grosso<\/strong>\u00a0j\u00e1 possui dois registros da doen\u00e7a, uma em\u00a0<strong>Campo Verde<\/strong>\u00a0e outra em\u00a0<strong>Primavera do Leste<\/strong>.<\/p>\n<p><strong>S\u00e3o Paulo<\/strong>\u00a0tamb\u00e9m possui dois casos confirmados na soja, ambos em\u00a0<strong>Itaber\u00e1<\/strong>.<\/p>\n<p>Completam a lista\u00a0<strong>Ponta Por\u00e3 (MS), Uberl\u00e2ndia (MG) e S\u00e3o Domingos (SC).<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2828902\" src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/SOJA-FERRUGEM-06-01.jpg\" sizes=\"auto, (max-width: 672px) 100vw, 672px\" srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/SOJA-FERRUGEM-06-01-286x240.jpg 286w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/SOJA-FERRUGEM-06-01-573x480.jpg 573w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/SOJA-FERRUGEM-06-01.jpg 672w\" alt=\"FERRUGEM SOJA\" width=\"672\" height=\"563\" \/><\/p>\n<p><strong>Casos excepcionais<\/strong><\/p>\n<p>Os 5 casos em S\u00e3o Miguel do Araguaia, em Goi\u00e1s, e outros 5 em Lagoa da Confus\u00e3o, no Tocantins, fazem parte de casos excepcionais. Ambos foram registrados durante o vazio sanit\u00e1rio da soja, devido uma autoriza\u00e7\u00e3o especial de plantio, que consiste no alagamento das \u00e1reas. O m\u00e9todo garante que n\u00e3o h\u00e1 prolifera\u00e7\u00e3o da doen\u00e7a, mas os registros dizem o contr\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 www.canalrural.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil j\u00e1 registra 23 casos de ferrugem asi\u00e1tica na soja na safra 2020\/2021, segundo &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30854,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-30853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Segundo levantamento do Cons\u00f3rcio Antiferrugem, importantes munic\u00edpios do Paran\u00e1, Mato Grosso do Sul, Mato Grosso e Minas Gerais j\u00e1 registraram a doen\u00e7a","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30853"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30853\/revisions"}],"predecessor-version":[{"id":30855,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30853\/revisions\/30855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30854"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}