{"id":30935,"date":"2021-01-07T10:28:06","date_gmt":"2021-01-07T14:28:06","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=30935"},"modified":"2021-01-07T10:28:06","modified_gmt":"2021-01-07T14:28:06","slug":"falta-de-acordo-com-mercosul-tira-brasil-do-mercado-de-suco-sul-coreano","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/falta-de-acordo-com-mercosul-tira-brasil-do-mercado-de-suco-sul-coreano\/","title":{"rendered":"Falta de acordo com Mercosul tira Brasil do mercado de suco sul-coreano"},"content":{"rendered":"<p>A falta de acordo comercial com o Mercosul tirou o suco de laranja brasileiro das prateleiras sul-coreanas. Atualmente, a taxa de importa\u00e7\u00e3o paga pelo produto praticamente torna invi\u00e1vel a venda do produto brasileiro ao pa\u00eds asi\u00e1tico, segundo estudo da\u00a0<a href=\"http:\/\/www.citrusbr.com\/\"><strong>Associa\u00e7\u00e3o Nacional dos Exportadores de Sucos C\u00edtricos (CitrusBR)<\/strong><\/a>, que mostra que a perda daquele mercado se d\u00e1 por conta de uma s\u00e9rie de acordos bilaterais firmados entre Coreia do Sul e outros pa\u00edses, como Estados Unidos e Europa.<\/p>\n<p>As vendas de suco de laranja brasileiro (FCOJ) para a Coreia do Sul, que na safra 2002\/03 chegaram a 33.900 toneladas, com receitas de US$ 28 milh\u00f5es, na safra 2019\/20 foram de apenas 46 toneladas de FCOJ, com uma receita de US$ 92 mil. Uma queda de 99,8% em volume e 99,6% em receita, respectivamente, conforme dados da Secretaria de Com\u00e9rcio Exterior (Secex), vinculada ao Minist\u00e9rio da Economia, compilados no estudo da CitruBR.<\/p>\n<p>A Coreia estabeleceu na Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio (OMC) uma tarifa de 54% ad valorem cobrada de todos os pa\u00edses do mundo. Essa taxa, por\u00e9m, pode ser diferente caso as negocia\u00e7\u00f5es entre Mercosul e Coreia do Sul culminem em acordo bilateral. Isso ajudaria o Brasil a brigar por mais espa\u00e7o naquele mercado.<\/p>\n<p>\u201cA Coreia do Sul tem 15 acordos comerciais em vigor. Dois deles foram celebrados com Estados Unidos e Uni\u00e3o Europeia, o que trouxe grande impacto para o FCOJ brasileiro naquele Pa\u00eds\u201d, informa em comunicado o diretor-executivo da CitrusBR, Ibiapaba Netto.<\/p>\n<p>Com quase 52 milh\u00f5es de habitantes e Produto Interno Bruto (PIB) de US$ 1,6 trilh\u00e3o em 2019, a Coreia do Sul \u00e9 um mercado valioso e o peso da tarifa para acessar esse mercado pode ser observado pelo hist\u00f3rico das importa\u00e7\u00f5es daquele pa\u00eds. Em 2013, ano seguinte \u00e0 entrada em vigor do acordo entre Coreia do Sul e Estados Unidos, os americanos tomaram a lideran\u00e7a como principais fornecedores de FCOJ, gozando da isen\u00e7\u00e3o total de tarifa de importa\u00e7\u00e3o. Em 2015 entrou em vigor o acordo entre Uni\u00e3o Europeia e Coreia do Sul. Entre os anos de 2017 e 2019, o Velho Continente aumentou a sua participa\u00e7\u00e3o em rela\u00e7\u00e3o aos Estados Unidos \u00e0 medida que o Brasil praticamente foi exclu\u00eddo daquele mercado.<\/p>\n<p>Outro reflexo do modelo tarif\u00e1rio sul-coreano apontado pelo estudo \u00e9 o impacto na competitividade do suco em compara\u00e7\u00e3o com outras bebidas. Ao mesmo tempo em que o Brasil foi praticamente exclu\u00eddo daquele mercado, bebidas mistas oriundas de pa\u00edses, como Turquia e Vietn\u00e3, tomaram a lideran\u00e7a na participa\u00e7\u00e3o das importa\u00e7\u00f5es daquele pa\u00eds. A participa\u00e7\u00e3o do FCOJ caiu de 68% para 13%.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 www.canalrural.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A falta de acordo comercial com o Mercosul tirou o suco de laranja brasileiro das &hellip;<\/p>\n","protected":false},"author":4,"featured_media":30936,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-30935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Segundo estudo da CitrusBR, o Brasil reduziu em 99% suas exporta\u00e7\u00f5es de suco de laranja ao pa\u00eds asi\u00e1tico nos \u00faltimos anos","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30935"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30935\/revisions"}],"predecessor-version":[{"id":30937,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/30935\/revisions\/30937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/30936"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}