{"id":31248,"date":"2021-01-15T10:25:57","date_gmt":"2021-01-15T14:25:57","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=31248"},"modified":"2021-01-15T10:25:57","modified_gmt":"2021-01-15T14:25:57","slug":"kalil-assina-protocolo-para-aquisicao-da-coronavac-e-se-reune-com-mauro-mendes","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/kalil-assina-protocolo-para-aquisicao-da-coronavac-e-se-reune-com-mauro-mendes\/","title":{"rendered":"Kalil assina protocolo para aquisi\u00e7\u00e3o da Coronavac e se re\u00fane com Mauro Mendes"},"content":{"rendered":"<p>O prefeito de V\u00e1rzea Grande, Kalil Baracat ter\u00e1 uma extensa agenda de trabalho nesta quarta-feira, 13 de janeiro de 2021, assinando nas primeiras horas da manh\u00e3 na manh\u00e3, durante reuni\u00e3o do Comit\u00ea de Enfrentamento ao novo Coronav\u00edrus \u2013 COVID 19, o protocolo de inten\u00e7\u00e3o de aquisi\u00e7\u00e3o de vacinas do Instituto Butantan, a CoronaVac.<\/p>\n<p>Tamb\u00e9m se re\u00fane a partir das 10 horas com o governador Mauro Mendes para tratar da troca do modal de transporte coletivo de massa do VLT (Ve\u00edculo Leve sobre Trilhos) para o BRT (Bus Rapid Transit) e de assunto da COVID-19, e, \u00e0s 14 horas sua equipe da Secretaria Municipal de Sa\u00fade se re\u00fane com o secret\u00e1rio de Sa\u00fade de Mato Grosso, Gilberto Figueiredo em busca de refor\u00e7o na atua\u00e7\u00e3o de controle da pandemia.<\/p>\n<p>O Comit\u00ea de V\u00e1rzea Grande dever\u00e1 ainda disparar novas medidas para endurecimento na fiscaliza\u00e7\u00e3o com apoio de aparato das Pol\u00edcias Militar, Civil e do Corpo de Bombeiros, al\u00e9m da Vigil\u00e2ncia em Sa\u00fade do Estado e da cidade que ainda ir\u00e1 refor\u00e7ar a Guarda Municipal para fiscaliza\u00e7\u00e3o mais efetiva a partir da evolu\u00e7\u00e3o do quadro de transmiss\u00e3o da COVID-19 de N\u00edvel Baixo para Moderado conforme demonstrado no Boletim do Governo do Estado de Mato Grosso da \u00faltima segunda-feira, 11 de janeiro.<\/p>\n<p>A inten\u00e7\u00e3o maior \u00e9 evitar medidas de fechamento de setores da economia, sendo que para isto, ter\u00e1 que haver um trabalho para reduzir o n\u00famero de transmiss\u00e3o de novos casos da COVID-19 que disparou nos \u00faltimos dias. O prefeito de V\u00e1rzea Grande tamb\u00e9m quer impedir um novo lockdown como aconteceu por mais de uma vez no decorrer do ano de 2020.<\/p>\n<p>No final de 2020, ainda na gest\u00e3o da prefeita Lucimar Sacre de Campos, foi formalizado ao Instituto Butantan o interesse de ter acesso a vacinas contra a COVID-19, caso n\u00e3o houvesse manifesta\u00e7\u00e3o por parte do Governo Federal que \u00e9 respons\u00e1vel pela pol\u00edtica de aquisi\u00e7\u00e3o e distribui\u00e7\u00e3o de vacinas como acontece com todas as demais doen\u00e7as<br \/>\npass\u00edveis de terem as pessoas imunizadas, como H1N1, Sarampo, BCG, Tr\u00edplice entre outros.<\/p>\n<p>Eu reuni\u00e3o com os principais secret\u00e1rios, o prefeito Kalil Baracat, sinalizou que n\u00e3o dispensa adotar medidas para conter a propaga\u00e7\u00e3o da doen\u00e7a, mas vai faz\u00ea-lo de forma criteriosa para se ter o m\u00ednimo de impacto para a popula\u00e7\u00e3o e para V\u00e1rzea Grande.<\/p>\n<p>\u201cNossa miss\u00e3o \u00e9 criar mecanismos de equil\u00edbrio que permita mais qualidade de vida para as pessoas sem colocar em risco a economia e a gera\u00e7\u00e3o de emprego e renda, pois a sa\u00fade p\u00fablica funciona porque temos recursos para serem aplicados no combate a COVID-19\u201d, disse Kalil sinalizando que n\u00e3o existe custo para se preservar a vida das pessoas.<\/p>\n<p>Ele disse ainda que vai aproveitar para definir uma s\u00e9rie de medidas em parceria com o Governo Mauro Mendes para fomentar o desenvolvimento em V\u00e1rzea Grande e recuperar a posi\u00e7\u00e3o de destaque da segundo maior cidade de Mato Grosso. \u201cMuito foi feito nos \u00faltimos anos, mas temos que avan\u00e7ar e melhorar ainda mais\u201d, disse Kalil Baracat.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 \u00a0www.varzeagrande.mt.gov.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de V\u00e1rzea Grande, Kalil Baracat ter\u00e1 uma extensa agenda de trabalho nesta quarta-feira, &hellip;<\/p>\n","protected":false},"author":4,"featured_media":31251,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-31248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Prefeito de V\u00e1rzea Grande quer garantir acesso da popula\u00e7\u00e3o \u00e0 vacina do Instituto Butantan e vai debater com o governador a quest\u00e3o da troca do VLT pelo BRT","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/31248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=31248"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/31248\/revisions"}],"predecessor-version":[{"id":31252,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/31248\/revisions\/31252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/31251"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=31248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=31248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=31248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}