{"id":31348,"date":"2021-01-18T09:28:46","date_gmt":"2021-01-18T13:28:46","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=31348"},"modified":"2021-01-18T09:28:46","modified_gmt":"2021-01-18T13:28:46","slug":"mauro-e-gilberto-figueiredo-participam-de-ato-de-recebimento-das-vacinas-do-ministerio-da-saude","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mauro-e-gilberto-figueiredo-participam-de-ato-de-recebimento-das-vacinas-do-ministerio-da-saude\/","title":{"rendered":"Mauro e Gilberto Figueiredo participam de ato de recebimento das vacinas do Minist\u00e9rio da Sa\u00fade"},"content":{"rendered":"<p>O Governador Mauro Mendes e o secret\u00e1rio de Estado de Sa\u00fade, Gilberto Figueiredo, participam nesta segunda-feira (18) do ato simb\u00f3lico de recebimento das vacinas contra a Covid-19, realizado pelo Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>O ato est\u00e1 marcado para as 7 horas (hor\u00e1rio de Bras\u00edlia), em Guarulhos, no Estado de S\u00e3o Paulo. Na ocasi\u00e3o, o ministro da Sa\u00fade, Eduardo Pazuello, dever\u00e1 anunciar quando as vacinas contra a Covid-19 ser\u00e3o enviadas aos Estados para dar in\u00edcio \u00e0 imuniza\u00e7\u00e3o da popula\u00e7\u00e3o.<\/p>\n<p><strong>Plano Estadual<\/strong><\/p>\n<p>O Governo de Mato Grosso, por meio da Secretaria Estadual da Sa\u00fade (SES-MT), trabalha em uma for\u00e7a tarefa para que a vacina contra a Covid-19 chegue aos munic\u00edpios o mais r\u00e1pido poss\u00edvel. A a\u00e7\u00e3o faz parte do Plano Estadual de Operacionaliza\u00e7\u00e3o da Vacina\u00e7\u00e3o contra a Covid-19 em Mato Grosso e prev\u00ea, caso necess\u00e1rio, o apoio de seis aeronaves do Centro Integrado de Opera\u00e7\u00f5es A\u00e9reas (Ciopaer).<\/p>\n<p>Com o objetivo de promover a adequada log\u00edstica da vacina, com seguran\u00e7a, efetividade e equidade, a SES vai ampliar a Rede de Frio Estadual e j\u00e1 viabiliza uma Central Estadual e mais quatro Centrais Regionais (Barra do Gar\u00e7as, C\u00e1ceres, Rondon\u00f3polis e Sinop), assim como a aquisi\u00e7\u00e3o de equipamentos de refrigera\u00e7\u00e3o e frota adequada para distribui\u00e7\u00e3o terrestre. O investimento estimado \u00e9 de R$ 2,2 milh\u00f5es.<\/p>\n<p>A escolta dos materiais at\u00e9 os 14 polos de distribui\u00e7\u00e3o ser\u00e1 feita pela Secretaria de Estado de Seguran\u00e7a P\u00fablica (Sesp), al\u00e9m das Pol\u00edcias Federal e Rodovi\u00e1ria Federal e o Minist\u00e9rio da Defesa. Nos casos em que for necess\u00e1rio, o Ciopaer disponibilizar\u00e1 sua frota a\u00e9rea para dar celeridade \u00e0 distribui\u00e7\u00e3o.<\/p>\n<p>Nos pr\u00f3ximos dias, os 141 munic\u00edpios de Mato Grosso come\u00e7am a receber as agulhas e seringas que j\u00e1 se encontram em estoque e que ser\u00e3o utilizadas no plano de vacina\u00e7\u00e3o contra a Covid-19. A SES tamb\u00e9m providenciou a aquisi\u00e7\u00e3o suplementar de 6,5 mil seringas para o enfrentamento de vacina\u00e7\u00e3o, com investimento na ordem de R$ 2,8 milh\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 \u00a0www.odocumento.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governador Mauro Mendes e o secret\u00e1rio de Estado de Sa\u00fade, Gilberto Figueiredo, participam nesta &hellip;<\/p>\n","protected":false},"author":4,"featured_media":31349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-31348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/31348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=31348"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/31348\/revisions"}],"predecessor-version":[{"id":31350,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/31348\/revisions\/31350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/31349"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=31348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=31348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=31348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}