{"id":32048,"date":"2021-02-04T09:18:49","date_gmt":"2021-02-04T13:18:49","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=32048"},"modified":"2021-02-04T09:18:49","modified_gmt":"2021-02-04T13:18:49","slug":"precos-dos-alimentos-estao-no-maior-nivel-desde-julho-de-2014","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/precos-dos-alimentos-estao-no-maior-nivel-desde-julho-de-2014\/","title":{"rendered":"Pre\u00e7os dos alimentos est\u00e3o no maior n\u00edvel desde julho de 2014"},"content":{"rendered":"<p>O \u00edndice de pre\u00e7os dos alimentos da\u00a0<a href=\"http:\/\/www.fao.org\/brasil\/pt\/\"><strong>Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para Agricultura e Alimenta\u00e7\u00e3o (FAO)<\/strong><\/a>\u00a0subiu 4,3% em janeiro, na compara\u00e7\u00e3o com o m\u00eas anterior, alcan\u00e7ando m\u00e9dia de 113,3 pontos, na oitava alta consecutiva. Desta vez, o \u00edndice tamb\u00e9m atingiu o maior n\u00edvel desde julho de 2014. Al\u00e9m disso, houve uma revis\u00e3o para cima da m\u00e9dia de dezembro, de 107,5 para 108,6, informou a FAO.<\/p>\n<p>A alta dos pre\u00e7os foi liderada pelos cereais, a\u00e7\u00facar e \u00f3leos vegetais, disse a ag\u00eancia de alimentos das Na\u00e7\u00f5es Unidas, nesta quinta-feira, 4.<\/p>\n<p>As preocupa\u00e7\u00f5es com a seguran\u00e7a alimentar levaram a Argentina e a R\u00fassia, grandes produtores e exportadores de gr\u00e3os, a apertar os controles de vendas externas nos \u00faltimos meses. A Argentina, que enfrenta o clima seco, colocou um limite nas exporta\u00e7\u00f5es de milho para garantir abastecimento dom\u00e9stico, mas logo voltou atr\u00e1s. A R\u00fassia, de olho no aumento dos pre\u00e7os dos alimentos para os seus cidad\u00e3os, estabeleceu planos para aumentar os impostos sobre as exporta\u00e7\u00f5es de gr\u00e3os. Ambas as medidas, juntamente com a forte demanda chinesa por milho, aumentaram os pre\u00e7os dos cereais, disse a FAO.<\/p>\n<p>Um sub\u00edndice de acompanhamento dos pre\u00e7os dos cereais subiu 7,1% (8,3 pontos) em janeiro, \u201crefletindo o fornecimento global cada vez mais restrito com produ\u00e7\u00e3o e estoques mais baixos do que o esperado anteriormente nos Estados Unidos, e compras substanciais pela China\u201d, relatou a organiza\u00e7\u00e3o.<\/p>\n<p>As preocupa\u00e7\u00f5es com a seca na Am\u00e9rica do Sul e uma suspens\u00e3o tempor\u00e1ria dos registros de exporta\u00e7\u00e3o de milho na Argentina tamb\u00e9m ajudaram a empurrar os pre\u00e7os internacionais do milho para o seu n\u00edvel mais alto desde meados de 2013, destacou.<\/p>\n<p>Os pre\u00e7os do \u00f3leo vegetal aumentaram 5,8% (7,7 pontos), atingindo teve m\u00e9dia de 138,8 pontos em janeiro, n\u00edvel mais alto desde 2012, j\u00e1 que a produ\u00e7\u00e3o de \u00f3leo de palma na Indon\u00e9sia e na Malas foi mais fraca do que o esperado, em virtude do excesso de chuvas, enquanto as greves na Argentina reduziram o fornecimento global de \u00f3leo de soja.<\/p>\n<p>Os pre\u00e7os do a\u00e7\u00facar subiram 8,1% gra\u00e7as \u00e0 forte demanda, ao aumento do pre\u00e7o do petr\u00f3leo e \u00e0 desvaloriza\u00e7\u00e3o do real.<\/p>\n<p>Latic\u00ednios e Carnes registraram ganhos mais discretos.<\/p>\n<p>O \u00cdndice de Pre\u00e7os de Carne da FAO subiu 1%, com m\u00e9dia de 96,0 pontos em janeiro, em compara\u00e7\u00e3o com dezembro de 2020, enquanto o \u00cdndice de Pre\u00e7os de Latic\u00ednios teve m\u00e9dia de 111,0 pontos em janeiro, um aumento de 1,6% ante o m\u00eas anterior.<\/p>\n<p>Entre as carnes, os pre\u00e7os para aves subiram mais, especialmente para as origens brasileiras, \u201csustentadas pela forte demanda global de importa\u00e7\u00e3o, enquanto surtos de gripe avi\u00e1ria restringiram as exporta\u00e7\u00f5es de aves de v\u00e1rios pa\u00edses europeus\u201d, afirma a FAO. \u201cApesar das altas compras da China no per\u00edodo que antecedeu as comemora\u00e7\u00f5es do ano-novo do pa\u00eds, as cota\u00e7\u00f5es dos pre\u00e7os das carnes bovina e su\u00edna aumentaram apenas ligeiramente, uma vez que a oferta global permaneceu adequada para atender a demanda.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00edndice de pre\u00e7os dos alimentos da\u00a0Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para Agricultura e Alimenta\u00e7\u00e3o (FAO)\u00a0subiu &hellip;<\/p>\n","protected":false},"author":4,"featured_media":32049,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-32048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"A alta foi liderada pelos cereais, a\u00e7\u00facar e \u00f3leos vegetais, disse a ag\u00eancia de alimentos das Na\u00e7\u00f5es Unidas","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=32048"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32048\/revisions"}],"predecessor-version":[{"id":32050,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32048\/revisions\/32050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/32049"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=32048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=32048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=32048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}