{"id":32218,"date":"2021-02-08T09:36:29","date_gmt":"2021-02-08T13:36:29","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=32218"},"modified":"2021-02-08T09:36:29","modified_gmt":"2021-02-08T13:36:29","slug":"soja-milho-e-cafe-caem-e-boi-tem-leve-alta-veja-noticias-desta-segunda","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/soja-milho-e-cafe-caem-e-boi-tem-leve-alta-veja-noticias-desta-segunda\/","title":{"rendered":"Soja, milho e caf\u00e9 caem, e boi tem leve alta; veja not\u00edcias desta segunda"},"content":{"rendered":"<ul>\n<li>Boi: demanda interna impede altas mais expressivas<\/li>\n<li>Milho: pre\u00e7os recuam pela terceira semana consecutiva<\/li>\n<li>Soja: colheita avan\u00e7a e cota\u00e7\u00f5es t\u00eam leve baixa<\/li>\n<li>Caf\u00e9: ar\u00e1bica cai no Brasil apesar da valoriza\u00e7\u00e3o em Nova York<\/li>\n<li>No exterior: bolsas estendem alta monitorando est\u00edmulos e vacinas<\/li>\n<li>No Brasil: infla\u00e7\u00e3o \u00e9 destaque da agenda econ\u00f4mica desta semana<\/li>\n<\/ul>\n<p><strong>Agenda:<\/strong><\/p>\n<ul>\n<li>Brasil: boletim Focus (Banco Central)<\/li>\n<li>Brasil: balan\u00e7a comercial da primeira semana de janeiro<\/li>\n<li>EUA: inspe\u00e7\u00f5es de exporta\u00e7\u00e3o semanal (USDA)<\/li>\n<\/ul>\n<h3><strong>Boi: demanda interna impede altas mais expressivas<\/strong><\/h3>\n<p>A demanda interna segue como fator principal limitante para novas altas mais expressivas da arroba no mercado brasileiro. O indicador do\u00a0<a href=\"http:\/\/cepea.esalq.usp.br\/br\"><strong>Cepea<\/strong><\/a>\u00a0passou de R$ 300,10 para R$ 301,70 por arroba, e segue abaixo do recorde marcado nesta primeira semana de fevereiro. Algumas consultorias especializadas reportam neg\u00f3cios pr\u00f3ximos a R$ 305 por arroba, sobretudo para animais voltados ao mercado externo.<\/p>\n<p>Na B3, este movimento de um limite para as altas fica ainda mais latente e os contratos futuros do boi gordo chegaram ao segundo dia consecutivo de baixas. O vencimento para fevereiro passou de R$ 298,60 para R$ 296,70 e o para mar\u00e7o foi de R$ 291,95 para R$ 290,40 por arroba.<\/p>\n<h3><strong>Milho: pre\u00e7os recuam pela terceira semana consecutiva<\/strong><\/h3>\n<p>O indicador do milho do Cepea recuou pela terceira semana consecutiva. As quedas nas compara\u00e7\u00f5es semanais foram modestas, de 0,11%, 1,29% e 0,67%, respectivamente. Por\u00e9m, d\u00e3o o tom da fraqueza dos pre\u00e7os desde meados de janeiro. A saca caiu de R$ 83,02 para R$ 82,78 na passagem di\u00e1ria e chegou ao menor patamar em 25 dias.<\/p>\n<p>No mercado futuro, os contratos mais curtos apresentaram leves quedas, enquanto os mais longos tiveram baixas maiores. O vencimento para mar\u00e7o passou de R$ 85,41 para R$ 85,36 e o para julho foi de R$ 78,23 para R$ 78,07 por saca.<\/p>\n<h3><strong>Soja: colheita avan\u00e7a e cota\u00e7\u00f5es t\u00eam leve baixa<\/strong><\/h3>\n<p>\u00c0 medida que a colheita da safra avan\u00e7a, o mercado brasileiro de soja ganha um pouco mais de movimento. Com isso, as cota\u00e7\u00f5es tendem a acompanhar a din\u00e2mica combinada da oleaginosa negociada na Bolsa de Chicago e do c\u00e2mbio no Brasil. O dia foi bastante vol\u00e1til nos Estados Unidos, mas ao fim do preg\u00e3o os pre\u00e7os recuaram. Em rela\u00e7\u00e3o ao d\u00f3lar, a moeda norte-americana teve expressiva desvaloriza\u00e7\u00e3o ante o real.<\/p>\n<p>De acordo com a consultoria Safras &amp; Mercado, em Passo Fundo (RS), a saca recuou de R$ 168 para R$ 167; em Cascavel (PR), foi de R$ 169 para R$ 168; e no porto de Paranagu\u00e1 (PR), baixou de R$ 165 para R$ 164.<\/p>\n<h3><strong>Caf\u00e9: ar\u00e1bica cai no Brasil apesar da valoriza\u00e7\u00e3o em Nova York<\/strong><\/h3>\n<p>A saca do caf\u00e9 ar\u00e1bica recuou no mercado f\u00edsico brasileiro de acordo com a consultoria Safras &amp; Mercado, apesar da valoriza\u00e7\u00e3o moderada observada em Nova York. O grande motivo foi a queda do d\u00f3lar em rela\u00e7\u00e3o ao real. Segundo a Safras, o dia foi travado na comercializa\u00e7\u00e3o em virtude da baixa da moeda norte-americana.<\/p>\n<p>No sul de Minas Gerais, o ar\u00e1bica bebida boa com 15% de cata\u00e7\u00e3o terminou o dia em R$ 660\/665 a saca, em compara\u00e7\u00e3o a R$ 670\/675 do dia anterior. No cerrado mineiro, o ar\u00e1bica bebida dura com 15% de cata\u00e7\u00e3o teve pre\u00e7o de R$ 670\/675, ante R$ 675\/680 de ontem.<\/p>\n<h3><strong>No exterior: bolsas estendem alta monitorando est\u00edmulos e vacinas<\/strong><\/h3>\n<p>As bolsas europeias globais procuram estender a alta da semana anterior monitorando de perto o avan\u00e7o da discuss\u00e3o em torno da aprova\u00e7\u00e3o do novo pacote de est\u00edmulos nos Estados Unidos. Al\u00e9m disso, o mercado fica atento a not\u00edcias em rela\u00e7\u00e3o \u00e0s vacinas, pois alguns estudos t\u00eam mostrado diminui\u00e7\u00e3o da efic\u00e1cia contra novas variantes do coronav\u00edrus, sobretudo contra a encontrada inicialmente na \u00c1frica do Sul.<\/p>\n<p>Neste domingo, 7, a \u00c1frica do Sul suspendeu a distribui\u00e7\u00e3o da vacina desenvolvida pela Universidade de Oxford em virtude de um estudo indicar diminui\u00e7\u00e3o da prote\u00e7\u00e3o do imunizante contra a variante encontrada no pa\u00eds. Os pesquisadores de Oxford argumentaram que a prote\u00e7\u00e3o contra casos moderados e graves da doen\u00e7a n\u00e3o p\u00f4de ser avaliada, pois os participantes do estudo eram de baixo risco.<\/p>\n<h3><strong>No Brasil: infla\u00e7\u00e3o \u00e9 destaque da agenda econ\u00f4mica desta semana<\/strong><\/h3>\n<p>Com o mercado de juros especulando cada vez mais se a taxa de juros subir\u00e1 na pr\u00f3xima reuni\u00e3o do Copom, os investidores focam bastante aten\u00e7\u00e3o nos dados de infla\u00e7\u00e3o. Nesta ter\u00e7a-feira, 9, o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) divulga o IPCA de janeiro e a Funda\u00e7\u00e3o Getulio Vargas (FGV), a primeira pr\u00e9via do IGP-M de fevereiro. Na sexta-feira, 12, a FGV ainda traz o IGP-10 de fevereiro.<\/p>\n<p>As commodities agr\u00edcolas e o min\u00e9rio de ferro t\u00eam pressionado os \u00edndices gerais de pre\u00e7os desde o ano passado em virtude do d\u00f3lar e de pol\u00edticas de est\u00edmulos econ\u00f4micos no Brasil e no mundo. O mercado de juros acompanha de perto os \u00edndices de infla\u00e7\u00e3o ao consumidor para monitorar se o aumento dos custos est\u00e1 sendo repassado a outros produtos da cesta de consumo. O Banco Central deve reagir com alta dos juros caso perceba que este repasse esteja ocorrendo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boi: demanda interna impede altas mais expressivas Milho: pre\u00e7os recuam pela terceira semana consecutiva Soja: &hellip;<\/p>\n","protected":false},"author":4,"featured_media":32219,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-32218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Enquanto isso, poss\u00edvel menor efici\u00eancia de algumas vacinas contra novas variantes do coronav\u00edrus deixa o mercado financeiro em alerta","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=32218"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32218\/revisions"}],"predecessor-version":[{"id":32220,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32218\/revisions\/32220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/32219"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=32218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=32218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=32218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}