{"id":32611,"date":"2021-02-17T10:04:29","date_gmt":"2021-02-17T14:04:29","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=32611"},"modified":"2021-02-17T10:04:29","modified_gmt":"2021-02-17T14:04:29","slug":"soja-casos-de-ferrugem-explodem-e-ja-ultrapassam-numeros-das-ultimas-quatro-safras","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/soja-casos-de-ferrugem-explodem-e-ja-ultrapassam-numeros-das-ultimas-quatro-safras\/","title":{"rendered":"Soja: casos de ferrugem explodem e j\u00e1 ultrapassam n\u00fameros das \u00faltimas quatro safras"},"content":{"rendered":"<p>O come\u00e7o da safra de soja 2020\/2021 no Brasil, em rela\u00e7\u00e3o \u00e0 ferrugem asi\u00e1tica, foi tranquilo, j\u00e1 que o clima n\u00e3o colaborava para que a doen\u00e7a avan\u00e7asse muito. Pois, nos primeiros 15 dias de janeiro, essa hist\u00f3ria mudou e os casos registrados explodiram em quase todos os estados, fazendo com que o pa\u00eds atingisse, at\u00e9 agora, o maior n\u00famero de casos da doen\u00e7a das \u00faltimas cinco safras.<\/p>\n<p><a href=\"https:\/\/www.canalrural.com.br\/projeto-soja-brasil\/personagem-soja-brasil-2020-2021\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2834778 lazyloaded\" src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21.jpg\" sizes=\"auto, (max-width: 1251px) 100vw, 1251px\" srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21-320x13.jpg 320w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21-640x25.jpg 640w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21-840x33.jpg 840w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21.jpg 1251w\" alt=\"\" width=\"1251\" height=\"49\" data-srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21-320x13.jpg 320w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21-640x25.jpg 640w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21-840x33.jpg 840w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21.jpg 1251w\" data-src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/vote-aqui-personagem-20-21.jpg\" data-sizes=\"(max-width: 1251px) 100vw, 1251px\" \/><\/a><\/p>\n<p>At\u00e9 o dia 15 de janeiro, os casos j\u00e1 reportados da doen\u00e7a atingiram 192 no site do\u00a0<a href=\"http:\/\/www.consorcioantiferrugem.net\/#\/main\">Cons\u00f3rcio Antiferrugem<\/a>, liderado pela Embrapa. No in\u00edcio de janeiro, o pa\u00eds computava apenas 88 casos, mostrando que o avan\u00e7o neste curto espa\u00e7o de tempo foi maior at\u00e9 do que j\u00e1 se tinha acumulado desde o in\u00edcio da safra.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2835027 aligncenter ls-is-cached lazyloaded\" src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2.jpg\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2-288x240.jpg 288w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2-575x480.jpg 575w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2.jpg 658w\" alt=\"FERRUGEM SOJA\" width=\"658\" height=\"549\" data-srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2-288x240.jpg 288w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2-575x480.jpg 575w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2.jpg 658w\" data-src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-2.jpg\" data-sizes=\"(max-width: 658px) 100vw, 658px\" \/><\/p>\n<p>Vale destacar ainda que esse n\u00famero \u00e9 o maior (at\u00e9 15 de janeiro) desde a safra 2016\/2017, quando o pa\u00eds acumulava 133 casos da doen\u00e7a. No ano passado, por exemplo, que foi um com os menores n\u00fameros de ferrugem, nesta mesma \u00e9poca a quantidade de casos n\u00e3o passava de 54.<\/p>\n<p><strong>Por estados<\/strong><\/p>\n<p>Segundo o Cons\u00f3rcio Antiferrugem, j\u00e1 foram reportados casos da doen\u00e7a em 11 estados:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2835025 aligncenter lazyloaded\" src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021.jpg\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-320x102.jpg 320w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021.jpg 629w\" alt=\"SOJA FERRUGEM\" width=\"629\" height=\"201\" data-srcset=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021-320x102.jpg 320w, https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021.jpg 629w\" data-src=\"https:\/\/imagens-cdn.canalrural.com.br\/wp-content\/uploads\/ferrugem-2021.jpg\" data-sizes=\"(max-width: 629px) 100vw, 629px\" \/><\/p>\n<p>A exemplo de 2019\/2020, o Paran\u00e1 lidera o ranking entre os estados com mais casos de ferrugem asi\u00e1tica no pa\u00eds. At\u00e9 o momento j\u00e1 relataram 86 casos da doen\u00e7a, divididos entre 53 munic\u00edpios. No ano passado, em toda a safra foram 71 casos, e em 2018, 58 casos. Somente em 2017 o estado havia tido tantos casos quanto agora, em torno de 113 casos de ferrugem.<\/p>\n<p>Os munic\u00edpios paranaenses com maiores problemas e mais casos relatados s\u00e3o: Cascavel (7), Palotina (5), Guarapuava (5), Castro (5) e Cand\u00f3i (4).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O come\u00e7o da safra de soja 2020\/2021 no Brasil, em rela\u00e7\u00e3o \u00e0 ferrugem asi\u00e1tica, foi &hellip;<\/p>\n","protected":false},"author":4,"featured_media":32612,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-32611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Em 15 dias o pa\u00eds registrou mais de 100 casos da doen\u00e7a. Cidades paranaenses lideram entre as com mais problemas no pa\u00eds. Confira!","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=32611"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32611\/revisions"}],"predecessor-version":[{"id":32613,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/32611\/revisions\/32613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/32612"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=32611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=32611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=32611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}