{"id":33044,"date":"2021-02-26T15:21:35","date_gmt":"2021-02-26T19:21:35","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=33044"},"modified":"2021-02-26T15:21:35","modified_gmt":"2021-02-26T19:21:35","slug":"sem-convenio-100-parana-tera-acrescimo-de-r-2-bi-no-custo-de-producao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sem-convenio-100-parana-tera-acrescimo-de-r-2-bi-no-custo-de-producao\/","title":{"rendered":"Sem Conv\u00eanio 100, Paran\u00e1 ter\u00e1 acr\u00e9scimo de R$ 2 bi no custo de produ\u00e7\u00e3o"},"content":{"rendered":"<p>O Conselho Nacional de Pol\u00edtica Fazend\u00e1ria (Confaz), formado por secret\u00e1rios de fazenda de todos estados e do Distrito Federal decidem nesta sexta-feira, 26, se renovam ou n\u00e3o o Conv\u00eanio 100, que reduz em at\u00e9 60% a base de c\u00e1lculo de ICMS sobre o transporte de insumos e produtos entre os estados. Se o benef\u00edcio fiscal n\u00e3o for renovado, c\u00e1lculos da secretaria de pol\u00edtica agr\u00edcola do Minist\u00e9rio da Agricultura (Mapa) indicam um impacto de R$ 16 bilh\u00f5es sobre a cadeia de alimentos.<\/p>\n<p>Sem o Conv\u00eanio 100, o Paran\u00e1 vai ser o segundo estado a ter o maior acr\u00e9scimo no custo de produ\u00e7\u00e3o, com mais de R$ 2 bilh\u00f5es. Segundo Luiz Elieser, t\u00e9cnico do departamento econ\u00f4mico da\u00a0<a href=\"https:\/\/sistemafaep.org.br\/faep\/\"><strong>Federa\u00e7\u00e3o de Agricultura do Paran\u00e1 (Faep)<\/strong><\/a>, o c\u00e1lculo preocupa, pois considera apenas as despesas a cadeia dos gr\u00e3os, deixando de fora o setor pecu\u00e1rio.<\/p>\n<p>\u201cSem a renova\u00e7\u00e3o do benef\u00edcio, o custo de vari\u00e1vel dos gr\u00e3os vai subir. Apenas para o caso da soja, a expectativa \u00e9 que o produtor desembolse 15% a mais, considerando que os insumos representam 67% do gasto do produtor. Al\u00e9m disso, o cultivo de outros gr\u00e3os pode ser inviabilizado\u201d, alerta Elieser.<\/p>\n<p>Ainda segundo o t\u00e9cnico da Faep, o fim do Conv\u00eanio 100 teria impacto para a popula\u00e7\u00e3o. \u201cQuando voc\u00ea aumenta o custo de produ\u00e7\u00e3o, o pre\u00e7os dos alimentos tamb\u00e9m ficam mais caros. Isso pode ainda causar mais press\u00e3o na infla\u00e7\u00e3o\u201d.<\/p>\n<p>Diante dos efeitos negativos sem a continuidade do benef\u00edcio fiscal, Elieser acredita que o Confaz ir\u00e1 renovar o Conv\u00eanio 100. \u201cO setor produtivo se mobilizou para negociar a manuten\u00e7\u00e3o do benef\u00edcio. A Faep tem um pedido para que ele seja estendido at\u00e9 31 de dezembro de 2021\u201d, finaliza<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Pol\u00edtica Fazend\u00e1ria (Confaz), formado por secret\u00e1rios de fazenda de todos estados &hellip;<\/p>\n","protected":false},"author":4,"featured_media":33045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-33044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Segundo t\u00e9cnico da Faep, a cadeia de gr\u00e3os ser\u00e1 a mais impactada; no caso da soja, produtor pode ter que desembolsar 15% a mais","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/33044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=33044"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/33044\/revisions"}],"predecessor-version":[{"id":33046,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/33044\/revisions\/33046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/33045"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=33044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=33044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=33044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}