{"id":33810,"date":"2021-03-12T08:42:21","date_gmt":"2021-03-12T12:42:21","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=33810"},"modified":"2021-03-12T08:42:21","modified_gmt":"2021-03-12T12:42:21","slug":"boi-e-milho-batem-recorde-e-soja-e-cafe-caem-veja-noticias-desta-sexta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/boi-e-milho-batem-recorde-e-soja-e-cafe-caem-veja-noticias-desta-sexta\/","title":{"rendered":"Boi e milho batem recorde e soja e caf\u00e9 caem; veja not\u00edcias desta sexta"},"content":{"rendered":"<ul>\n<li>Boi: oferta restrita se sobrep\u00f5e \u00e0 demanda interna fraca e arroba segue em alta<\/li>\n<li>Milho: saca chega ao nono dia de alta consecutiva<\/li>\n<li>Soja: cota\u00e7\u00e3o despenca mais de 3% com queda do d\u00f3lar<\/li>\n<li>Caf\u00e9: c\u00e2mbio tamb\u00e9m afeta pre\u00e7os do ar\u00e1bica no Brasil<\/li>\n<li>No exterior: \u00edndices de a\u00e7\u00f5es dos EUA renovam m\u00e1ximas hist\u00f3ricas<\/li>\n<li>No Brasil: d\u00f3lar cai 4,6% em dois dias<\/li>\n<\/ul>\n<p><strong>Agenda:<\/strong><\/p>\n<ul>\n<li>Brasil: vendas do varejo de janeiro (IBGE)<\/li>\n<li>Brasil: dados de desenvolvimento das lavouras do Mato Grosso (Imea)<\/li>\n<li>EUA: \u00edndice de pre\u00e7os ao produtor<\/li>\n<\/ul>\n<h3><strong>Boi: oferta restrita se sobrep\u00f5e \u00e0 demanda interna fraca e arroba segue em alta<\/strong><\/h3>\n<p>A consultoria Safras &amp; Mercado voltou a registrar avan\u00e7o das cota\u00e7\u00f5es da arroba do boi gordo em S\u00e3o Paulo. Em seu levantamento di\u00e1rio de pre\u00e7os, a empresa registrou o pre\u00e7o passando de\u00a0<a href=\"https:\/\/www.canalrural.com.br\/agronegocio\/boi-gordo-registra-alta-precos\/\"><strong>R$ 310 para R$ 311<\/strong><\/a>. A demanda interna que j\u00e1 estava enfraquecida deve sofrer mais um pouco com as novas medidas de restri\u00e7\u00e3o \u00e0 abertura de bares e restaurantes pelo Brasil. A nova rodada de aux\u00edlio emergencial deve ter um peso bastante abaixo do que foi no ano passado, pois o valor agora ser\u00e1 menor.<\/p>\n<p>Por outro lado, mesmo com a queda do d\u00f3lar nos \u00faltimos dois dias, os frigor\u00edficos exportadores mantiveram comportamento agressivo. Isso sinaliza que as vendas para a China devem continuar acelerando ap\u00f3s um in\u00edcio de ano lento.<\/p>\n<h3><strong>Milho: saca chega ao nono dia de alta consecutiva<\/strong><\/h3>\n<p>O indicador do milho do\u00a0<a href=\"https:\/\/www.cepea.esalq.usp.br\/br\"><strong>Cepea<\/strong><\/a>, calculado com base nos pre\u00e7os praticados em Campinas (SP), chegou ao nono dia consecutivo de alta. A cota\u00e7\u00e3o variou 0,14% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 91,59 para R$ 91,72 por saca. Portanto, no acumulado do ano, o indicador teve uma alta de 16,62%. Em 12 meses, os pre\u00e7os alcan\u00e7aram 61,56% de valoriza\u00e7\u00e3o.<\/p>\n<p>No mercado futuro, os contratos de milho negociados na B3 tamb\u00e9m seguem avan\u00e7ando. O vencimento para mar\u00e7o passou de R$ 91,08 para R$ 92,33 e o para maio foi de R$ 93,86 para R$ 94,06 por saca. As consultorias especializadas apontam que o foco da log\u00edstica voltada para a soja impulsiona os pre\u00e7os do cereal.<\/p>\n<h3><strong>Soja: cota\u00e7\u00e3o despenca mais de 3% com queda do d\u00f3lar<\/strong><\/h3>\n<p>A forte queda do d\u00f3lar em rela\u00e7\u00e3o ao real gerou uma grande press\u00e3o negativa nos pre\u00e7os da soja no mercado brasileiro. O indicador da soja do Cepea, calculado com base nos pre\u00e7os praticados no porto de Paranagu\u00e1 (PR), recuou 3,33% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 177,23 para R$ 171,32 por saca. Ainda assim, no acumulado do ano, o indicador tem uma alta de 11,32%.<\/p>\n<p>Em Chicago, ap\u00f3s a forte baixa de quarta-feira, 10, os contratos futuros se recuperaram parcialmente. O contrato com vencimento para maio, o mais negociado atualmente, valorizou 0,27% e passou de US$ 14,096 para US$ 14,134 por bushel.<\/p>\n<h3><strong>Caf\u00e9: c\u00e2mbio tamb\u00e9m afeta pre\u00e7os do ar\u00e1bica no Brasil<\/strong><\/h3>\n<p>Assim como no caso da soja, o c\u00e2mbio pressionou negativamente os pre\u00e7os do caf\u00e9 ar\u00e1bica no Brasil, ainda que em menor grau, pois no exterior houve alta mais consistente. O indicador do caf\u00e9 ar\u00e1bica do Cepea, calculado com base nos pre\u00e7os praticados em Minas Gerais, S\u00e3o Paulo e Paran\u00e1, caiu 0,32% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 739,17 para R$ 736,8 por saca.<\/p>\n<p>Na Bolsa de Nova York, os contratos futuros do ar\u00e1bica seguem em trajet\u00f3ria de recupera\u00e7\u00e3o e chegaram ao quarto dia consecutivo de alta. O contrato com vencimento para maio, o mais l\u00edquido no momento, teve alta de 1,15% e passou de US$ 1,3085 para US$ 1,3235 por libra-peso.<\/p>\n<h3><strong>No exterior: \u00edndices de a\u00e7\u00f5es dos EUA renovam m\u00e1ximas hist\u00f3ricas<\/strong><\/h3>\n<p>Os \u00edndices Dow Jones, S&amp;P 500 e Nasdaq, os principais dentro das bolsas norte-americanas, renovaram nesta quinta-feira, 11, as respectivas m\u00e1ximas hist\u00f3ricas. O otimismo se deu na esteira da san\u00e7\u00e3o do presidente Joe Biden do pacote de US$ 1,9 trilh\u00e3o em est\u00edmulos \u00e0 economia dos Estados Unidos contra os impactos negativos da pandemia.<\/p>\n<p>Na abertura dos mercados desta sexta, por\u00e9m, as taxas de juros dos t\u00edtulos do Tesouro dos EUA voltam a subir e pressionam negativamente os \u00edndices de a\u00e7\u00f5es. O t\u00edtulo com vencimento em dez anos chegou \u00e0 m\u00e1xima de 1,614%. O temor dos investidores \u00e9 de que o excesso de recursos destinados \u00e0s empresas seja migrado para os t\u00edtulos em virtude da eleva\u00e7\u00e3o dos juros.<\/p>\n<h3><strong>No Brasil: d\u00f3lar cai 4,6% em dois dias<\/strong><\/h3>\n<p>O al\u00edvio do d\u00f3lar em rela\u00e7\u00e3o \u00e0s moedas emergentes no exterior, a aprova\u00e7\u00e3o da PEC Emergencial em segundo turno na C\u00e2mara dos Deputados e a atua\u00e7\u00e3o do Banco Central fizeram a moeda norte-americana ter desvaloriza\u00e7\u00e3o expressiva em rela\u00e7\u00e3o ao real. Em apenas dois dias, o recuo chegou a 4,6%. Nesta quinta, a cota\u00e7\u00e3o passou de R$ 5,6526 para R$ 5,5428.<\/p>\n<p>Na agenda econ\u00f4mica de hoje, o destaque \u00e9 a divulga\u00e7\u00e3o das vendas do varejo em janeiro. \u00c9 poss\u00edvel que o resultado ainda seja impactado pelo fim do aux\u00edlio emergencial, como foi no caso do m\u00eas de dezembro. Enquanto a ind\u00fastria apresentou dados positivos em janeiro, o setor de servi\u00e7os teve retra\u00e7\u00e3o da receita e do volume.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boi: oferta restrita se sobrep\u00f5e \u00e0 demanda interna fraca e arroba segue em alta Milho: &hellip;<\/p>\n","protected":false},"author":4,"featured_media":33811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-33810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"O recuo do d\u00f3lar nos dois \u00faltimos dias pressiona as cota\u00e7\u00f5es internas das commodities. As que tiveram alta foi por causa da baixa oferta","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/33810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=33810"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/33810\/revisions"}],"predecessor-version":[{"id":33812,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/33810\/revisions\/33812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/33811"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=33810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=33810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=33810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}