{"id":34523,"date":"2021-03-25T09:26:30","date_gmt":"2021-03-25T13:26:30","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=34523"},"modified":"2021-03-25T09:26:30","modified_gmt":"2021-03-25T13:26:30","slug":"mato-grosso-realiza-evento-sobre-oportunidades-para-o-agronegocio-na-china","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mato-grosso-realiza-evento-sobre-oportunidades-para-o-agronegocio-na-china\/","title":{"rendered":"Mato Grosso realiza evento sobre oportunidades para o agroneg\u00f3cio na China"},"content":{"rendered":"<p>O Governo de Mato Grosso, por meio da Secretaria de Estado de Desenvolvimento Econ\u00f4mico (Sedec), realiza nesta sexta-feira (26.03) o webinar Oportunidades para o Agroneg\u00f3cio na China. Durante uma hora, produtores rurais e empres\u00e1rios do agroneg\u00f3cio do Estado poder\u00e3o entender como funciona as rela\u00e7\u00f5es comerciais entre Mato Grosso e China e, ainda, aprender na pr\u00e1tica como estreitar os la\u00e7os com o pa\u00eds asi\u00e1tico.<\/p>\n<p>O secret\u00e1rio de Desenvolvimento Econ\u00f4mico de Mato Grosso, C\u00e9sar Miranda, far\u00e1 uma palestra sobre esta rela\u00e7\u00e3o entre o Estado e a China que vem de muitos anos e est\u00e1 se fortalecendo.<\/p>\n<p>\u201cA China \u00e9 nosso principal parceiro comercial e essa rela\u00e7\u00e3o \u00e9 uma via de m\u00e3o dupla. Mato Grosso cresceu muito com essa parceria e a China tamb\u00e9m expandiu com nossos produtos. O webinar ser\u00e1 um momento de muito aprendizado e troca de informa\u00e7\u00f5es\u201d, avalia.<\/p>\n<p>As tend\u00eancias de mercado, os benef\u00edcios de se fazer neg\u00f3cios com a China e os caminhos para estas negocia\u00e7\u00f5es ser\u00e3o revelados por Rafael Fraga, consultor de Neg\u00f3cios Internacionais da CW CPA, empresa de consultoria e contabilidade com escrit\u00f3rios na China continental e Hong Kong.<\/p>\n<p>\u201cExplicarei caminhos para negociar, tanto para comprar como para vender para a China e os benef\u00edcios de ter uma empresa l\u00e1, como fazer para abrir esta empresa e as obriga\u00e7\u00f5es legais. Al\u00e9m disso, apresentarei um estudo de caso de cliente que entrou no mercado asi\u00e1tico pela China, quais obst\u00e1culos enfrentou e as vantagens de atuar l\u00e1\u201d, explica Fraga.<\/p>\n<p>A analista da Apex Brasil, Ana Claudia Barbosa, apresentar\u00e1 oportunidades de neg\u00f3cios a empres\u00e1rios brasileiros em feiras e miss\u00f5es comerciais que ocorrer\u00e3o durante o ano de 2021 na China.<\/p>\n<p>\u201cA Apex tem uma boa agenda para este ano para aquele mercado em diferentes setores, como l\u00e1cteos, caf\u00e9, frutas, carnes, entre outros\u201d, explica.<\/p>\n<p>A Apex Brasil tem escrit\u00f3rios em Xangai e Pequim que d\u00e3o suporte aos empres\u00e1rios brasileiros. \u201cPara quem est\u00e1 pensando em China, h\u00e1 tamb\u00e9m um ponto essencial no plano de neg\u00f3cios: o com\u00e9rcio on-line ou e-commerce. Vou explicar um pouco sobre este modelo de neg\u00f3cio e a import\u00e2ncia dele no mercado chin\u00eas\u201d, finaliza Ana Claudia.<\/p>\n<p>Servi\u00e7o<\/p>\n<p>Webinar \u201cOportunidades para o Agroneg\u00f3cio na China\u201d<\/p>\n<p>Data: 26\/03\/2021, \u00e0s 9h de Mato Grosso<\/p>\n<p>Local: Facebook do Governo do Estado (www.facebook.com\/govmatogrosso)<\/p>\n<p>Participantes<\/p>\n<p>C\u00e9sar Miranda, secret\u00e1rio de Estado de Desenvolvimento Econ\u00f4mico de MT<\/p>\n<p>Ana Claudia Barbosa, analista da Apex Brasil<\/p>\n<p>Rafael Fraga, consultor da CW CPA<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 RdmOnline<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo de Mato Grosso, por meio da Secretaria de Estado de Desenvolvimento Econ\u00f4mico (Sedec), &hellip;<\/p>\n","protected":false},"author":4,"featured_media":34524,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-34523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Webinar ser\u00e1 nesta sexta-feira (26.03), \u00e0s 9h, transmitido pelo Facebook do Governo","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/34523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=34523"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/34523\/revisions"}],"predecessor-version":[{"id":34525,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/34523\/revisions\/34525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/34524"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=34523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=34523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=34523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}