{"id":35016,"date":"2021-04-01T08:51:58","date_gmt":"2021-04-01T12:51:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=35016"},"modified":"2021-04-01T08:51:58","modified_gmt":"2021-04-01T12:51:58","slug":"trf4-condena-mineradora-a-ressarcir-uniao-por-extracao-irregular-superior-a-63-mil-toneladas-de-areia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/trf4-condena-mineradora-a-ressarcir-uniao-por-extracao-irregular-superior-a-63-mil-toneladas-de-areia\/","title":{"rendered":"TRF4 condena mineradora a ressarcir Uni\u00e3o por extra\u00e7\u00e3o irregular superior a 63 mil toneladas de areia"},"content":{"rendered":"<div id=\"infocoweb_corpo\" class=\"infocoweb_corpo\">\n<p>O Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF4) julgou procedente um recurso da Uni\u00e3o e condenou a empresa paranaense Minera\u00e7\u00e3o Floresta Gua\u00edra Ltda a pagar a quantia de R$ 227.947,45 por\u00a0ter\u00a0realizado extra\u00e7\u00e3o ilegal de areia, no volume de 63.849 toneladas, em \u00e1reas dos munic\u00edpios de Gua\u00edra (PR) e Terra Roxa (PR), durante os anos de 2014 a 2017. A decis\u00e3o \u00e9 da 3\u00aa Turma da Corte e foi proferida de maneira un\u00e2nime na sess\u00e3o virtual de julgamento do colegiado ocorrida no dia 24\/3.<\/p>\n<p><strong>Hist\u00f3rico do caso<\/strong><\/p>\n<p>A a\u00e7\u00e3o civil p\u00fablica foi ajuizada pela Uni\u00e3o em julho de 2019 na primeira inst\u00e2ncia da Justi\u00e7a Federal do Paran\u00e1. A autora requisitou a condena\u00e7\u00e3o da empresa ao ressarcimento integral do dano causado ao er\u00e1rio em decorr\u00eancia da extra\u00e7\u00e3o ilegal do recurso mineral.<\/p>\n<p>A Uni\u00e3o alegou que a r\u00e9 realizou extra\u00e7\u00e3o irregular de areia em volume superior ao autorizado e ainda continuou a lavra nos meses subsequentes ao t\u00e9rmino da validade das Guias de Utiliza\u00e7\u00e3o, em novembro de 2016.<\/p>\n<p>Dessa forma, a conduta da empresa teria resultado em les\u00e3o ao patrim\u00f4nio p\u00fablico no valor de R$ 227.947,45, correspondente as 63.849 toneladas de areia retiradas ilegalmente.<\/p>\n<p><strong>Senten\u00e7a<\/strong><\/p>\n<p>O ju\u00edzo da 2\u00aa Vara Federal de Umuarama (PR) analisou a a\u00e7\u00e3o e considerou parcialmente procedente o pedido da Uni\u00e3o, condenando a r\u00e9 a ressarcir ao er\u00e1rio o montante de R$ 113.973,73, sendo a quantia atualizada pela Taxa Selic at\u00e9 a data de\u00a0efetiva\u00e7\u00e3o do pagamento. A senten\u00e7a foi proferida em dezembro de 2019.<\/p>\n<p><strong>Apela\u00e7\u00e3o<\/strong><\/p>\n<p>A Uni\u00e3o recorreu da decis\u00e3o ao TRF4. No recurso, sustentou que os crit\u00e9rios utilizados para a fixa\u00e7\u00e3o do montante indenizat\u00f3rio seriam insuficientes, j\u00e1 que a empresa foi condenada a ressarcir o valor correspondente a 50% do faturamento total com a extra\u00e7\u00e3o irregular do min\u00e9rio.<\/p>\n<p>A parte autora defendeu que o entendimento adotado no Superior Tribunal de Justi\u00e7a (STJ) \u00e9 de que a indeniza\u00e7\u00e3o deve ser integral e proporcional \u00e0 redu\u00e7\u00e3o patrimonial sofrida pela Uni\u00e3o e que a atualiza\u00e7\u00e3o monet\u00e1ria incide desde a retirada irregular at\u00e9 o efetivo pagamento.<\/p>\n<p><strong>Decis\u00e3o do colegiado<\/strong><\/p>\n<p>A relatora do caso no Tribunal, desembargadora federal Marga Inge Barth Tessler, destacou em seu voto que, de acordo com o C\u00f3digo Civil, \u201ca indeniza\u00e7\u00e3o em raz\u00e3o do ato il\u00edcito praticado pela empresa r\u00e9 deve ser suficiente para reparar o dano causado, ou seja, deve ser equivalente, de forma hipot\u00e9tica, \u00e0 reposi\u00e7\u00e3o do min\u00e9rio extra\u00eddo do seu local de origem\u201d.<\/p>\n<p>\u201cNesse contexto, a indeniza\u00e7\u00e3o, no caso em an\u00e1lise, deve se dar pelo valor de comercializa\u00e7\u00e3o da areia irregularmente extra\u00edda pela parte r\u00e9, por corresponder ao pre\u00e7o ordin\u00e1rio do min\u00e9rio, de propriedade da Uni\u00e3o, o qual foi indevidamente retirado da natureza. Assim, o valor a ser indenizado corresponde a R$ 227.947,45\u201d, completou a magistrada.<\/p>\n<p>Tessler tamb\u00e9m seguiu entendimento estabelecido pelo STJ para determinar que a atualiza\u00e7\u00e3o monet\u00e1ria sobre a d\u00edvida pelo ato il\u00edcito deve incidir a partir da data do efetivo preju\u00edzo.<\/p>\n<p>Nesse sentido, a 3\u00aa Turma, por unanimidade, deu total provimento \u00e0 apela\u00e7\u00e3o da Uni\u00e3o.<\/p>\n<p><a href=\"https:\/\/odocumento.com.br\/trf4-condena-mineradora-a-ressarcir-uniao-por-extracao-irregular-superior-a-63-mil-toneladas-de-areia\/controlador.php?acao=consulta_processual_resultado_pesquisa&amp;selForma=NU&amp;txtValor=50036161920194047004&amp;selOrigem=TRF&amp;chkMostrarBaixados=1\">N\u00b0\u00a05003616-19.2019.4.04.7004\/TRF<\/a><\/p>\n<\/div>\n<div id=\"infocoweb_rodape\" class=\"infocoweb_rodape\">Fonte:\u00a0<a href=\"https:\/\/www.trf4.jus.br\/trf4\/controlador.php?acao=noticia_visualizar&amp;id_noticia=15773#73\" target=\"_blank\" rel=\"noopener\">TRF4<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF4) julgou procedente um recurso da Uni\u00e3o e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":35017,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-35016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/35016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=35016"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/35016\/revisions"}],"predecessor-version":[{"id":35018,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/35016\/revisions\/35018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/35017"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=35016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=35016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=35016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}