{"id":35960,"date":"2021-04-14T14:49:45","date_gmt":"2021-04-14T18:49:45","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=35960"},"modified":"2021-04-14T14:49:45","modified_gmt":"2021-04-14T18:49:45","slug":"milho-doencas-causadas-pela-cigarrinha-serao-cobertas-pelo-proagro","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/milho-doencas-causadas-pela-cigarrinha-serao-cobertas-pelo-proagro\/","title":{"rendered":"Milho: doen\u00e7as causadas pela cigarrinha ser\u00e3o cobertas pelo Proagro"},"content":{"rendered":"<p>O\u00a0<a href=\"https:\/\/www.bcb.gov.br\/\"><strong>Banco Central<\/strong><\/a>\u00a0emitiu um comunicado nesta ter\u00e7a-feira, 13, esclarecendo o tratamento a ser dado, no \u00e2mbito do Programa de Garantia da Atividade Agropecu\u00e1ria (Proagro), \u00e0s perdas decorrentes da cigarrinha<em>\u00a0Dalbulus maidis<\/em>\u00a0na lavoura de milho.<\/p>\n<p>Segundo o documento, as perdas causadas por doen\u00e7as transmitidas pela cigarrinha receber\u00e3o a cobertura do Proagro, \u201cj\u00e1 que n\u00e3o se disp\u00f5e, atualmente, de m\u00e9todo difundido de combate, controle ou profilaxia, que seja t\u00e9cnica e economicamente exequ\u00edvel\u201d.<\/p>\n<p>A nota, assinada pelo chefe do Departamento de Regula\u00e7\u00e3o, Supervis\u00e3o e Controle das Opera\u00e7\u00f5es do Cr\u00e9dito Rural e do Proagro (Derop), Claudio Filgueiras Pacheco Moreira, tamb\u00e9m recomenda aos agentes do Proagro a revis\u00e3o de eventuais indeferimentos de pedidos de cobertura de opera\u00e7\u00f5es enquadradas a partir de 1\u00ba de julho de 2020, caso tenham sido motivados pelo entendimento de que as perdas decorrentes da presen\u00e7a de cigarrinha nas lavouras de milho n\u00e3o seriam amparadas pelo programa.<\/p>\n<p>Caso sejam desenvolvidos m\u00e9todos de controle ou combate t\u00e9cnica e economicamente exequ\u00edveis da praga, a orienta\u00e7\u00e3o pode ser alterada futuramente.<\/p>\n<h3><strong>O que \u00e9 o Proagro?<\/strong><\/h3>\n<p>O programa \u00e9 custeado por recursos alocados pela Uni\u00e3o, al\u00e9m de recursos provenientes da taxa paga pelo produtor rural para aderir ao Proagro.<\/p>\n<p>O objetivo \u00e9 garantir a amortiza\u00e7\u00e3o ou a liquida\u00e7\u00e3o de custeios agr\u00edcolas de financiamento, quando no caso de ocorr\u00eancia de sinistro na lavoura e na propor\u00e7\u00e3o das perdas apuradas, e permitir o recebimento dos recursos pr\u00f3prios comprovadamente aplicados na lavoura.<\/p>\n<p>Nas opera\u00e7\u00f5es de custeio agr\u00edcola, h\u00e1 cobertura de lavouras afetadas pelos seguintes fen\u00f4menos: chuva excessiva, geada, granizo, seca, varia\u00e7\u00e3o excessiva de temperatura, ventos fortes e ventos frios. Nas opera\u00e7\u00f5es de custeio pecu\u00e1rio, s\u00e3o amparadas as perdas decorrentes de doen\u00e7as sem m\u00e9todo de combate, controle ou profilaxia.<\/p>\n<p>O Proagro \u00e9 administrado pelo Banco Central e executado por institui\u00e7\u00f5es financeiras autorizadas a operar em cr\u00e9dito rural.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00a0Banco Central\u00a0emitiu um comunicado nesta ter\u00e7a-feira, 13, esclarecendo o tratamento a ser dado, no \u00e2mbito &hellip;<\/p>\n","protected":false},"author":4,"featured_media":35961,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-35960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Segundo o Banco Central, a decis\u00e3o foi tomada porque n\u00e3o existe forma de manejo e controle vi\u00e1vel para lidar com a praga no momento","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/35960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=35960"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/35960\/revisions"}],"predecessor-version":[{"id":35962,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/35960\/revisions\/35962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/35961"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=35960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=35960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=35960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}