{"id":36322,"date":"2021-04-20T10:32:42","date_gmt":"2021-04-20T14:32:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=36322"},"modified":"2021-04-20T10:32:42","modified_gmt":"2021-04-20T14:32:42","slug":"subvencao-do-plano-safra-acordo-permitira-recomposicao-de-recursos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/subvencao-do-plano-safra-acordo-permitira-recomposicao-de-recursos\/","title":{"rendered":"Subven\u00e7\u00e3o do Plano Safra: acordo permitir\u00e1 recomposi\u00e7\u00e3o de recursos"},"content":{"rendered":"<p>O deputado federal Efraim Filho (DEM-PB) apresentou nesta segunda-feira, 19, um projeto que altera a Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO). Entre outras coisas, o texto permite que o governo bloqueie por decreto despesas discricion\u00e1rias (que incluem custeio e investimentos) para recompor despesas obrigat\u00f3rias, como benef\u00edcios previdenci\u00e1rios, seguro-desemprego e<strong>\u00a0subs\u00eddios.<\/strong><\/p>\n<p>O tema muito interessa \u00e0 agropecu\u00e1ria, que teve boa parte dos recursos para subven\u00e7\u00e3o do Plano Safra 2021\/22 cortada. A proposta or\u00e7ament\u00e1ria do governo federal para 2021 previa R$ 10,3 bilh\u00f5es para equaliza\u00e7\u00e3o do cr\u00e9dito agr\u00edcola, seguro rural e apoio \u00e0 comercializa\u00e7\u00e3o. Por\u00e9m, o relator-geral do Or\u00e7amento, Marcio Bittar (MDB-AC), reduziu para R$ 7,55 bilh\u00f5es.<\/p>\n<p>Em transmiss\u00e3o ao vivo no Canal Rural nesta segunda-feira, o presidente da\u00a0<a href=\"https:\/\/fpagropecuaria.org.br\/\"><strong>Frente Parlamentar da Agropecu\u00e1ria (FPA)<\/strong><\/a>, deputado federal S\u00e9rgio Souza (PP-PR), afirmou que o Congresso estava fechando um acordo com o governo federal para resolver o impasse e permitir o remanejamento de recursos.<\/p>\n<p>\u201cO governo poder\u00e1 fazer uma parte disso de forma administrativa e uma parte precisar\u00e1 de autoriza\u00e7\u00e3o do Congresso Nacional. Ele [o Executivo] encaminha ao Congresso, e n\u00f3 vamos votar um PLN [Projeto de Lei do Congresso Nacional] para compor esses recursos\u201d, explica.<\/p>\n<p>Segundo o presidente da FPA, o acordo est\u00e1 bem encaminhado e tem tudo para dar certo. \u201cS\u00f3 n\u00e3o posso afirmar que est\u00e1 100% garantido porque depende de v\u00e1rios fatores e pessoas no meio do caminho. Mas eu diria que est\u00e1 muito bem encaminhando o acordo para a recomposi\u00e7\u00e3o integral das perdas da equaliza\u00e7\u00e3o de juros em todos esses programas, principalmente para a agricultura familiar\u201d, pontuou.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.canalrural.com.br\/programas\/informacao\/rural-noticias\/daoud-subvencao-agro\/\"><strong>Daoud: Tudo indica que a subven\u00e7\u00e3o ao agro ser\u00e1 recomposta<\/strong><\/a><\/li>\n<\/ul>\n<p>O Programa Nacional de Fortalecimento da Agricultura Familiar (Pronaf) sofreu o maior corte. O governo federal havia previsto cerca de R$ 3,85 bilh\u00f5es para equaliza\u00e7\u00e3o, mas o valor foi reduzido em 35%, caindo para R$ 2,5 bilh\u00f5es.<\/p>\n<p>O secret\u00e1rio de Agricultura Familiar e Cooperativismo do\u00a0<a href=\"https:\/\/www.gov.br\/agricultura\/pt-br\"><strong>Minist\u00e9rio da Agricultura<\/strong><\/a>, Fernando Schwanke, lembrou que o recurso para subven\u00e7\u00e3o \u00e9 muito importante para fazer chegar o cr\u00e9dito rural mais barato ao produtor. \u201cPrecisamos continuar ampliando a produ\u00e7\u00e3o de alimentos dentro, do Pronaf principalmente\u201d, disse.<\/p>\n<p>J\u00e1 o coordenador do N\u00facleo Econ\u00f4mico na\u00a0<a href=\"https:\/\/www.cnabrasil.org.br\/\"><strong>Confedera\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Brasil (CNA)<\/strong><\/a>, Renato Conchon, refor\u00e7a a import\u00e2ncia de recompor toda a subven\u00e7\u00e3o, j\u00e1 que o recurso para equaliza\u00e7\u00e3o de juros do Programa Nacional de A poio ao M\u00e9dio Produtor Rural (Pronamp) tamb\u00e9m foi reduzido\u00a0em 28,4%, saindo de R$ 4,389 bilh\u00f5es para R$ 3,142 bilh\u00f5es.<\/p>\n<p>\u201cO m\u00e9dio produtor rural brasileiro precisa de um olhar diferenciado para fazer com que ele alavanque. Ele corre risco, em algum momento, se ele n\u00e3o for acompanhado, se ele n\u00e3o tiver uma pol\u00edtica voltada com um olhar diferenciado, de voltar para o Pronaf\u201d\u201d, afirma Conchon.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal Efraim Filho (DEM-PB) apresentou nesta segunda-feira, 19, um projeto que altera a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":36323,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-36322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Projeto permitir\u00e1 que o governo federal remaneje valores para atender despesas obrigat\u00f3rias, como os subs\u00eddios concedidos \u00e0 agropecu\u00e1ria","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=36322"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36322\/revisions"}],"predecessor-version":[{"id":36324,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36322\/revisions\/36324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/36323"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=36322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=36322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=36322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}