{"id":36445,"date":"2021-04-22T09:42:53","date_gmt":"2021-04-22T13:42:53","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=36445"},"modified":"2021-04-22T09:42:53","modified_gmt":"2021-04-22T13:42:53","slug":"soja-bate-recorde-no-porto-de-paranagua-veja-noticias-desta-quinta","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/soja-bate-recorde-no-porto-de-paranagua-veja-noticias-desta-quinta\/","title":{"rendered":"Soja bate recorde no porto de Paranagu\u00e1; veja not\u00edcias desta quinta"},"content":{"rendered":"<ul>\n<li>Boi: arroba tem acomoda\u00e7\u00e3o no mercado f\u00edsico e no futuro<\/li>\n<li>Milho: bushel fecha acima de US$ 6 em Chicago<\/li>\n<li>Soja: saca renova recorde no indicador do Cepea para o porto de Paranagu\u00e1 (PR)<\/li>\n<li>Caf\u00e9: ar\u00e1bica tenta atingir nova m\u00e1xima hist\u00f3rica<\/li>\n<li>No exterior: reuni\u00e3o do Banco Central Europeu \u00e9 destaque na agenda<\/li>\n<li>No Brasil: volta do feriado pode trazer ajuste na bolsa e no d\u00f3lar<\/li>\n<\/ul>\n<p><strong>Agenda:<\/strong><\/p>\n<ul>\n<li>Brasil: pr\u00e9via da sondagem da ind\u00fastria de abril (FGV)<\/li>\n<li>Brasil: dados das lavouras do Rio Grande do Sul (Emater)<\/li>\n<li>EUA: exporta\u00e7\u00f5es semanais de gr\u00e3os (USDA)<\/li>\n<\/ul>\n<h3><strong>Boi: arroba tem acomoda\u00e7\u00e3o no mercado f\u00edsico e no futuro<\/strong><\/h3>\n<p>Ap\u00f3s alguns dias de queda, a arroba do boi gordo tem acomoda\u00e7\u00e3o e cota\u00e7\u00f5es ficam praticamente est\u00e1veis no mercado f\u00edsico e no futuro. O indicador do boi gordo do\u00a0<a href=\"https:\/\/www.cepea.esalq.usp.br\/br\"><strong>Cepea<\/strong><\/a>\u00a0subiu 0,14% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 315,4 para R$ 315,85 por arroba. Sendo assim, no acumulado do ano, o indicador valorizou 18,23%. Em 12 meses, os pre\u00e7os alcan\u00e7aram 60,78% de alta.<\/p>\n<p>No mercado futuro, os contratos do boi gordo negociados na B3 tiveram desempenho misto, em que a ponta mais curta recuou, a parte do meio da curva teve leve valoriza\u00e7\u00e3o e os v\u00e9rtices mais longos tiveram ligeiro recuo. O vencimento para abril passou de R$ 311,8 para R$ 311,1, o para maio foi de R$ 306,8 para R$ 306,95 e o para outubro, de R$ 326,85 para R$ 326,45 por arroba.<\/p>\n<h3><strong>Milho: bushel fecha acima de US$ 6 em Chicago<\/strong><\/h3>\n<p>Os contratos futuros do milho negociados em Chicago tiveram o terceiro dia consecutivo de altas expressivas e fecharam acima de US$ 6 por bushel pela primeira vez em 2021, considerando o vencimento para julho. O contrato com vencimento para julho subiu 2,43% e passou de US$ 5,92 para US$ 6,064 por bushel.<\/p>\n<p>A produtividade da segunda safra brasileira segue sendo a principal preocupa\u00e7\u00e3o do mercado de milho mundial em virtude da falta de chuvas. A consultoria IHS Markit diminuiu sua proje\u00e7\u00e3o para a safrinha em 5,5 milh\u00f5es de toneladas para um total de 79,45 milh\u00f5es de toneladas.<\/p>\n<h3><strong>Soja: saca renova recorde no indicador do Cepea para o porto de Paranagu\u00e1 (PR)<\/strong><\/h3>\n<p>O indicador da soja do Cepea, calculado com base nos pre\u00e7os praticados no porto de Paranagu\u00e1 (PR), subiu pelo terceiro dia consecutivo e renovou o recorde hist\u00f3rico da s\u00e9rie. A cota\u00e7\u00e3o variou 0,4% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 178,61 para R$ 179,32 por saca. Desse modo, no acumulado do ano, o indicador teve uma alta de 16,52%, e em 12 meses, os pre\u00e7os alcan\u00e7aram 76,76% de valoriza\u00e7\u00e3o.<\/p>\n<p>Em Chicago, os contratos futuros da soja tiveram valoriza\u00e7\u00e3o pelo s\u00e9timo dia seguido e registraram novas m\u00e1ximas para o ano. O contrato com vencimento para julho, o mais negociado atualmente, valorizou 1,5% e passou de US$ 14,576 para US$ 14,794 por bushel.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.canalrural.com.br\/noticias\/pecuaria\/boi\/abate-femeas-mato-grosso-trimestre\/\"><strong>Bovinos: abate de f\u00eameas em MT despenca 26% no primeiro trimestre<\/strong><\/a><\/li>\n<\/ul>\n<h3><strong>Caf\u00e9: ar\u00e1bica tenta atingir nova m\u00e1xima hist\u00f3rica<\/strong><\/h3>\n<p>O caf\u00e9 ar\u00e1bica segue em recupera\u00e7\u00e3o no mercado brasileiro ap\u00f3s as quedas observadas na segunda quinzena de mar\u00e7o. O indicador do caf\u00e9 ar\u00e1bica do Cepea se valorizou e est\u00e1 pr\u00f3ximo de renovar a m\u00e1xima hist\u00f3rica da s\u00e9rie, atualmente em R$ 748,80 por saca. A cota\u00e7\u00e3o variou 0,93% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 736,3 para R$ 743,12 por saca.<\/p>\n<p>Em Nova York, a cota\u00e7\u00e3o dos contratos futuros do ar\u00e1bica segue buscando o n\u00edvel de US$ 1,40 por libra-peso registrado em 25 de fevereiro. O contrato com vencimento para julho, o mais l\u00edquido no momento, teve baixa de 0,19% e passou de US$ 1,3445 para US$ 1,342 por libra-peso.<\/p>\n<h3><strong>No exterior: reuni\u00e3o do Banco Central Europeu \u00e9 destaque na agenda<\/strong><\/h3>\n<p>A agenda econ\u00f4mica tem como destaque a reuni\u00e3o do Banco Central Europeu (BCE). A expectativa dos investidores \u00e9 que o BCE n\u00e3o altere as diretrizes atuais da pol\u00edtica monet\u00e1ria, mas que inicie a sinaliza\u00e7\u00e3o sobre a retirada das medidas de est\u00edmulo no futuro. O mercado espera que, caso a vacina\u00e7\u00e3o ganhe ritmo na Uni\u00e3o Europeia, a recupera\u00e7\u00e3o econ\u00f4mica faria com que as medidas de est\u00edmulo fossem revertidas.<\/p>\n<p>Em comunica\u00e7\u00f5es recentes, a presidente do BCE, Christine Lagarde, tem indicado que projeta melhora da economia na regi\u00e3o no segundo semestre. Na agenda dos Estados Unidos, o destaque \u00e9 a divulga\u00e7\u00e3o dos dados semanais de pedidos de seguro desemprego. Na semana passada, o resultado bem melhor que o projetado pelo mercado trouxe novas altas para o mercado acion\u00e1rio norte-americano.<\/p>\n<h3><strong>No Brasil: volta do feriado pode trazer ajuste na bolsa e no d\u00f3lar<\/strong><\/h3>\n<p>Com os mercados fechados no Brasil nesta quarta-feira, 21, em virtude do feriado de Tiradentes, a expectativa \u00e9 que hoje o Ibovespa e o d\u00f3lar se ajustem ao movimento de ontem no exterior. O dia foi marcado por uma interrup\u00e7\u00e3o do ligeiro pessimismo que marcou os mercados nos \u00faltimos dois dias. Com isso, as bolsas europeias e norte-americanas tiveram alta e o d\u00f3lar recuou em rela\u00e7\u00e3o aos principais pares e moedas emergentes.<\/p>\n<p>Dessa forma, caso o cen\u00e1rio pol\u00edtico n\u00e3o prejudique o desempenho dos ativos brasileiros, a expectativa \u00e9 de que d\u00f3lar e bolsa apresentem melhora na abertura dos neg\u00f3cios. Com a agenda econ\u00f4mica esvaziada nesta semana, o notici\u00e1rio pol\u00edtico \u00e9 acompanhado ainda mais de perto pelos investidores.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boi: arroba tem acomoda\u00e7\u00e3o no mercado f\u00edsico e no futuro Milho: bushel fecha acima de &hellip;<\/p>\n","protected":false},"author":4,"featured_media":36446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-36445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"A cota\u00e7\u00e3o do caf\u00e9 voltou a se aproximar os maiores patamares hist\u00f3ricos e o boi gordo tamb\u00e9m apresentou recupera\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=36445"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36445\/revisions"}],"predecessor-version":[{"id":36447,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36445\/revisions\/36447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/36446"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=36445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=36445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=36445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}