{"id":36772,"date":"2021-04-27T15:06:42","date_gmt":"2021-04-27T19:06:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=36772"},"modified":"2021-04-27T15:06:42","modified_gmt":"2021-04-27T19:06:42","slug":"governador-afirma-que-parceria-com-exercito-ajudou-a-reduzir-desmatamento-ilegal","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governador-afirma-que-parceria-com-exercito-ajudou-a-reduzir-desmatamento-ilegal\/","title":{"rendered":"Governador afirma que parceria com Ex\u00e9rcito ajudou a reduzir desmatamento ilegal"},"content":{"rendered":"<p>O governador Mauro Mendes afirmou que a Opera\u00e7\u00e3o Verde Brasil 2, fruto de parceria entre o Ex\u00e9rcito e o Governo de Mato Grosso, colaborou para que o Estado conseguisse reduzir o desmatamento ilegal.<\/p>\n<p>Mauro Mendes participou da cerim\u00f4nia de transi\u00e7\u00e3o da opera\u00e7\u00e3o para o Plano Amaz\u00f4nia 2021-2022, na manh\u00e3 desta ter\u00e7a-feira (27.04) na 13\u00aa Brigada de Infantaria Motorizada do Ex\u00e9rcito Brasileiro, junto com o general Soares, que chefia o Comando Militar do Oeste.<\/p>\n<p>\u201cQuero registrar meu agradecimento ao Ex\u00e9rcito brasileiro, na pessoa do general Soares, muito obrigado pelo trabalho e por toda a dedica\u00e7\u00e3o que o Ex\u00e9rcito Brasileiro demonstrou durante a Opera\u00e7\u00e3o Verde Brasil 2, que termina coroada por muitos resultados positivos. Tivemos que autuar muita gente, apreender muitas m\u00e1quinas, e fazer muitas a\u00e7\u00f5es que lamentavelmente ocorreram porque pessoas ainda insistem em n\u00e3o respeitar a legisla\u00e7\u00e3o e o que diz o C\u00f3digo Florestal Brasileiro\u201d, afirmou Mauro.<\/p>\n<p>Conforme o governador, de agosto de 2020 a janeiro deste ano, os alertas de desmatamento em Mato Grosso reduziram 31,5%, a maior m\u00e9dia entre os estados da regi\u00e3o amaz\u00f4nica. Em 2021, somente o Estado est\u00e1 investindo R$ 73 milh\u00f5es em a\u00e7\u00f5es de preven\u00e7\u00e3o e combate ao desmatamento ilegal e inc\u00eandios florestais.<\/p>\n<p>\u201cJ\u00e1 mobilizamos recursos para aquisi\u00e7\u00e3o de equipamentos, como mais um helic\u00f3ptero, e todo esse esfor\u00e7o \u00e9 para preservar o meio ambiente e, acima de tudo, preservar a legalidade. Temos que cada vez mais atuar para preservar. A lei precisa ser respeitada\u201d, pontuou.<\/p>\n<p>O general Soares destacou que entre os resultados positivos da Opera\u00e7\u00e3o Verde Brasil 2, est\u00e3o a apreens\u00e3o de 151 m\u00b2 de madeira, 15 mil focos de inc\u00eandio combatidos e R$ 2,5 bilh\u00f5es em multas aplicadas.<\/p>\n<p>\u201cFoi uma satisfa\u00e7\u00e3o trabalhar junto com todos. Nesse tipo de opera\u00e7\u00e3o, n\u00f3s n\u00e3o somos os protagonistas, mas atuamos para ajudar os \u00f3rg\u00e3os de fiscaliza\u00e7\u00e3o ambiental e as pol\u00edcias. Fizemos todo o poss\u00edvel na medida das nossas possibilidades.<\/p>\n<p><a href=\"https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2021\/04\/3-41.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36774 size-large\" src=\"https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2021\/04\/3-41-1024x683.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2021\/04\/3-41.jpg 1024w, https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2021\/04\/3-41-300x200.jpg 300w, https:\/\/www.cfnews.com.br\/portal\/wp-content\/uploads\/2021\/04\/3-41-768x512.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><img decoding=\"async\" src=\"http:\/\/www.mt.gov.br\/documents\/21013\/16730278\/962A8092.jpg\" alt=\"\" \/><\/p>\n<p>O secret\u00e1rio-adjunto Executivo de Meio Ambiente do Estado, Alex Marega, frisou que o Governo de Mato Grosso vai continuar a atuar com rigor dentro do que \u00e9 previsto no Plano de A\u00e7\u00e3o para o Combate ao Desmatamento e aos Inc\u00eandios Florestais.<\/p>\n<p>\u201cO Estado n\u00e3o vai parar. N\u00f3s conseguimos em 2019 aplicar o dobro da m\u00e9dia hist\u00f3rica e em 2020 quintuplicamos as nossas a\u00e7\u00f5es, com 1,5 bilh\u00e3o em multas somente por parte do estado, com a responsabiliza\u00e7\u00e3o dos infratores ambientais. E muito disso devido a essas parcerias\u201d, destacou.<\/p>\n<p>O secret\u00e1rio de Estado de Seguran\u00e7a P\u00fablica ressaltou o trabalho conjunto entre todas as institui\u00e7\u00f5es e \u00f3rg\u00e3os que atuaram na opera\u00e7\u00e3o: Ex\u00e9rcito, For\u00e7a Nacional, Ibama, Abin, PF, PRF, ICMBio, Censipam, Sema, Sesp, Ciopaer, Bombeiros, Pol\u00edcia Militar e Pol\u00edcia Civil.<\/p>\n<p>\u201cEssa parceria com o Ex\u00e9rcito demonstra que quanto mais integradas as for\u00e7as federais e estaduais, a gente alcan\u00e7a maior redu\u00e7\u00e3o de desmatamento. Essa integra\u00e7\u00e3o n\u00e3o faz com o que o trabalho fique mais f\u00e1cil, mas que fique mais leve. Com uma \u00fanica coordena\u00e7\u00e3o do Ex\u00e9rcito e do Estado n\u00f3s conseguimos alcan\u00e7ar esses resultados da Opera\u00e7\u00e3o Verde Brasil 1 e 2, al\u00e9m das opera\u00e7\u00f5es estaduais\u201d, declarou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Foto:\u00a0 Tch\u00e9lo Figueiredo\u00a0 \u00a0\u00a0|\u00a0 \u00a0 Fonte:\u00a0 MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes afirmou que a Opera\u00e7\u00e3o Verde Brasil 2, fruto de parceria entre &hellip;<\/p>\n","protected":false},"author":4,"featured_media":36773,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-36772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=36772"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36772\/revisions"}],"predecessor-version":[{"id":36775,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/36772\/revisions\/36775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/36773"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=36772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=36772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=36772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}