{"id":37107,"date":"2021-05-02T09:20:43","date_gmt":"2021-05-02T13:20:43","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=37107"},"modified":"2021-05-02T09:20:43","modified_gmt":"2021-05-02T13:20:43","slug":"secar-e-armazenar-graos-para-racao-aumenta-rentabilidade-diz-emater","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/secar-e-armazenar-graos-para-racao-aumenta-rentabilidade-diz-emater\/","title":{"rendered":"Secar e armazenar gr\u00e3os para ra\u00e7\u00e3o aumenta rentabilidade, diz Emater"},"content":{"rendered":"<p>Na regi\u00e3o de Santa Rosa (RS), produtores tem adotado uma nova estrat\u00e9gia para secagem e armazenamento de gr\u00e3os atrav\u00e9s de um projeto elaborado pela\u00a0<a href=\"http:\/\/www.emater.tche.br\/site\/\"><strong>Emater\/RS-Ascar<\/strong><\/a>. O projeto buscar dar maior autonomia para os produtores e melhor controle na manuten\u00e7\u00e3o da qualidade dos gr\u00e3os e ainda contemplar a necessidade e a realidade de cada propriedade, desde pequenas unidades, com baixo custo, at\u00e9 estruturas completas, automatizadas.<\/p>\n<p>Um dos projetos rec\u00e9m implantados foi na propriedade de Jo\u00e3o Eduardo Wille, no munic\u00edpio de Linha Pitanga. Foram constru\u00eddos dois silos com capacidade para armazenar duas mil sacas de milho, cujos gr\u00e3os s\u00e3o destinados para ra\u00e7\u00e3o do gado de leite, o que favorece para um menor custo de produ\u00e7\u00e3o e maior qualidade na dieta fornecida. Junto aos silos secadores, foi constru\u00eddo uma f\u00e1brica de ra\u00e7\u00e3o, que por sua vez j\u00e1 tritura e mistura os insumos automaticamente, reduzindo a necessidade de m\u00e3o de obra.<\/p>\n<p>O produtor possui 120 vacas (99 vacas em lacta\u00e7\u00e3o e 21 secas) e 45 novilhas e terneiras, sendo produzidos em m\u00e9dia 78.250 litros de leite por m\u00eas. Na propriedade trabalham tr\u00eas membros da fam\u00edlia e mais tr\u00eas colaboradores, uma vez que al\u00e9m do leite s\u00e3o terminados 1.700 su\u00ednos por lote e produzidos milho silagem, milho gr\u00e3o, feno e pastagens. O produtor ainda ressalta que ap\u00f3s implantar o sistema, obteve uma redu\u00e7\u00e3o do custo da ra\u00e7\u00e3o, que \u00e9 produzida e aproveitada na propriedade, al\u00e9m de ter maior autonomia e facilidade no trabalho.<\/p>\n<p>Para a instala\u00e7\u00e3o dos silos e da f\u00e1brica de ra\u00e7\u00e3o, foram investidos aproximadamente R$ 270 mil, dos quais 165 mil foram financiados pelo Programa Nacional de Fortalecimento da Agricultura Familiar (Pronaf), com juros de 2,75% a 4% ao ano. O restante \u00e9 oriundo de recursos pr\u00f3prios.<\/p>\n<p>O extensionista da Emater\/RS-Ascar Elir Paulo Pasquetti, tamb\u00e9m destaca a aplica\u00e7\u00e3o do projeto na cidade de Nova Candel\u00e1ria, pois j\u00e1 foram constru\u00eddos 14 silos secadores e armazenadores de alvenaria com capacidade de secar e armazenar 11.800 sacas, o que corresponde \u00e0 produ\u00e7\u00e3o de aproximadamente 98 hectares de milho, que est\u00e1 sendo estocada nas propriedades. Ele ainda ressalta que a secagem e a armazenagem dentro da propriedade reduzem custos com transporte, taxas de limpeza e secagem. Al\u00e9m disso, contribui para um milho de excelente qualidade a um custo menor ao produtor, possibilitando uma maior renda na produ\u00e7\u00e3o do leite.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na regi\u00e3o de Santa Rosa (RS), produtores tem adotado uma nova estrat\u00e9gia para secagem e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":37108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-37107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"A secagem e a armazenagem dentro da propriedade reduz custos com transporte e taxas de limpeza e ainda garante a qualidade dos gr\u00e3os","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=37107"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37107\/revisions"}],"predecessor-version":[{"id":37109,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37107\/revisions\/37109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/37108"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=37107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=37107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=37107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}