{"id":37805,"date":"2021-05-11T15:54:29","date_gmt":"2021-05-11T19:54:29","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=37805"},"modified":"2021-05-11T15:54:29","modified_gmt":"2021-05-11T19:54:29","slug":"soja-na-vespera-do-usda-chicago-fecha-no-maior-patamar-desde-2012","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/soja-na-vespera-do-usda-chicago-fecha-no-maior-patamar-desde-2012\/","title":{"rendered":"Soja: na v\u00e9spera do USDA, Chicago fecha no maior patamar desde 2012"},"content":{"rendered":"<p>Os contratos futuros da soja negociados na Bolsa de Mercadorias de Chicago (CBOT) fecharam a ter\u00e7a-feira com pre\u00e7os em alta. Na v\u00e9spera do relat\u00f3rio de maio do\u00a0<a href=\"https:\/\/www.usda.gov\/\"><strong>Departamento de Agricultura dos Estados Unidos<\/strong><\/a>, o cen\u00e1rio fundamental deflagrou um movimento de compras por parte de fundos e especuladores, colocando a posi\u00e7\u00e3o julho no melhor n\u00edvel desde setembro de 2021.<\/p>\n<p>O mercado aposta que os dados do USDA v\u00e3o apontar a manuten\u00e7\u00e3o do aperto nos estoques globais da oleaginosa at\u00e9 2022.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.canalrural.com.br\/projeto-soja-brasil\/noticia\/soja-dispara-em-chicago-e-passa-de-us-1625-pela-1a-vez-em-9-anos\/\"><strong>Soja dispara em Chicago e passa de US$ 16,25 pela 1\u00aa vez em 9 anos<\/strong><\/a><\/li>\n<\/ul>\n<p>O Departamento vai divulgar as suas primeiras estimativas de oferta e demanda de soja americana para a temporada 2021\/22. O mercado aposta em n\u00fameros de produ\u00e7\u00e3o e estoques acima dos obtidos em 2020\/21. O relat\u00f3rio de maio do Departamento ser\u00e1 divulgado nesta quarta, 12, \u00e0s 13h.<\/p>\n<p>Analistas consultados pelas ag\u00eancias internacionais apostam em produ\u00e7\u00e3o de 4,441 bilh\u00f5es de bushels em 2021\/22, superando a safra 2020\/21, que est\u00e1 estimada em 4,135 bilh\u00f5es de bushels. Para os estoques, a previs\u00e3o \u00e9 de eleva\u00e7\u00e3o, passando de 120 milh\u00f5es previstos em abril para 2020\/21 para 132 milh\u00f5es de bushels na nova temporada. O n\u00famero para a temporada 20\/21 pode ser cortado para 118 milh\u00f5es, segundo avalia\u00e7\u00e3o do mercado.<\/p>\n<p>Em rela\u00e7\u00e3o ao quadro de oferta e demanda mundial da soja, o mercado aposta em estoques finais 2021\/22 de 88,8 milh\u00f5es de toneladas, superando as 86,9 milh\u00f5es de toneladas indicadas para 2020\/21. Esse \u00faltimo n\u00famero n\u00e3o dever\u00e1 ser modificado no pr\u00f3ximo levantamento.<\/p>\n<p>A produ\u00e7\u00e3o brasileira de soja em 2020\/21 dever\u00e1 ter sua estimativa elevada de 136 milh\u00f5es para 136,1 milh\u00f5es de toneladas. A safra argentina pode ter corte, passando de 47,5 milh\u00f5es para 46,7 milh\u00f5es de toneladas. Ontem, o USDA divulgou relat\u00f3rio sobre a evolu\u00e7\u00e3o de plantio das lavouras de soja. At\u00e9 9 de maio, a \u00e1rea plantada estava apontada em 42%. O mercado esperava o n\u00famero em 40%. Na semana passada, o n\u00famero estava em 24%.<\/p>\n<p>Em igual per\u00edodo do ano passado, a semeadura era de 36%. A m\u00e9dia \u00e9 de 22%. Apesar da boa evolu\u00e7\u00e3o do plantio, as condi\u00e7\u00f5es clim\u00e1ticas preocupam, principalmente em fun\u00e7\u00e3o do adiamento na fase de emerg\u00eancia, o que pode prejudicar o potencial produtivo.<\/p>\n<p>Os contratos da soja em gr\u00e3o com entrega em julho fecharam com alta de 27,25 centavos de d\u00f3lar por libra-peso ou 1,71% a US$ 16,14 3\/4 por bushel. A posi\u00e7\u00e3o agosto teve cota\u00e7\u00e3o de US$ 15,53 por bushel, com ganho de 24,75 centavos ou 1,61%.<\/p>\n<p>Nos subprodutos, a posi\u00e7\u00e3o julho do farelo subiu US$ 4,70 ou 1,06% a US$ 447,00 por tonelada. No \u00f3leo, os contratos com vencimento em julho fecharam a 64,80 centavos de d\u00f3lar, ganho de 0,96 centavo ou 1,5%.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os contratos futuros da soja negociados na Bolsa de Mercadorias de Chicago (CBOT) fecharam a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":37806,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-37805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"O mercado aposta que os dados do USDA v\u00e3o apontar a manuten\u00e7\u00e3o do aperto nos estoques globais da oleaginosa at\u00e9 2022","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=37805"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37805\/revisions"}],"predecessor-version":[{"id":37807,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37805\/revisions\/37807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/37806"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=37805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=37805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=37805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}