{"id":37838,"date":"2021-05-12T09:24:41","date_gmt":"2021-05-12T13:24:41","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=37838"},"modified":"2021-05-12T09:24:41","modified_gmt":"2021-05-12T13:24:41","slug":"com-quebra-no-milho-conab-reduz-estimativa-da-safra-de-graos-em-2-mi-de-toneladas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/com-quebra-no-milho-conab-reduz-estimativa-da-safra-de-graos-em-2-mi-de-toneladas\/","title":{"rendered":"Com quebra no milho, Conab reduz estimativa da safra de gr\u00e3os em 2 mi de toneladas"},"content":{"rendered":"<p>A produ\u00e7\u00e3o nacional de gr\u00e3os est\u00e1 estimada em 271,7 milh\u00f5es de toneladas, aumento de 5,7% ou 14,7 milh\u00f5es de toneladas superior ao produzido em 2019\/2020. No \u00faltimo levantamento, a companhia estimava um volume em 273,8 milh\u00f5es de toneladas. Os dados fazem parte do 8\u00ba levantamento da safra 2020\/2021 de gr\u00e3os, divulgado nesta quarta-feira, 12, pela\u00a0<a href=\"https:\/\/www.conab.gov.br\/\"><strong>Companhia Nacional de Abastecimento (Conab).<\/strong><\/a><\/p>\n<p>A posi\u00e7\u00e3o hist\u00f3rica deve-se \u00e0 produ\u00e7\u00e3o recorde da soja e aumento estimado do milho total.\u00a0\u00a0A situa\u00e7\u00e3o das culturas de primeira safra, com exce\u00e7\u00e3o do milho e arroz, est\u00e3o no encerramento da colheita. Para as de segunda safra, caso do feij\u00e3o, predominam os est\u00e1dios de flora\u00e7\u00e3o e enchimento de gr\u00e3os.<\/p>\n<p>J\u00e1 quanto ao milho segunda safra, em face do atraso na semeadura, mas com um percentual significativo de desenvolvimento vegetativo e flora\u00e7\u00e3o, a cultura depender\u00e1 das condi\u00e7\u00f5es clim\u00e1ticas. J\u00e1 no caso das culturas de inverno, o plantio se intensifica este m\u00eas, mas depender\u00e1 do volume das precipita\u00e7\u00f5es.<\/p>\n<div id=\"supertag-ad-q84b18dpt\" data-google-query-id=\"CNuKj9eexPACFYomuQYdAY0AOg\">\n<div id=\"google_ads_iframe_\/21692678505\/Canal_Rural_Display\/BALCAO_RURAL_DESK_0__container__\"><\/div>\n<\/div>\n<p>Mesmo com um volume ainda recorde, em compara\u00e7\u00e3o com a estimativa do m\u00eas passado, nota-se uma redu\u00e7\u00e3o de 2,1 milh\u00f5es de toneladas. A redu\u00e7\u00e3o deve-se, sobretudo, ao retardamento da colheita da soja e, como consequ\u00eancia, o plantio de grande parte da \u00e1rea do milho segunda safra fora da janela ideal, aliado \u00e0 baixa ocorr\u00eancia de chuvas. Portanto, j\u00e1 h\u00e1 redu\u00e7\u00e3o na produtividade esperada do cereal.<\/p>\n<h3><strong>\u00c1rea\u00a0<\/strong><\/h3>\n<p><strong>A previs\u00e3o para \u00e1rea plantada \u00e9 de crescimento de 4,1% ou 2,7 milh\u00f5es de hectares<\/strong>, alcan\u00e7ando 68,6 milh\u00f5es de hectares. Os destaques s\u00e3o\u00a0 para a soja, com aumento de 4,2% ou 1,6 milh\u00e3o de hectares, e para o milho segunda safra com ganho de 8,8%, correspondendo a 1,2 milh\u00e3o de hectares.<\/p>\n<p><strong>Para o milho<\/strong>, cuja produ\u00e7\u00e3o total est\u00e1 estimada em 106,4 milh\u00f5es de toneladas, o crescimento \u00e9 de 3,7% sobre a produ\u00e7\u00e3o de 2019\/20. S\u00e3o produzidas 24,7 milh\u00f5es de toneladas na primeira safra, com previs\u00e3o de 79,8 milh\u00f5es na segunda safra e 1,9 milh\u00e3o na terceira safra.<\/p>\n<p>A soja mant\u00e9m o seu destaque, com uma\u00a0 produ\u00e7\u00e3o recorde estimada em 135,4 milh\u00f5es de toneladas, 8,5% ou 10,6 milh\u00f5es de toneladas superior \u00e0 da safra 2019\/20. O Brasil assegura o t\u00edtulo de maior produtor mundial da leguminosa.<\/p>\n<h3><strong>Milho<\/strong><\/h3>\n<p>As incertezas relacionadas ao clima ir\u00e3o nortear as informa\u00e7\u00f5es e a conjuntura para o cereal, particularmente em maio, per\u00edodo decisivo para a defini\u00e7\u00e3o da segunda e\u00a0<strong>mais importante safra brasileira de milho<\/strong>, podendo estabelecer novas perspectivas para a produ\u00e7\u00e3o brasileira na temporada 2020\/2021.<\/p>\n<p><strong>A colheita do milho ver\u00e3o<\/strong>, com as suas caracter\u00edsticas de poder postergar, para dar espa\u00e7o para outras lavouras, particularmente na concorr\u00eancia com a soja, avan\u00e7a para o seu t\u00e9rmino nas principais regi\u00f5es produtoras.<\/p>\n<p>Os dados relacionados \u00e0 terceira safra do cereal, cuja semeadura ter\u00e1 in\u00edcio a partir deste m\u00eas, receber\u00e3o os est\u00edmulos tanto dos pre\u00e7os praticados atualmente quanto pela expectativa de normaliza\u00e7\u00e3o clim\u00e1tica, nas regi\u00f5es onde o plantio ser\u00e1 exercido.<\/p>\n<p>Na consolida\u00e7\u00e3o das tr\u00eas safras, o cen\u00e1rio atual aponta para uma produ\u00e7\u00e3o de 106.413,5 mil toneladas de milho, representando um incremento de 3,7% em rela\u00e7\u00e3o ao alcan\u00e7ado na safra passada.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A produ\u00e7\u00e3o nacional de gr\u00e3os est\u00e1 estimada em 271,7 milh\u00f5es de toneladas, aumento de 5,7% &hellip;<\/p>\n","protected":false},"author":4,"featured_media":37839,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-37838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Por conta da seca em regi\u00f5es produtoras, a perspectiva para a produ\u00e7\u00e3o do cereal recuou de 109 milh\u00f5es de toneladas para 106,4 milh\u00f5es de toneladas","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=37838"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37838\/revisions"}],"predecessor-version":[{"id":37840,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/37838\/revisions\/37840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/37839"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=37838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=37838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=37838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}