{"id":38641,"date":"2021-05-24T09:57:08","date_gmt":"2021-05-24T13:57:08","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=38641"},"modified":"2021-05-24T09:57:08","modified_gmt":"2021-05-24T13:57:08","slug":"boi-gordo-se-recupera-e-volta-a-r-310-veja-noticias-desta-segunda","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/boi-gordo-se-recupera-e-volta-a-r-310-veja-noticias-desta-segunda\/","title":{"rendered":"Boi gordo se recupera e volta a R$ 310; veja not\u00edcias desta segunda"},"content":{"rendered":"<ul>\n<li>Boi: arroba segue mostrando recupera\u00e7\u00e3o<\/li>\n<li>Milho: pre\u00e7os ficam est\u00e1veis no f\u00edsico, mas recuam fortemente no futuro<\/li>\n<li>Soja: Chicago alcan\u00e7a quarto dia consecutivo de queda<\/li>\n<li>Caf\u00e9: indicador do Cepea tem leve alta seguindo c\u00e2mbio<\/li>\n<li>No exterior: dados de atividade econ\u00f4mica s\u00e3o destaques da semana nos EUA<\/li>\n<li>No Brasil: d\u00f3lar tem segunda alta semanal consecutiva<\/li>\n<\/ul>\n<p><strong>Agenda:<\/strong><\/p>\n<ul>\n<li>Brasil: relat\u00f3rio Focus (Banco Central)<\/li>\n<li>Brasil: balan\u00e7a comercial das tr\u00eas primeiras semanas de maio<\/li>\n<li>EUA: inspe\u00e7\u00f5es de exporta\u00e7\u00e3o semanal (USDA)<\/li>\n<\/ul>\n<h3><strong>Boi: arroba segue mostrando recupera\u00e7\u00e3o<\/strong><\/h3>\n<p>O indicador do boi gordo do\u00a0<a href=\"https:\/\/www.cepea.esalq.usp.br\/br\"><strong>Cepea<\/strong><\/a>\u00a0teve um dia de alta dos pre\u00e7os e voltou a ficar acima de R$ 310 por arroba. A cota\u00e7\u00e3o variou 2,28% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 305,45 para R$ 312,4 por arroba. Sendo assim, no acumulado do ano, o indicador valorizou 16,94%, e em 12 meses, os pre\u00e7os alcan\u00e7aram 54,65% de alta.<\/p>\n<p>Na B3, os contratos futuros do boi gordo encerraram a semana em baixa na compara\u00e7\u00e3o di\u00e1ria, por\u00e9m, tiveram boa recupera\u00e7\u00e3o nos dias anteriores. O vencimento para maio passou de R$ 313,20 para R$ 311,50, o para junho foi de R$ 325,65 para R$ 322,75 e o para outubro passou de R$ 344,85 para R$ 342,55 por arroba.<\/p>\n<h3><strong>Milho: pre\u00e7os ficam est\u00e1veis no f\u00edsico, mas recuam fortemente no futuro<\/strong><\/h3>\n<p>De acordo com a consultoria Safras &amp; Mercado, o mercado brasileiro de milho teve pre\u00e7os est\u00e1veis ap\u00f3s uma s\u00e9rie de quedas. Apesar disso, o analista Fernando Iglesias apontou que houve novo aumento do volume ofertado. Em Cascavel (PR), a cota\u00e7\u00e3o ficou em R$ 95\/97, e em Campinas (SP), em R$ 102\/103 por saca.<\/p>\n<p>Na B3, por outro lado, a s\u00e9rie de recuos segue firme e at\u00e9 teve aumento de intensidade no encerramento da semana. O vencimento para julho passou de R$ 97,19 para R$ 94,96, o para setembro foi de R$ 95,91 para R$ 93,85, e o para mar\u00e7o de 2022, de R$ 96,95 para R$ 94,63 por saca.<\/p>\n<h3><strong>Soja: Chicago alcan\u00e7a quarto dia consecutivo de queda<\/strong><\/h3>\n<p>As cota\u00e7\u00f5es dos contratos futuros da soja negociados em Chicago alcan\u00e7aram o quarto dia consecutivo de queda em virtude da melhora das proje\u00e7\u00f5es de chuvas em regi\u00f5es produtoras nos Estados Unidos. Nesse per\u00edodo, o recuo acumulado chegou a quase 4%. Na passagem de dia, o vencimento para julho caiu 0,46% e passou de US$ 15,332 para US$ 15,262 por bushel.<\/p>\n<p>No Brasil, o indicador da soja do Cepea, calculado com base nos pre\u00e7os praticados no porto de Paranagu\u00e1 (PR), teve um dia de pre\u00e7os mais baixos mesmo com a alta do d\u00f3lar em rela\u00e7\u00e3o ao real. A cota\u00e7\u00e3o variou -0,52% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 173,91 para R$ 173,01 por saca. Desse modo, no acumulado do ano, o indicador teve uma alta de 12,42%.<\/p>\n<h3><strong>Caf\u00e9: indicador do Cepea tem leve alta seguindo c\u00e2mbio<\/strong><\/h3>\n<p>O indicador do caf\u00e9 ar\u00e1bica do Cepea teve um dia de leve alta dos pre\u00e7os e seguiu o movimento do c\u00e2mbio. A cota\u00e7\u00e3o variou 0,28% em rela\u00e7\u00e3o ao dia anterior e passou de R$ 823,23 para R$ 825,55 por saca. Dessa forma, no acumulado do ano, o indicador valorizou 36,07%. Em 12 meses, os pre\u00e7os alcan\u00e7aram 43,52% de alta.<\/p>\n<p>Em Nova York, por outro lado, os contratos futuros do caf\u00e9 ar\u00e1bica tiveram um dia de pre\u00e7os mais baixos, mas ainda conseguiram se manter acima de US$ 1,50 por libra-peso. O vencimento para julho ensaiou novamente uma recupera\u00e7\u00e3o durante o preg\u00e3o, mas fechou em baixa de 0,56%, cotado a US$ 1,501 por libra-peso.<\/p>\n<h3><strong>No exterior: dados de atividade econ\u00f4mica s\u00e3o destaques da semana nos EUA<\/strong><\/h3>\n<p>Ainda com a infla\u00e7\u00e3o global no radar, nesta semana, os investidores focam em dados de atividade econ\u00f4mica nos Estados Unidos. Os destaques ser\u00e3o a segunda leitura do PIB do primeiro trimestre e a confian\u00e7a do consumidor de maio. Na sexta-feira, 28, os indicadores de renda e gastos pessoais de abril ser\u00e3o acompanhados da divulga\u00e7\u00e3o do PCE, um importante \u00edndice de infla\u00e7\u00e3o acompanhado pelo Banco Central dos EUA (Fed).<\/p>\n<p>Na Zona do Euro, a agenda econ\u00f4mica est\u00e1 mais esvaziada e tem apenas indicadores de confian\u00e7a dos consumidores e das empresas. Dessa forma, o mercado seguir\u00e1 avaliando a recupera\u00e7\u00e3o econ\u00f4mica nos Estados Unidos e na Europa para projetar a capacidade dos Banco Centrais de manter as pol\u00edticas de est\u00edmulos monet\u00e1rios.<\/p>\n<h3><strong>No Brasil: d\u00f3lar tem segunda alta semanal consecutiva<\/strong><\/h3>\n<p>Ap\u00f3s uma sequ\u00eancia de cinco baixas semanais, o d\u00f3lar encerrou a segunda semana consecutiva em alta em rela\u00e7\u00e3o ao real. A moeda norte-americana subiu 1,56% e passou de R$ 5,271 para R$ 5,353 entre a segunda e a terceira semana de maio. O avan\u00e7o do d\u00f3lar no exterior em virtude de apreens\u00e3o dos investidores com a possibilidade de o Fed discutir a redu\u00e7\u00e3o de est\u00edmulos monet\u00e1rios foi o principal fator a explicar o movimento do c\u00e2mbio.<\/p>\n<p>A agenda econ\u00f4mica desta semana tem como destaques pelo lado da infla\u00e7\u00e3o o IGP-M e o IPCA-15 de maio. Al\u00e9m disso, ser\u00e3o divulgadas as cria\u00e7\u00f5es de vagas formais de emprego pelo Caged de abril. Por fim, o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) divulga a taxa de desemprego apurada pela PNAD Cont\u00ednua mensal de mar\u00e7o.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boi: arroba segue mostrando recupera\u00e7\u00e3o Milho: pre\u00e7os ficam est\u00e1veis no f\u00edsico, mas recuam fortemente no &hellip;<\/p>\n","protected":false},"author":4,"featured_media":38642,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-38641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Enquanto isso, no mercado f\u00edsico, o milho ficou est\u00e1vel, a soja caiu e o caf\u00e9 subiu","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=38641"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38641\/revisions"}],"predecessor-version":[{"id":38643,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38641\/revisions\/38643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/38642"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=38641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=38641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=38641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}