{"id":38745,"date":"2021-05-25T10:44:43","date_gmt":"2021-05-25T14:44:43","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=38745"},"modified":"2021-05-25T10:44:43","modified_gmt":"2021-05-25T14:44:43","slug":"76-dos-produtores-usam-whatsapp-para-negociar-aponta-pesquisa-da-abmra","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/76-dos-produtores-usam-whatsapp-para-negociar-aponta-pesquisa-da-abmra\/","title":{"rendered":"76% dos produtores usam WhatsApp para negociar, aponta pesquisa da ABMRA"},"content":{"rendered":"<p>Cerca de 76% os produtores rurais brasileiros utilizam o WhatsApp para negociar, e 74% se mant\u00eam atualizados usando a internet. Essas s\u00e3o algumas das conclus\u00f5es da 8\u00aa Pesquisa ABMRA H\u00e1bitos do Produtor Rural, divulgada pela\u00a0<a href=\"https:\/\/abmra.org.br\/\"><strong>Associa\u00e7\u00e3o Brasileira de Marketing Rural e Agroneg\u00f3cio (ABMRA)<\/strong><\/a>, nesta ter\u00e7a-feira, 25.<\/p>\n<p>Previs\u00e3o do tempo e informa\u00e7\u00e3o s\u00e3o os principais conte\u00fados buscados por agricultores e criadores. \u201cNunca o conte\u00fado foi t\u00e3o importante nas m\u00eddias digitais\u201d, aponta a pesquisa. \u201cO Facebook continua sendo importante como rede social, por\u00e9m n\u00e3o para fazer neg\u00f3cios, e o YouTube quase triplicou de import\u00e2ncia em rela\u00e7\u00e3o \u00e0 pesquisa de 2017\u201d, detalha Jorge Espanha, presidente da ABMRA.<\/p>\n<p>O estudo disponibilizado tamb\u00e9m constata o avan\u00e7o das ferramentas de comunica\u00e7\u00e3o no campo: 94% dos produtores t\u00eam smartphone, contra 61% na pesquisa anterior, realizada em 2017. Outro ponto importante \u00e9 a maior oferta de internet no meio rural, dispon\u00edvel para 91% dos produtores de animais e 88% para os agricultores. 57% dos entrevistados usam a rede 15 ou mais vezes por dia.<\/p>\n<h3><strong>Agroneg\u00f3cio na pandemia<\/strong><\/h3>\n<p>A pandemia da Covid-19 causou grandes estragos na economia brasileira. Por\u00e9m, mais uma vez, o agroneg\u00f3cio se mostrou resiliente. De acordo com a pesquisa, 86% dos agricultores e pecuaristas n\u00e3o fizeram qualquer mudan\u00e7a na administra\u00e7\u00e3o de suas propriedades e 78% mant\u00eam os planos de investimentos durante a crise sanit\u00e1ria.<\/p>\n<p>Isso se deve, segundo o estudo, ao menor impacto da pandemia. Para 64% dos entrevistados, os reflexos nos neg\u00f3cios foram pequenos. A pandemia tem impacto m\u00e9dio no campo para 11% dos produtores rurais e alto para 25% deles.<\/p>\n<h3><strong>Participa\u00e7\u00e3o das mulheres<\/strong><\/h3>\n<p>A mulher ganha cada vez mais espa\u00e7o no campo, particularmente em postos de gest\u00e3o e em determinadas atividades produtivas, representando 26% dos cargos de decis\u00e3o e comando. Para 94% dos produtores rurais consultados, a mulher \u00e9 vital ou muito importante no neg\u00f3cio rural.<\/p>\n<p>O Brasil \u00e9 muito grande e tem caracter\u00edsticas regionais pr\u00f3prias, inclusive em termos de perfil da produ\u00e7\u00e3o, o que se reflete no resultado da pesquisa. Um exemplo \u00e9 a mulher no campo, especificamente quanto \u00e0 sua maior ou menor presen\u00e7a em postos de gest\u00e3o ou lideran\u00e7a. No leite, por exemplo, ela participa com 88%; em contrapartida, na soja, com apenas 2%.<\/p>\n<h3><strong>Futuros dos eventos presenciais<\/strong><\/h3>\n<p>A pandemia mudou a realidade dos eventos. Dias de campo, feiras, exposi\u00e7\u00f5es, congressos e outros se tornaram virtuais.<\/p>\n<p>\u201cO produtor rural continua preferindo os eventos t\u00e9cnicos e comerciais, por\u00e9m aguardam com expectativa as edi\u00e7\u00f5es presenciais. A 8\u00aa Pesquisa ABMRA H\u00e1bitos do Produtor Rural identificou que 39% dos agricultores e criadores foram a eventos presenciais antes da pandemia e que 58% deles pretendem ir no futuro. Essa resposta foi praticamente un\u00e2nime: os produtores rurais desejam a volta dos eventos presenciais\u201d, aponta Ricardo Nicodemos.<\/p>\n<h3><strong>Como foi feita a pesquisa?<\/strong><\/h3>\n<p>Segundo a ABMRA, a pesquisa ocorreu presencialmente, seguindo todos os protocolos de sa\u00fade e seguran\u00e7a, e foi realizada entre outubro de 2020 e janeiro de 2021 com 3.048 produtores rurais (homens e mulheres com poder de decis\u00e3o, de propriedades de pequeno, m\u00e9dio e grande portes) de 16 estados de todas as regi\u00f5es do pa\u00eds, abrangendo 14 culturas agr\u00edcolas e quatro atividades animais.<\/p>\n<p>\u201cA 8\u00aa Pesquisa ABMRA H\u00e1bitos do Produtor Rural mostra, com exatid\u00e3o, o que est\u00e1 na mente dos agricultores e criadores neste exato momento em que o Brasil e o mundo ainda s\u00e3o impactados pela pandemia do novo coronav\u00edrus\u201d, destaca Ricardo Nicodemos, vice-presidente da associa\u00e7\u00e3o e coordenador da pesquisa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 76% os produtores rurais brasileiros utilizam o WhatsApp para negociar, e 74% se &hellip;<\/p>\n","protected":false},"author":4,"featured_media":38746,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-38745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Estudo tamb\u00e9m indica crescimento da participa\u00e7\u00e3o das mulheres em cargos importantes e baixo impacto da pandemia no agroneg\u00f3cio","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=38745"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38745\/revisions"}],"predecessor-version":[{"id":38747,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38745\/revisions\/38747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/38746"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=38745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=38745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=38745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}