{"id":38784,"date":"2021-05-25T14:51:12","date_gmt":"2021-05-25T18:51:12","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=38784"},"modified":"2021-05-25T14:51:12","modified_gmt":"2021-05-25T18:51:12","slug":"plano-safra-pode-ser-lancado-sem-financiamentos-com-juros-controlados","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/plano-safra-pode-ser-lancado-sem-financiamentos-com-juros-controlados\/","title":{"rendered":"Plano Safra pode ser lan\u00e7ado sem financiamentos com juros controlados"},"content":{"rendered":"<div class=\"fl-row fl-row-fixed-width fl-row-bg-none fl-node-5e7d7411591dd\" data-node=\"5e7d7411591dd\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"fl-row-content fl-row-fixed-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e7d7411591e3 fl-col-group-equal-height fl-col-group-align-center\" data-node=\"5e7d7411591e3\">\n<div class=\"fl-col fl-node-5e7d7411591e7 fl-col-small\" data-node=\"5e7d7411591e7\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-html fl-node-5e7d7411591ec\" data-node=\"5e7d7411591ec\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-html\">\n<div class=\"info-data-single\">\n<div class=\"autor-single\">Por Canal Rural<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-row fl-row-fixed-width fl-row-bg-none fl-node-5e7d7411591d4\" data-node=\"5e7d7411591d4\">\n<div class=\"fl-row-content-wrap\">\n<div class=\"uabb-row-separator uabb-top-row-separator\"><\/div>\n<div class=\"fl-row-content fl-row-fixed-width fl-node-content\">\n<div class=\"fl-col-group fl-node-5e7d7411591e9\" data-node=\"5e7d7411591e9\">\n<div class=\"fl-col fl-node-5e7d7411591ea\" data-node=\"5e7d7411591ea\">\n<div class=\"fl-col-content fl-node-content\">\n<div class=\"fl-module fl-module-html fl-node-5e7d7411591ed\" data-node=\"5e7d7411591ed\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-html\">\n<div class=\"canal-rural-player-new\"><iframe class=\"canal-rural-player-new-item lazyloaded\" src=\"https:\/\/www.canalrural.com.br\/?video_slug=rogerio-boueri_20210525023953&amp;img_extension=jpg\" data-rocket-lazyload=\"fitvidscompatible\" data-ll-status=\"loaded\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"fl-module fl-module-rich-text fl-node-5e7d7411591eb\" data-node=\"5e7d7411591eb\">\n<div class=\"fl-module-content fl-node-content\">\n<div class=\"fl-rich-text\">\n<p>Se o projeto de lei do Congresso Nacional 4 de 2021 (PLN 4) n\u00e3o for votado, o Plano Safra 2021\/22 pode acabar sendo lan\u00e7ado apenas com financiamentos a juros livres. De acordo com o sub-secret\u00e1rio de Pol\u00edtica Agr\u00edcola do\u00a0<a href=\"https:\/\/www.gov.br\/economia\/pt-br\"><strong>Minist\u00e9rio da Economia<\/strong><\/a>, Rog\u00e9rio Boueri, o governo federal n\u00e3o tem uma alternativa.<\/p>\n<p>\u201cOs recursos equalizados necessitam da recomposi\u00e7\u00e3o or\u00e7ament\u00e1ria, porque, do contr\u00e1rio, n\u00e3o haver\u00e1 previs\u00e3o or\u00e7ament\u00e1ria e disponibilidade financeira\u201d, alerta. \u201cAs opera\u00e7\u00f5es com recursos livres poder\u00e3o acontecer. A gente n\u00e3o divulgou os n\u00famero porque, em geral, fazemos concatenadamente com as equalizadas\u201d. Na avalia\u00e7\u00e3o dele, isso seria \u201cterr\u00edvel para a agropecu\u00e1ria\u201d.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.canalrural.com.br\/programas\/informacao\/rural-noticias\/daoud-a-agricultura-nao-espera-e-o-produtor-precisa-do-plano-safra\/\"><strong>Daoud: A agricultura n\u00e3o espera e o produtor precisa do Plano Safra<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.canalrural.com.br\/noticias\/agricultura\/agricultura-familiar-credito-rural-aplicativo-serasa\/\"><strong>Agricultura familiar ter\u00e1 ofertas de cr\u00e9dito rural em aplicativo da Serasa<\/strong><\/a><\/li>\n<\/ul>\n<p>A quest\u00e3o est\u00e1 na m\u00e3o do Congresso Nacional, onde foram feitos os cortes no Or\u00e7amento da Uni\u00e3o para 2021. Segundo Boueri, o Executivo est\u00e1 pronto para fazer as sugest\u00f5es para o Plano Safra, mas precisa que o texto seja aprovado no Congresso.<\/p>\n<p>\u201cPrecisamos de um momento pol\u00edtico, porque isso n\u00e3o afetou apenas a agropecu\u00e1ria. Apesar de ela ter sido diretamente afetada, h\u00e1 outros aspectos or\u00e7ament\u00e1rios que s\u00e3o superiores aos valores da agropecu\u00e1ria\u201d, pontua.<\/p>\n<p>Boueri acredita que o impasse pode chegar ao fim nesta semana ou na pr\u00f3xima. Caso aconte\u00e7a na semana que vem, o governo ter\u00e1 que solicitar uma reuni\u00e3o extraordin\u00e1ria do Conselho Monet\u00e1rio Nacional (CMN) para apresentar o Plano Safra.<\/p>\n<p>Caso o PLN 4 seja rejeitado, o governo estuda direcionar os recursos equalizados para o Programa Nacional de Fortalecimento da Agricultura Familiar (Pronaf).<\/p>\n<p>O sub-secret\u00e1rio lembra que um atraso na aprova\u00e7\u00e3o do Plano Safra vai gerar um atraso na chegada dos recursos ao produtor rural, j\u00e1 que h\u00e1 todo um processo burocr\u00e1tico no meio do caminho, que envolve desde o Or\u00e7amento at\u00e9 portarias do Tesouro Nacional.<\/p>\n<p>\u201cExistem processos internos no Minist\u00e9rio da Agricultura e no Minist\u00e9rio da Economia para que possamos ter o dinheiro na m\u00e3o de quem mais precisa, que \u00e9 o produtor rural\u201d, finaliza.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 Canal Rural<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Canal Rural Se o projeto de lei do Congresso Nacional 4 de 2021 (PLN &hellip;<\/p>\n","protected":false},"author":4,"featured_media":38785,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-38784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Alerta foi dado pelo sub-secret\u00e1rio de Pol\u00edtica Agr\u00edcola do Minist\u00e9rio da Economia, diante da demora na vota\u00e7\u00e3o do projeto de lei que libera recursos para subven\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=38784"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38784\/revisions"}],"predecessor-version":[{"id":38786,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38784\/revisions\/38786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/38785"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=38784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=38784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=38784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}