{"id":38908,"date":"2021-05-27T14:31:57","date_gmt":"2021-05-27T18:31:57","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=38908"},"modified":"2021-05-27T14:31:57","modified_gmt":"2021-05-27T18:31:57","slug":"governador-acoes-do-estado-tem-fomentado-a-agroindustrializacao-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governador-acoes-do-estado-tem-fomentado-a-agroindustrializacao-em-mato-grosso\/","title":{"rendered":"Governador: a\u00e7\u00f5es do Estado tem fomentado a agroindustrializa\u00e7\u00e3o em Mato Grosso"},"content":{"rendered":"<p>O governador Mauro Mendes afirmou que o pacote de obras e a\u00e7\u00f5es do programa Mais MT tem fomentado a agroindustrializa\u00e7\u00e3o em Mato Grosso.<\/p>\n<p>A declara\u00e7\u00e3o foi dada nesta semana em entrevista ao programa Dia Dia Rural, do canal Terra Viva, da Band.<\/p>\n<p>O gestor relatou que Mato Grosso hoje \u00e9 o maior produtor brasileiro das principais commodities agr\u00edcolas, como a soja, milho, algod\u00e3o e tamb\u00e9m em rebanho bovino.<\/p>\n<p>Al\u00e9m disso, conforme o governador, a agroindustrializa\u00e7\u00e3o tem crescido substancialmente no estado nos \u00faltimos anos, especialmente no setor de etanol de milho, com 80% da produ\u00e7\u00e3o nacional (2,14 bilh\u00f5es de litros na safra 2020\/2021).<\/p>\n<p>\u201cEstamos na onda da agroindustrializa\u00e7\u00e3o. H\u00e1 muitos anos somos o maior produtor de milho, e agora estamos transformando esse milho em etanol, em DDG, gerando mais valor agregado, em uma ind\u00fastria bastante tecnificada\u201d, afirmou.<\/p>\n<p>Para Mauro Mendes, as a\u00e7\u00f5es implementadas pelo Governo de Mato Grosso t\u00eam colaborado na atra\u00e7\u00e3o de ind\u00fastrias do setor, a exemplo da revis\u00e3o dos incentivos fiscais, redu\u00e7\u00e3o da burocracia para a emiss\u00e3o de licen\u00e7as e tamb\u00e9m o equil\u00edbrio econ\u00f4mico obtido pela gest\u00e3o, trazendo seguran\u00e7a jur\u00eddica aos investidores.<\/p>\n<p>\u201cH\u00e1 dois anos, a nossa situa\u00e7\u00e3o fiscal era bastante ruim. T\u00ednhamos sal\u00e1rios atrasados e centenas de obras paralisadas. Quando eu assumi, fizemos uma dura pol\u00edtica fiscal e conseguimos recuperar o estado de Mato Grosso. Conseguimos saltar de Nota C para Nota A no Tesouro Nacional. Vamos investir este ano em torno de 15% da nossa receita, um dos maiores investimentos do pa\u00eds, em raz\u00e3o da pujan\u00e7a da nossa economia e pelas medidas corretas do Governo em cortar despesa e melhorar a arrecada\u00e7\u00e3o p\u00fablica\u201d, citou.<\/p>\n<p>De acordo com Mauro Mendes, os investimentos em infraestrutura do Governo de Mato Grosso tamb\u00e9m est\u00e3o sendo fundamentais para atra\u00e7\u00e3o de empresas e, com isso, gera\u00e7\u00e3o de emprego, renda e qualidade de vida aos mato-grossenses.<\/p>\n<p>\u201cVamos ter esse ano nas m\u00e3os das empreiteiras em torno de 1.500 km de rodovias sendo asfaltadas, e um programa de 5 mil pontes de madeira em parceria com as prefeituras. Essa infraestrutura melhorando, traz mais investimento privado, que vai aumentar as \u00e1reas produtivas, que vai baixar o custo do produtor, e que vai fazer com que o empres\u00e1rio tenha mais capacidade de investir\u201d.<\/p>\n<p>\u201cHoje Mato Grosso \u00e9 um estado de oportunidades e temos buscado investidores na \u00e1rea da agroindustrializa\u00e7\u00e3o. Exemplo disso \u00e9 a ind\u00fastria de etanol de milho, que h\u00e1 poucos anos n\u00e3o existia e hoje j\u00e1 somos o primeiro estado em produ\u00e7\u00e3o de etanol de milho, com grande perspectiva de continuar crescendo\u201d, finalizou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes afirmou que o pacote de obras e a\u00e7\u00f5es do programa Mais &hellip;<\/p>\n","protected":false},"author":4,"featured_media":38909,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-38908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"Mauro Mendes falou sobre os investimentos do Governo de Mato Grosso em infraestrutura","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=38908"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38908\/revisions"}],"predecessor-version":[{"id":38910,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/38908\/revisions\/38910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/38909"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=38908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=38908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=38908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}